{"id":131,"date":"2008-09-27T00:00:00","date_gmt":"2008-09-27T00:00:00","guid":{"rendered":"http:\/\/www.revue3emillenaire.com\/blog\/?p=131"},"modified":"2010-01-09T18:42:05","modified_gmt":"2010-01-09T17:42:05","slug":"intelligence-de-lenergie-par-robert-linssen","status":"publish","type":"post","link":"https:\/\/www.revue3emillenaire.com\/blog\/intelligence-de-lenergie-par-robert-linssen\/","title":{"rendered":"Intelligence de l&#39;Energie par Robert Linssen"},"content":{"rendered":"<p style=\"text-align: justify;\">(R\u00e9sum\u00e9 d&rsquo;une communication faite au Colloque international de philosophie \u00e0 Nice, le 30 mars 1963, sous le titre\u00a0 Myst\u00e8res Atomiques et Spiritualit\u00e9 de la Mati\u00e8re.)<br \/>\n(Revue \u00catre Libre, Num\u00e9ros 205-207, Janvier-Mars 1963)<\/p>\n<p style=\"text-align: justify;\">Le professeur Jean Wahl a d\u00e9clar\u00e9 qu&rsquo;il existait deux sortes de m\u00e9taphysiciens. Premi\u00e8rement ceux qui se cantonnent dans l&rsquo;abstraction pure et l&rsquo;argumentation th\u00e9orique. Deuxi\u00e8mement, ceux qui sont plus attentifs au langage de l&rsquo;exp\u00e9rience concr\u00e8te et s&rsquo;interrogent constamment sur la signification des faits.<\/p>\n<p style=\"text-align: justify;\">Carlo Suar\u00e8s consid\u00e8re la premi\u00e8re cat\u00e9gorie de m\u00e9taphysiciens ceux de l&rsquo;argumentation th\u00e9orique pure \u2014 comme des\u00a0 \u00ab escamoteurs \u00bb. L&rsquo;ampleur de leurs sp\u00e9culations intellectuelles les plonge dans une sorte d&rsquo;autohypnose. Par un curieux paradoxe, ils fuient le monde, ils s&rsquo;escamotent eux-m\u00eames avec leurs probl\u00e8mes r\u00e9els, ils se coupent du monde en subissant la magie de leurs propres cr\u00e9ations mentales.<\/p>\n<p style=\"text-align: justify;\">Nous t\u00e2cherons au cours de cet expos\u00e9 de ne pas nous perdre dans l&rsquo;argumentation pure mais d&rsquo;\u00e9couter aussi objectivement que possible le langage des faits.<\/p>\n<p style=\"text-align: justify;\">Les faits sont nombreux. L&rsquo;\u00e9volution prodigieuse des sciences physiques durant les cinquante derni\u00e8res ann\u00e9es a boulevers\u00e9 la plupart des conceptions relatives \u00e0 la nature de la Mati\u00e8re et de l&rsquo;Energie.<\/p>\n<p style=\"text-align: justify;\">Les principes traditionnels de l\u00e9galit\u00e9 universelle, de causalit\u00e9, d&rsquo;individualit\u00e9, de conservation de l&rsquo;\u00e9nergie sont remis tr\u00e8s s\u00e9rieusement en question.<\/p>\n<p style=\"text-align: justify;\">Nous examinerons simultan\u00e9ment au cours de cette communication des aspects apparemment oppos\u00e9s et contradictoires de l&rsquo;Univers.<\/p>\n<p style=\"text-align: justify;\">Nous mettrons d&rsquo;abord en \u00e9vidence l&rsquo;existence d&rsquo;une Unit\u00e9 \u00e9nerg\u00e9tique de profondeur sous-jacente aux innombrables apparences de surface. Donc, en un certain sens, tout est UN, en d\u00e9pit de l&rsquo;apparente multiplicit\u00e9 de propri\u00e9t\u00e9s, d&rsquo;aspects, de formes des choses et des \u00eatres.<\/p>\n<p style=\"text-align: justify;\">Et cependant, nous verrons par la suite que si tout est UN en profondeur, tout est absolument diff\u00e9rent en surface. Des objets aussi semblables que deux atomes d&rsquo;hydrog\u00e8ne ne sont pas absolument identiques.<\/p>\n<p style=\"text-align: justify;\">Unit\u00e9 de profondeur et singularit\u00e9s de surface sont les aspects oppos\u00e9s mais compl\u00e9mentaires d&rsquo;une m\u00eame R\u00e9alit\u00e9.<\/p>\n<p style=\"text-align: justify;\">Cette derni\u00e8re \u00e9chappe \u00e0 toute tentative de repr\u00e9sentation mentale. La notion de compl\u00e9mentarit\u00e9 introduite en physique par le prince Louis de Broglie constitue l&rsquo;une des cl\u00e9s fondamentales permettant \u00e0 l&rsquo;homme d&rsquo;acc\u00e9der \u00e0 la compr\u00e9hension d&rsquo;un grand nombre de faits apparemment contradictoires, dont la simultan\u00e9it\u00e9 \u00e9tait jusqu&rsquo;\u00e0 pr\u00e9sent paradoxale sinon incompr\u00e9hensible.<\/p>\n<p style=\"text-align: justify;\">Au cours de certaines exp\u00e9riences, les physiciens ont observ\u00e9 dans l&rsquo;\u00e9lectron un comportement rigoureusement corpusculaire. Au cours d&rsquo;exp\u00e9riences diff\u00e9rentes d&rsquo;autres physiciens ont observ\u00e9 un comportement absolument oppos\u00e9, de nature ondulatoire. Nous savons maintenant qu&rsquo;il n&rsquo;y a qu&rsquo;un \u00e9lectron se r\u00e9v\u00e9lant corpusculaire ou ondulatoire suivant l&rsquo;angle sous lequel on l&rsquo;examine.<\/p>\n<p style=\"text-align: justify;\">Nous parvenons ainsi \u00e0 d\u00e9passer la perspective traditionnellement dualiste impliqu\u00e9e par l&rsquo;observation de propri\u00e9t\u00e9s, de qualit\u00e9s ou de processus oppos\u00e9s dans un m\u00eame objet.<\/p>\n<p style=\"text-align: justify;\">Dans cet ordre d&rsquo;id\u00e9es, nous pouvons dire que l&rsquo;Unit\u00e9 \u00e9nerg\u00e9tique des profondeurs et les innombrables singularit\u00e9s de surface constituent les faces oppos\u00e9es mais compl\u00e9mentaires d&rsquo;une seule et m\u00eame R\u00e9alit\u00e9.<\/p>\n<p style=\"text-align: justify;\"><strong>Echelle d&rsquo;observation cr\u00e9ant le ph\u00e9nom\u00e8ne.<\/strong><\/p>\n<p style=\"text-align: justify;\">Toutes les nuances pr\u00e9c\u00e9demment \u00e9voqu\u00e9es r\u00e9sultent indirectement d&rsquo;une loi fondamentale : l&rsquo;\u00e9chelle d&rsquo;observation cr\u00e9e le ph\u00e9nom\u00e8ne.<\/p>\n<p style=\"text-align: justify;\">Le philosophe suisse Guye donnait l&rsquo;exemple suivant : disposez \u00e0 un m\u00e8tre de vous un m\u00e9lange de billes blanches et noires en quantit\u00e9s \u00e9gales. Vous pourrez observer facilement les billes noires et les billes blanches contrastant par l&rsquo;opposition r\u00e9ciproque de leurs coloris.<\/p>\n<p style=\"text-align: justify;\">Sans rien changer au m\u00e9lange, disposez-les ensuite \u00e0 cinquante m\u00e8tres de vous. Autrement dit, \u00ab changez l&rsquo;\u00e9chelle d&rsquo;observation \u00bb. Vous ne verrez plus distinctement les billes blanches et noires. Vous aurez la certitude de contempler un ensemble homog\u00e8ne gris. L&rsquo;\u00e9chelle d&rsquo;observation a chang\u00e9, le ph\u00e9nom\u00e8ne aussi. Ce principe pourrait d&rsquo;ailleurs \u00eatre illustr\u00e9 de mille fa\u00e7ons diff\u00e9rentes.<\/p>\n<p style=\"text-align: justify;\">Il conditionne non seulement les ph\u00e9nom\u00e8nes optiques mais tous les ph\u00e9nom\u00e8nes en g\u00e9n\u00e9ral, toutes nos perceptions physiques et psychologiques.<br \/>\n<strong><br \/>\nLimites de l&rsquo;analyse.<\/strong><\/p>\n<p style=\"text-align: justify;\">Lorsque nous entendons un avion dans la nuit, nous d\u00e9sirons souvent localiser sa position exacte. Si ses contours ne sont pas d\u00e9finis par des lumi\u00e8res, nous dirigerons vers lui un faisceau lumineux afin de le situer de fa\u00e7on pr\u00e9cise. Dans ce processus d&rsquo;observation l&rsquo;action du faisceau lumineux sur l&rsquo;avion est pratiquement nulle. Mais, par un curieux paradoxe, il en est tout autrement dans le domaine des corpuscules atomiques.<\/p>\n<p style=\"text-align: justify;\">En effet, si je d\u00e9sire observer un \u00e9lectron ou tout autre corpuscule, le faisceau de photons que j&rsquo;utilise pour le situer \u00e9tant d&rsquo;une grandeur assez proche de l&rsquo;\u00e9lectron, le perturbe profond\u00e9ment. Je ne pourrai constater que ce qui s&rsquo;est produit apr\u00e8s la perturbation provoqu\u00e9e par mon analyse.<\/p>\n<p style=\"text-align: justify;\">Il y a interaction de plus en plus grande entre le sujet observateur et l&rsquo;objet observ\u00e9\u00a0 et <strong>cette interaction cro\u00eet dans la mesure o\u00f9 nous tendons vers le c\u0153ur ultime des choses<\/strong>. Elle est pratiquement nulle \u00e0 notre \u00e9chelle habituelle, elle est tr\u00e8s importante au niveau atomique, elle est plus importante encore au niveau psychologique.<\/p>\n<p style=\"text-align: justify;\">Ceci a \u00e9t\u00e9 mis en \u00e9vidence non seulement par Heisenberg, mais surtout par l&rsquo;\u00e9minent math\u00e9maticien suisse Ferdinand Gonseth, qui \u00e9crit :<br \/>\n\u00ab Lorsqu&rsquo;une information est li\u00e9e \u00e0 certains moyens d&rsquo;informations indispensables et irrempla\u00e7ables, ces moyens entrent pour une part dans la forme m\u00eame de l&rsquo;information. La connaissance qui en d\u00e9rive porte en elle-m\u00eame les caract\u00e8res syst\u00e9matiques, peut-\u00eatre accidentels des proc\u00e9d\u00e9s informateurs comme des lois de structures n\u00e9cessaires \u00e0 priori. \u00bb<\/p>\n<p style=\"text-align: justify;\">Autant physiquement que psychologiquement, les processus d&rsquo;analyse poss\u00e8dent tous leurs limites et leurs conditionnements. Force nous est, si nous voulons d\u00e9couvrir la R\u00e9alit\u00e9, de d\u00e9passer l&rsquo;optique dualiste habituelle, conditionn\u00e9e par les interf\u00e9rences in\u00e9vitables existant entre l&rsquo;observateur, l&rsquo;observ\u00e9 et les \u00e9chelles d&rsquo;observation.<\/p>\n<p style=\"text-align: justify;\"><strong>Au-del\u00e0 du mat\u00e9rialisme et du spiritualisme.<\/strong><\/p>\n<p style=\"text-align: justify;\">Les consid\u00e9rations qui pr\u00e9c\u00e8dent nous font entrevoir l&rsquo;Univers sous un tout autre aspect.<\/p>\n<p style=\"text-align: justify;\">Cahen d\u00e9clarait : \u00ab l&rsquo;Univers n&rsquo;est une r\u00e9alit\u00e9 que dans sa Totalit\u00e9. Le ph\u00e9nom\u00e8ne est une convention \u00bb.<\/p>\n<p style=\"text-align: justify;\">En fait jusqu&rsquo;\u00e0 pr\u00e9sent toutes les sciences et toutes les valeurs d\u00e9coulant de l&rsquo;observation des faits et des perceptions sensorielles sont bas\u00e9es sur l&rsquo;\u00e9tude de \u00ab ph\u00e9nom\u00e8nes \u00bb consid\u00e9r\u00e9s \u00e0 tort comme isol\u00e9s. Il s&rsquo;agit l\u00e0 de morcellements arbitraires \u00e9labor\u00e9s par les fonctions analytiques habituelles d&rsquo;un processus mental qui est loin d&rsquo;avoir r\u00e9alis\u00e9 toutes ses possibilit\u00e9s.<\/p>\n<p style=\"text-align: justify;\">Le concept d&rsquo;Unit\u00e9 fondamentale d&rsquo;un Univers Homog\u00e8ne, la nature absolument nouvelle de cet Univers, qui n&rsquo;est plus mat\u00e9riel comme nous concevions la mati\u00e8re, ni spirituel comme traditionnellement nous concevions l&rsquo;esprit, sont autant d&rsquo;\u00e9l\u00e9ments attirant l&rsquo;attention des esprits attentifs.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;\u00e9volution r\u00e9cente des sciences physiques et biologiques a boulevers\u00e9 de fond en comble les notions traditionnelles du mat\u00e9rialisme et du spiritualisme.<\/p>\n<p style=\"text-align: justify;\">Des penseurs chr\u00e9tiens \u00e9minents, tel Teilhard de Chardin, \u00e9crivent le mot \u00ab Mati\u00e8re \u00bb avec un M majuscule.<\/p>\n<p style=\"text-align: justify;\">Des savants physiciens ou chimistes, de tendances positives et scientiste, tel Robert Tournaire, nous font entrevoir les \u00e9l\u00e9ments d&rsquo;une nouvelle spiritualit\u00e9 de l&rsquo;\u00e9nergie.<\/p>\n<p style=\"text-align: justify;\">De telles prises de positions auraient, il y a cinquante ans, provoqu\u00e9 le scandale. Elles se seraient heurt\u00e9es au scepticisme.<\/p>\n<p style=\"text-align: justify;\">Actuellement, force nous est d&rsquo;admettre que le savoir humain tend de plus en plus vers une synth\u00e8se qui se situe au-del\u00e0 des cadres habituels du mat\u00e9rialisme et du spiritualisme.<\/p>\n<p style=\"text-align: justify;\">Nous tenterons de r\u00e9sumer sommairement quels sont, \u00e0 notre avis, les facteurs dominants, les d\u00e9couvertes qui ont contribu\u00e9 \u00e0 la synth\u00e8se qui semble se r\u00e9aliser au cours de cette seconde moiti\u00e9 du vingti\u00e8me si\u00e8cle et que nous avons parfois d\u00e9sign\u00e9e sous le nom de \u00ab Mat\u00e9rialisme spirituel \u00bb se situant au-del\u00e0 du th\u00e9isme et de l&rsquo;ath\u00e9isme traditionnels.<\/p>\n<p style=\"text-align: justify;\"><strong>I. \u2014 De la multiplicit\u00e9 vers l&rsquo;Unit\u00e9.<\/strong><\/p>\n<p style=\"text-align: justify;\">L&rsquo;\u00e9tude de la physique et de la chimie nous r\u00e9v\u00e8le que l&rsquo;immense vari\u00e9t\u00e9 des \u00eatres et des choses provient d&rsquo;une seule et m\u00eame \u00e9nergie.<\/p>\n<p style=\"text-align: justify;\">Au point de d\u00e9part, nous avons un nombre pratiquement illimit\u00e9 de substances complexes, telles le bois, les cellules de notre chair.<\/p>\n<p style=\"text-align: justify;\">Ces substances complexes r\u00e9sultent de m\u00e9langes de corps purs, dont le plus petit \u00e9chantillon est la mol\u00e9cule (mol\u00e9cule d&rsquo;eau, de sucre). Dans l&rsquo;\u00e9tat actuel de la chimie, environ deux millions de corps purs ont \u00e9t\u00e9 identifi\u00e9s.<\/p>\n<p style=\"text-align: justify;\">A une \u00e9chelle d&rsquo;observation plus profonde, nous constatons que ces deux millions de mol\u00e9cules r\u00e9sultent des combinaisons vari\u00e9es de 92 corps simples ou atomes diff\u00e9rents (atome d&rsquo;hydrog\u00e8ne, d&rsquo;or).<\/p>\n<p style=\"text-align: justify;\">Chaque atome est comparable \u00e0 un syst\u00e8me solaire aux dimensions tr\u00e8s r\u00e9duites. Il en faut dix millions pour former un millim\u00e8tre.<\/p>\n<p style=\"text-align: justify;\">Au centre se trouve le noyau \u00e9lectris\u00e9 positivement autour duquel gravitent de petites plan\u00e8tes appel\u00e9es \u00e9lectrons plan\u00e9taires.<\/p>\n<p style=\"text-align: justify;\">Dans l&rsquo;atome d&rsquo;hydrog\u00e8ne, le plus simple, nous ne comptons qu&rsquo;un seul \u00e9lectron plan\u00e9taire n\u00e9gatif.<\/p>\n<p style=\"text-align: justify;\">Dans celui d&rsquo;Uranium, le plus complexe, il existe un cort\u00e8ge de 92 \u00e9lectrons plan\u00e9taires n\u00e9gatifs r\u00e9partis en couches successives. Ces couches sont de v\u00e9ritables carapaces \u00e9lectriques, plus imp\u00e9n\u00e9trables que mille boucliers d&rsquo;acier, prot\u00e9geant le noyau.<\/p>\n<p style=\"text-align: justify;\">A une \u00e9chelle d&rsquo;observation plus profonde encore, nous constaterions que le noyau n&rsquo;est pas ins\u00e9cable. Il est constitu\u00e9 de tout un ensemble de particules de nature tr\u00e8s \u00e9trange, dont le comportement t\u00e9moigne d&rsquo;une ing\u00e9niosit\u00e9 extraordinaire. Parmi ces constituants ultimes, au nombre d&rsquo;une trentaine environ, figurent les neutrons et les protons (utilis\u00e9s dans l&rsquo;artillerie atomique), les pions positifs, neutres ou n\u00e9gatifs, les neutrinos, etc.<\/p>\n<p style=\"text-align: justify;\">Enfin ces diff\u00e9rents corpuscules et le champ lui-m\u00eame, les espaces intra et interatomiques doivent \u00eatre consid\u00e9r\u00e9s comme les modes d&rsquo;une seule et m\u00eame \u00e9nergie.<br \/>\n<strong><br \/>\nII. \u2014 Universalit\u00e9 du Mouvement.<\/strong><\/p>\n<p style=\"text-align: justify;\">Rien n&rsquo;est immobile, ni dans la Mati\u00e8re ni dans l&rsquo;Esprit. Tout se meut. Tout se transforme.<\/p>\n<p style=\"text-align: justify;\">Des penseurs \u00e9minents, tels Spinoza, Bergson, Edouard Leroy avaient insist\u00e9 sur l&rsquo;importance du mouvement et du changement dans l&rsquo;Univers. Des auteurs plus r\u00e9cents, tels Constantin Brunner et Lother Bickel, nous disent que \u00ab toutes les formes et tous les\u00a0 \u00e9v\u00e9nements de ce monde ne sont que les degr\u00e9s divers d&rsquo;un\u00a0 seul et m\u00eame processus de mouvement \u00bb. (Le Dedans et le Dehors, Gallimard, 1962, p. 27.)<\/p>\n<p style=\"text-align: justify;\">Constantin Brunner d\u00e9clare : \u00ab Le mouvement constitue l&rsquo;essence une de tous les ph\u00e9nom\u00e8nes diff\u00e9rents \u00bb.<\/p>\n<p style=\"text-align: justify;\">Une \u00e9tude sommaire de l&rsquo;extraordinaire mobilit\u00e9 des corpuscules mat\u00e9riels d\u00e9montre imm\u00e9diatement le bien fond\u00e9 des \u00e9crits de Brunner et Bickel.<\/p>\n<p style=\"text-align: justify;\">A l&rsquo;\u00e9chelle d&rsquo;observation mol\u00e9culaire, nous savons que les mol\u00e9cules d&rsquo;un fragment d&rsquo;acier effectuent environ 8.000 milliards d&rsquo;oscillations par seconde. Celles du diamant effectuent environ 39.000 milliards d&rsquo;oscillations.<\/p>\n<p style=\"text-align: justify;\">Le nombre des oscillations mol\u00e9culaires de tous les corps est connu. Lorsque la temp\u00e9rature de ces corps augmente l&rsquo;amplitude des oscillations est plus grande. De ce fait, les mol\u00e9cules prennent plus de place et le corps est l&rsquo;objet du ph\u00e9nom\u00e8ne de dilatation bien connu de tous.<\/p>\n<p style=\"text-align: justify;\">A l&rsquo;\u00e9chelle atomique, les mouvements sont infiniment plus rapides encore. Les \u00e9lectrons plan\u00e9taires des diff\u00e9rents corps effectuent en chaque seconde entre 200.000 et 6.000.000 de milliards de tours.<\/p>\n<p style=\"text-align: justify;\">Songeons que ces chiffres ne r\u00e9sultent pas d&rsquo;une imagination de visionnaire ou de po\u00e8te. Ils expriment une intensit\u00e9 de mouvement qui se poursuit l\u00e0, perp\u00e9tuellement, au c\u0153ur des choses et des \u00eatres, en d\u00e9pit de leurs apparences d&rsquo;immobilit\u00e9 \u00ab de surface \u00bb.<\/p>\n<p style=\"text-align: justify;\">Cette notion d&rsquo;intensit\u00e9 de mouvement est d&rsquo;ailleurs la seule qui puisse subsister en notre esprit, l&rsquo;imagination humaine \u00e9tant incapable d&rsquo;une repr\u00e9sentation ad\u00e9quate de tels processus.<\/p>\n<p style=\"text-align: justify;\">Plus en profondeur encore, nous assistons au c\u0153ur m\u00eame du noyau atomique \u00e0 des intensit\u00e9s de mouvement v\u00e9ritablement hallucinantes. Nous y reviendrons ult\u00e9rieurement de fa\u00e7on plus d\u00e9taill\u00e9e, car nous touchons l\u00e0 \u00e0 l&rsquo;un des faits les plus r\u00e9v\u00e9lateurs de la spiritualit\u00e9 de la Mati\u00e8re.<\/p>\n<p style=\"text-align: justify;\">Pour nous r\u00e9sumer, nous dirons avec le professeur Edouard Leroy \u00ab que l&rsquo;Univers est un immense \u00e9difice form\u00e9 d&rsquo;\u00e9tages vibratoires \u00bb, mouvements relativement lents \u00e0 la surface reposant sur des mouvements de plus en plus rapides dans la mesure o\u00f9 nous allons en profondeur. La R\u00e9alit\u00e9 semble toujours \u00e9chapper \u00e0 l&rsquo;analyse. Cette derni\u00e8re nous r\u00e9v\u00e8le le sillage d&rsquo;une Eternelle Pr\u00e9sence, mais de cette R\u00e9alit\u00e9 Elle-m\u00eame, nous ne saisissons que ce qui n&rsquo;est d\u00e9j\u00e0 plus Elle.<\/p>\n<p style=\"text-align: justify;\">Nous voudrions cependant ajouter une chose que l&rsquo;on omet trop souvent de prendre en consid\u00e9ration.<\/p>\n<p style=\"text-align: justify;\">Lorsque nous parlons d&rsquo;atomes, d&rsquo;\u00e9lectrons, lorsque nous \u00e9voquons les mouvements prodigieux et de plus en plus rapides des \u00e9nergies constitutives de la mati\u00e8re, nous ne parlons pas seulement d&rsquo;un processus anonyme se d\u00e9roulant \u00e0 l&rsquo;ext\u00e9rieur de nous, au c\u0153ur des pav\u00e9s que nous foulons aux pieds en nous promenant en rue ou \u00e0 l&rsquo;int\u00e9rieur des murs de la maison qui nous abrite. Non. R\u00e9p\u00e9tons-le \u00e0 dessein. Nous n&rsquo;\u00e9voquons pas l\u00e0 des processus qui nous sont ext\u00e9rieurs, mais qui, bien au contraire, se d\u00e9roulent dans l&rsquo;intimit\u00e9 la plus profonde de notre \u00eatre, et ce \u00e0 la fois physiquement et psychologiquement.<\/p>\n<p style=\"text-align: justify;\">En un mot, lorsque nous parlons de ces mouvements, c&rsquo;est de notre \u00eatre profond qu&rsquo;il s&rsquo;agit. Cette intensit\u00e9 de mouvement constitue l&rsquo;essence ultime des \u00eatres et des choses.<\/p>\n<p style=\"text-align: justify;\">Ce concept dynamique, excluant toute immobilit\u00e9, tant dans la Mati\u00e8re que dans l&rsquo;Esprit, faisait dire humoristiquement \u00e0 Carlo Suar\u00e8s que \u00ab l&rsquo;absolu, en tant que r\u00e9alit\u00e9 immuable, \u00e9tait le \u00ab roi \u00bb des mots sans contenu \u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>III. \u2014 La mati\u00e8re d\u00e9mat\u00e9rialis\u00e9e.<\/strong><\/p>\n<p style=\"text-align: justify;\">Mais si tout est mouvement, une question fondamentale nous vient \u00e0 l&rsquo;esprit : qu&rsquo;est-ce que la Mati\u00e8re ? Qu&rsquo;est-ce qu&rsquo;un corpuscule atomique ? Qu&rsquo;est-ce que nous pouvons entendre exactement par \u00e9lectrons ou protons ?<\/p>\n<p style=\"text-align: justify;\">Nous avons en effet tendance \u00e0 projeter les images r\u00e9sultant de nos perceptions sensorielles vulgaires dans un domaine o\u00f9 elles se r\u00e9v\u00e8lent totalement inad\u00e9quates.<\/p>\n<p style=\"text-align: justify;\">Toute personne ayant quelque peu \u00e9tudi\u00e9 la physique ou la chimie se souviendra du sch\u00e9ma de l&rsquo;atome de Bohr, repr\u00e9sentant un noyau central sph\u00e9rique entour\u00e9 de quelques \u00e9lectrons plan\u00e9taires de forme parfaitement sph\u00e9rique. Ce sch\u00e9ma fig\u00e9 aux contours d\u00e9finis n&rsquo;a aucun rapport avec la r\u00e9alit\u00e9 des faits.<\/p>\n<p style=\"text-align: justify;\">Nous avons tendance \u00e0 supposer que si nous disposions d&rsquo;un sens du toucher suffisamment perfectionn\u00e9, il nous serait possible d&rsquo;\u00e9prouver entre deux doigts la solidit\u00e9 de ces corpuscules ultimes \u00e0 la fa\u00e7on dont nous pouvons sentir le frottement de minuscules grains de sables. Nous avons trop facilement tendance \u00e0 imaginer les corpuscules atomiques semblables \u00e0 d&rsquo;infimes billes de billard solides, opaques, aux contours nettement d\u00e9finis. Il n&rsquo;en n&rsquo;est rien.<\/p>\n<p style=\"text-align: justify;\">Plus de solidit\u00e9, plus d&rsquo;opacit\u00e9, plus de contours d\u00e9finis. Les corpuscules atomiques sont d\u00e9crits comme des \u00ab paquets d&rsquo;ondes \u00bb, comme des \u00ab zones d&rsquo;influences \u00bb, comme des tourbillons d&rsquo;\u00e9nergie, comme des localisations d&rsquo;ondes de probabilit\u00e9.<\/p>\n<p style=\"text-align: justify;\">La physique, science de la mati\u00e8re par excellence, a d\u00e9mat\u00e9rialis\u00e9 le monde mat\u00e9riel. Les plus mat\u00e9rialistes doivent en convenir. Le \u00ab Dieu mati\u00e8re \u00bb du si\u00e8cle pass\u00e9 s&rsquo;est transfigur\u00e9 en pure lumi\u00e8re.<\/p>\n<p style=\"text-align: justify;\">Son visage glacial et fig\u00e9 n&rsquo;\u00e9tait un symbole de mort et de d\u00e9solation que dans la mesure de notre ignorance et de notre incapacit\u00e9 de percevoir la nature v\u00e9ritable des choses. Le monde physique se d\u00e9pouille de son opacit\u00e9. Les ombres ne sont qu&rsquo;apparentes.<\/p>\n<p style=\"text-align: justify;\">Qu&rsquo;on se le dise et qu&rsquo;on se le r\u00e9p\u00e8te. Le langage qui va suivre n&rsquo;est ni celui du visionnaire, ni du mystique ou du po\u00e8te. Nul physicien ne peut aujourd&rsquo;hui contester que les plus beaux feux d&rsquo;artifice, que nous aurions pu contempler, ne sont rien devant la f\u00e9erie de lumi\u00e8re et d&rsquo;intensit\u00e9 de mouvement qui se poursuit silencieusement, durant des si\u00e8cles, dans le plus modeste grain de sable, dans le pav\u00e9 anonyme que mart\u00e8lent distraitement nos pas.<\/p>\n<p style=\"text-align: justify;\">Nous rappellerons, ici, une fois de plus \u2014 et nous nous r\u00e9p\u00e9terons \u00e0 dessein \u00e0 diverses reprises \u2014 que cette f\u00e9erie de lumi\u00e8re, ce d\u00e9ploiement d&rsquo;\u00e9nergie ne se d\u00e9roulent pas seulement au c\u0153ur du grain de sable anonyme perdu parmi ses milliards de voisins anonymes. Non.<\/p>\n<p style=\"text-align: justify;\">Ces processus, redisons-le, se d\u00e9roulent dans l&rsquo;intimit\u00e9 des mol\u00e9cules g\u00e9antes et des atomes constituant nos propres cellules.<\/p>\n<p style=\"text-align: justify;\">Fait important : ils ne r\u00e9sultent pas d&rsquo;un hasard chaotique. Au contraire; ann\u00e9e apr\u00e8s ann\u00e9e, les physiciens restent confondus devant l&rsquo;habilet\u00e9 des processus atomiques et surtout intra-atomiques.<\/p>\n<p style=\"text-align: justify;\">Nous allons en examiner un exemple saisissant.<\/p>\n<p style=\"text-align: justify;\"><strong>IV. \u2014 Le fait fondamental des relations.<\/strong><\/p>\n<p style=\"text-align: justify;\">L&rsquo;\u00e9tude du comportement des constituants intranucl\u00e9aires fournit aux physiciens et aux m\u00e9taphysiciens de tr\u00e8s amples mati\u00e8res \u00e0 r\u00e9flexion.<\/p>\n<p style=\"text-align: justify;\">Chacun sait en effet que les corps \u00e9lectris\u00e9s de m\u00eame signe se repoussent. Cette r\u00e9pulsion est d&rsquo;autant plus grande que la masse des corps en question est importante. Elle est \u00e9galement fonction de leur proximit\u00e9 r\u00e9ciproque.<\/p>\n<p style=\"text-align: justify;\">Or, la densit\u00e9 des protons existant au c\u0153ur des noyaux atomiques est consid\u00e9rable. Au surplus, les noyaux lourds, tels ceux du platine, du plomb, de l&rsquo;or, contiennent un nombre important de protons, tous charg\u00e9s du m\u00eame signe positif, et situ\u00e9s fortement \u00e0 proximit\u00e9 les uns des autres. Les physiciens se demandaient, il y a trente ans, quelle \u00e9tait la force myst\u00e9rieuse capable d&#8217;emp\u00eacher les noyaux atomiques des corps lourds d&rsquo;exploser. La force de r\u00e9pulsion des protons est en effet \u00e9norme. C&rsquo;est un savant japonais, le professeur Yukawa, qui \u00e9mit en 1935 l&rsquo;hypoth\u00e8se de l&rsquo;existence, au c\u0153ur du noyau, d&rsquo;une force de liaison reliant les constituants intranucl\u00e9aires et neutralisant l&rsquo;\u00e9norme force de r\u00e9pulsion.<\/p>\n<p style=\"text-align: justify;\">Il s&rsquo;agit plus exactement de particules \u00e9tranges d\u00e9sign\u00e9es sous le nom de M\u00e9son Pi ou pions, dont les comportements extraordinaires parviennent \u00e0 maintenir la stabilit\u00e9 apparente du noyau atomique. Insistons sur le fait que ces particules, qui n&rsquo;\u00e9taient qu&rsquo;hypoth\u00e8ses incertaines, ont \u00e9t\u00e9 effectivement d\u00e9couvertes d\u00e8s 1947 et v\u00e9ritablement manipul\u00e9es depuis 1955.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;\u00e9tude attentive de leur comportement nous r\u00e9v\u00e8le le spectacle le plus hallucinant qui soit. En effet, des milliards de milliards de fois par seconde, les protons perdent un pion positif et deviennent des neutrons, tandis que des neutrons deviennent des protons et que des pions neutres et n\u00e9gatifs sont l&rsquo;objet d&rsquo;inter-\u00e9changes, dont l&rsquo;intensit\u00e9 \u00e9chappe \u00e0 toutes les possibilit\u00e9s de la repr\u00e9sentation imaginative. C&rsquo;est gr\u00e2ce \u00e0 cet ing\u00e9nieux artifice, \u00e0 cette intensit\u00e9 d&rsquo;inter-\u00e9changes que l&rsquo;harmonie d&rsquo;ensemble du noyau est conserv\u00e9e.<\/p>\n<p style=\"text-align: justify;\">Un \u00e9minent physicien compara\u00eet le r\u00f4le du pion au sein des constituants intranucl\u00e9aires \u00e0 celui du ballon de volley-ball, auquel restent suspendus tous les joueurs d&rsquo;une \u00e9quipe.<\/p>\n<p style=\"text-align: justify;\">En r\u00e9sum\u00e9, nous assistons, au c\u0153ur du noyau atomique, au bal masqu\u00e9 le plus extraordinaire qui soit.<\/p>\n<p style=\"text-align: justify;\">Au cours de rondes infernales, les participants changent d&rsquo;individualit\u00e9 des milliards de milliards de fois par seconde. Un fait se d\u00e9gage avec \u00e9vidence de ces processus \u00e9tranges. Nous pourrions le r\u00e9sumer sous la forme suivante :<\/p>\n<p style=\"text-align: justify;\">Dans le domaine ultime de la mat\u00e9rialit\u00e9, au c\u0153ur de l&rsquo;intra-atome, l<strong>e fait des relations est plus important que l&rsquo;individualit\u00e9 des \u00e9l\u00e9ments reli\u00e9s.<\/strong><\/p>\n<p style=\"text-align: justify;\">Dans une \u00e9tude remarquable, publi\u00e9e avec la collaboration d&rsquo;Einstein, de Niels Bohr, de W. Heisenberg, sur le Principe de Compl\u00e9mentarit\u00e9, le prince Louis de Broglie conclut dans un sens semblable. Il d\u00e9clare que \u00ab la perte d&rsquo;individualit\u00e9 subie par les constituantes d&rsquo;un syst\u00e8me et traduite en m\u00e9canique classique\u00a0 par la notion d&rsquo;\u00e9nergie potentielle s&rsquo;accentue au fur et \u00e0 mesure que la liaison des constituants dans le syst\u00e8me devient plus \u00e9troite \u00bb. (Revue Dialectica, p. 329. Presses Universitaires de France.)<\/p>\n<p style=\"text-align: justify;\">Ainsi que l&rsquo;exprime Louis de Broglie, il existe une \u00ab sorte de compl\u00e9mentarit\u00e9 entre l&rsquo;id\u00e9e de constituant autonome et celle de syst\u00e8me \u00bb. Mais dans la mesure o\u00f9 nous allons vers l&rsquo;essence ultime des choses, le fait des liaisons ou relations s&rsquo;intensifiant, nous assistons \u00e0 l&rsquo;\u00e9vanouissement progressif de la notion d&rsquo;individualit\u00e9.<\/p>\n<p style=\"text-align: justify;\">Le fait des relations est non seulement important en physique mais en biologie. La fluidit\u00e9 des \u00e9changes, la labilit\u00e9 cellulaire et l&rsquo;intensit\u00e9 des relations figurent parmi les conditions essentielles de la vie.<\/p>\n<p style=\"text-align: justify;\">Le fait fondamental des relations ne se r\u00e9v\u00e8le pas seulement au c\u0153ur de l&rsquo;intra-atome. Il existe de fa\u00e7on aussi frappante dans les rapports reliant les \u00e9lectrons plan\u00e9taires n\u00e9gatifs au noyau central positif.<\/p>\n<p style=\"text-align: justify;\">Un chimiste connu n&rsquo;h\u00e9sitait pas \u00e0 dire que dans l&rsquo;atome d&rsquo;hydrog\u00e8ne, par exemple, l&rsquo;unique \u00e9lectron plan\u00e9taire n\u00e9gatif ne repr\u00e9sentant qu&rsquo;un deux milli\u00e8me de la masse du noyau, n&rsquo;\u00e9tait qu&rsquo;un pr\u00e9texte ing\u00e9nieux utilis\u00e9 par la loi fondamentale des relations.<\/p>\n<p style=\"text-align: justify;\">Entre chaque syst\u00e8me atomique complet et son cort\u00e8ge d&rsquo;\u00e9lectrons plan\u00e9taires, il existe \u00e9galement un processus de relations infiniment plus important que tous ceux qui ont \u00e9t\u00e9 pr\u00e9c\u00e9demment \u00e9voqu\u00e9s. Nous tenterons de les r\u00e9sumer dans les lignes qui suivent.<\/p>\n<p style=\"text-align: justify;\"><strong>L&rsquo;interfusion cosmique.<\/strong><\/p>\n<p style=\"text-align: justify;\">La physique nous enseigne en effet qu&rsquo;il existe une pr\u00e9sence potentielle de chaque corpuscule atomique, \u00e9tendant son action jusqu&rsquo;aux ultimes confins de l&rsquo;Univers. Et r\u00e9ciproquement \u00ab quelque chose \u00bb des atomes situ\u00e9s au c\u0153ur des n\u00e9buleuses les plus lointaines p\u00e9n\u00e8tre les milliards d&rsquo;atomes de notre plan\u00e8te. Une fois de plus, il ne s&rsquo;agit pas ici d&rsquo;une affirmation de visionnaire ou de po\u00e8te.<\/p>\n<p style=\"text-align: justify;\">Ainsi que l&rsquo;exprime Teilhard de Chardin (Le ph\u00e9nom\u00e8ne humain, p. 36):<br \/>\n\u00ab Quel que soit l&rsquo;espace dans lequel nous le supposons plac\u00e9, chaque \u00e9l\u00e9ment cosmique remplit enti\u00e8rement de son rayonnement ce volume lui-m\u00eame. Si \u00e9troitement circonscrit que soit le c\u0153ur d&rsquo;un atome, son domaine est coextensif, au moins virtuellement, \u00e0 celui de n&rsquo;importe quel autre atome. Plus par des moyens d&rsquo;une puissance toujours accrue nous p\u00e9n\u00e9trons loin et profond dans la Mati\u00e8re, plus l&rsquo;interliaison de ses parties nous confond. <strong>Chaque \u00e9l\u00e9ment du cosmos est positivement tiss\u00e9 de tous les autres<\/strong>. \u00bb<\/p>\n<p style=\"text-align: justify;\">Il est donc rigoureusement impossible d&rsquo;isoler un objet du milieu ambiant. Des milliards de filaments invisibles partent de ses atomes constitutifs et le relient aux innombrables atomes de l&rsquo;Univers entier, tandis que de l&rsquo;Univers entier des milliards de liens invisibles p\u00e9n\u00e8trent dans l&rsquo;intimit\u00e9 de sa substance.<\/p>\n<p style=\"text-align: justify;\">Tout est dans tout continuellement avec une intensit\u00e9 \u00e9chappant \u00e0 toute imagination. L&rsquo;interfusion cosmique doit \u00eatre consid\u00e9r\u00e9e comme l&rsquo;un des faits fondamentaux de l&rsquo;Univers.<\/p>\n<p style=\"text-align: justify;\">La mise en \u00e9vidence de l&rsquo;importance du fait des relations et de l&rsquo;interfusion cosmique nous montre l&rsquo;univers, non seulement comme une Totalit\u00e9 Une, mais aussi comme une extraordinaire multiplicit\u00e9 de points diff\u00e9rents. Certes, l&rsquo;Unit\u00e9 des profondeurs doit occuper une place de priorit\u00e9 par rapport aux innombrables singularit\u00e9s \u00ab de surface \u00bb. Mais, nous ne pouvons, pour autant, nier l&rsquo;importance et le r\u00f4le \u00e9trange de ces singularit\u00e9s.<\/p>\n<p style=\"text-align: justify;\">Nous disions que tout est diff\u00e9rent. Rien n&rsquo;est plus rigoureusement exact. A notre \u00e9chelle, et regard\u00e9es de fa\u00e7on superficielle, deux billes d&rsquo;acier de m\u00eame diam\u00e8tre, de m\u00eame composition, aux m\u00eames contours nettement d\u00e9finis et polis, peuvent \u00eatre consid\u00e9r\u00e9es comme semblables.<\/p>\n<p style=\"text-align: justify;\">Mais en fait, il ne s&rsquo;agit l\u00e0 que \u00ab d&rsquo;\u00e0 peu pr\u00e8s \u00bb. En science pure on ne se contente pas d&rsquo;\u00e0 peu pr\u00e8s. Or, le r\u00e9seau de relations r\u00e9ciproques de ces deux billes d&rsquo;acier identiques, ou m\u00eame de deux atomes d&rsquo;hydrog\u00e8ne identiques, avec tous les atomes voisins d&rsquo;abord et tous ceux de l&rsquo;univers entier ensuite, est enti\u00e8rement diff\u00e9rent, ne fut-ce d\u00e9j\u00e0 en raison de leurs positions diff\u00e9rentes. Tout point particulier dans l&rsquo;univers est absolument unique, et en fait totalement diff\u00e9rent du point le plus rapproch\u00e9 qui, de prime abord lui para\u00eet si semblable.<\/p>\n<p style=\"text-align: justify;\">Non seulement tout point particulier est rigoureusement unique et diff\u00e9rent par sa position privil\u00e9gi\u00e9e dans l&rsquo;espace, mais tout moment de temps, toute seconde qui passe, comporte \u00e9galement un caract\u00e8re d&rsquo;unicit\u00e9.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;erreur dans laquelle tombent les positions philosophiques extr\u00eames peut \u00eatre d\u00e9finie comme suit.<\/p>\n<p style=\"text-align: justify;\">Les spiritualistes et certaines philosophies indiennes d\u00e9noncent l&rsquo;illusion absolue de la multiplicit\u00e9 et des singularit\u00e9s. Ce ne sont l\u00e0 pour elles que purs mirages, \u00ab Maya \u00bb. Seule l&rsquo;Unit\u00e9 existe.<\/p>\n<p style=\"text-align: justify;\">Pour la plupart des philosophes positivistes, scientistes occidentaux, seules importent les singularit\u00e9s. Mais ils poss\u00e8dent d&rsquo;elles des repr\u00e9sentations absolument fausses.<\/p>\n<p style=\"text-align: justify;\">La v\u00e9rit\u00e9 est \u00e0 mi-chemin entre ces positions extr\u00eames.<\/p>\n<p style=\"text-align: justify;\">Elle se trouve \u00e0 notre avis dans une vision oc\u00e9anique que nous permettent d&rsquo;entrevoir les optiques non-dualistes des anciens ma\u00eetres du Ch&rsquo;an chinois. Sans le vouloir, et tout en l&rsquo;ignorant totalement, il semble que Krishnamurti se rapproche beaucoup de ce point de vue.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;oc\u00e9an, dans cette vision \u00ab oc\u00e9anique \u00bb symbolise l&rsquo;Univers envisag\u00e9 comme Totalit\u00e9 Une homog\u00e8ne. La substance en est l&rsquo;eau.<\/p>\n<p style=\"text-align: justify;\">A la surface de cet Oc\u00e9an d\u00e9ferlent des milliards de petites vaguelettes \u00e9vanescentes. Elles sont toutes dou\u00e9es d&rsquo;une singularit\u00e9, d&rsquo;une unicit\u00e9, d&rsquo;une forme particuli\u00e8re. Mais toutes sont provisoires. Chacun de nous est une de ces vaguelettes.<\/p>\n<p style=\"text-align: justify;\">La forme, la singularit\u00e9, l&rsquo;unicit\u00e9 sont \u00e9vanescentes.<\/p>\n<p style=\"text-align: justify;\">La Sagesse consiste en la r\u00e9alisation permanente de la vision oc\u00e9anique de base, tout en ayant la capacit\u00e9 d&rsquo;\u00e9couter le langage extraordinaire des faits que racontent les milliards de vaguelettes \u00e9vanescentes, en saisissant qu&rsquo;au c\u0153ur de toutes ces \u00e9vanescences de surface existent l&rsquo;infini et l&rsquo;\u00e9ternit\u00e9 des profondeurs.<\/p>\n<p style=\"text-align: justify;\">La sagesse ne consisterait donc pas \u00e0 nier les singularit\u00e9s, mais \u00e0 les situer \u00e0 leur juste place, \u00e0 les voir telles qu&rsquo;elles sont, \u00e0 comprendre et r\u00e9aliser leur caract\u00e8re provisoire.<\/p>\n<p style=\"text-align: justify;\">Toutes nos souffrances, tous les drames de la s\u00e9paration, de l&rsquo;attachement, de la mort se pr\u00e9sentent \u00e0 notre esprit d\u00e8s l&rsquo;instant o\u00f9 nous perdons de vue le caract\u00e8re provisoire de la singularit\u00e9 d&rsquo;une vaguelette. Nous nous identifions \u00e0 la forme sur laquelle veut se fixer notre esprit et nous perdons de vue la r\u00e9alit\u00e9 essentielle de l\u2019eau.<br \/>\n<strong><br \/>\nL&rsquo;intelligence de l&rsquo;Energie.<\/strong><\/p>\n<p style=\"text-align: justify;\">Nous avons mis en \u00e9vidence l&rsquo;importance du fait des relations et celle de l&rsquo;interfusion cosmique.<\/p>\n<p style=\"text-align: justify;\">Un nombre de plus en plus grand de savants et de penseurs s&rsquo;accordent \u00e0 consid\u00e9rer que l&rsquo;Univers ressemble davantage \u00e0 une grande pens\u00e9e qu&rsquo;\u00e0 une machine r\u00e9gie par les seules lois du hasard.<\/p>\n<p style=\"text-align: justify;\"><strong>L&rsquo;intelligence peut \u00eatre consid\u00e9r\u00e9e comme l&rsquo;ad\u00e9quacit\u00e9 dans les relations<\/strong>. Ceci est \u00e9vident.<\/p>\n<p style=\"text-align: justify;\">A l&rsquo;\u00e9chelle humaine ordinaire, le sens commun qualifie d&rsquo;inintelligente toute personne maladroite physiquement ou intellectuellement.<\/p>\n<p style=\"text-align: justify;\">Tout \u00eatre incapable de r\u00e9pondre ad\u00e9quatement \u00e0 une circonstance est consid\u00e9r\u00e9 comme inintelligent.<\/p>\n<p style=\"text-align: justify;\">Les tests d&rsquo;intelligence s&rsquo;appliquant \u00e0 la plus tendre enfance sont bas\u00e9s sur la capacit\u00e9 qu&rsquo;ont les enfants de r\u00e9assembler des fragments d&rsquo;objets ou de r\u00e9unir les pi\u00e8ces d\u00e9tach\u00e9es de jouets s&#8217;embo\u00eetant les uns des autres. La rapidit\u00e9 de ces r\u00e9assemblages joue un r\u00f4le d\u00e9terminant dans l&rsquo;\u00e9valuation des quotients intellectuels.<\/p>\n<p style=\"text-align: justify;\">Que dire d\u00e8s lors de l&rsquo;ad\u00e9quacit\u00e9 extraordinaire des constituants ultimes de la Mati\u00e8re. Nulle part dans l&rsquo;Univers entier, nous ne pouvons observer des exemples d&rsquo;ad\u00e9quacit\u00e9 aussi parfaits, aussi rapide que ceux r\u00e9v\u00e9l\u00e9s au c\u0153ur des noyaux atomiques. L&rsquo;habilet\u00e9 des inter-\u00e9changes d\u00e9passe toutes les possibilit\u00e9s de nos repr\u00e9sentations mentales. Le c\u00e9l\u00e8bre physicien atomique, R. Oppenheimer, d\u00e9clarait un jour humoristiquement que \u00ab les corpuscules atomiques connaissent mieux le calcul tensoriel que les physiciens \u00bb&#8230;<\/p>\n<p style=\"text-align: justify;\">L&rsquo;\u00e9minent physicien et math\u00e9maticien anglais P.-A.-M. Dirac, \u00e9crivait (Revue Synth\u00e8ses, n\u00ba 201, p. 19) :\u00a0 \u00ab Il semble que ce soit un principe g\u00e9n\u00e9ral que les lois fondamentales de la physique soient \u00e9troitement li\u00e9es aux hautes math\u00e9matiques. Ceci devient de plus en plus \u00e9vident, \u00e0 mesure qu&rsquo;augmente notre connaissance de la nature. On n&rsquo;explique pas pourquoi il en soit ainsi. On doit seulement accepter cela comme un fait. On peut dire que Dieu est math\u00e9maticien et qu&rsquo;il a employ\u00e9 dans la cr\u00e9ation de l&rsquo;univers les math\u00e9matiques de l&rsquo;esp\u00e8ce la plus sublime. Toute personne ayant un peu \u00e9tudi\u00e9 les math\u00e9matiques peut voir qu&rsquo;il y a une grande beaut\u00e9 dans les relations math\u00e9matiques.<\/p>\n<p style=\"text-align: justify;\">Or on a trouv\u00e9 que les lois fondamentales de la physique, quand elles sont obtenues dans leur forme correcte, ont ce type de grande beaut\u00e9 math\u00e9matique&#8230; \u00bb<\/p>\n<p style=\"text-align: justify;\">La plupart des penseurs actuels, tels Lothar Bickel, Constantin Brunner, Roger Godel, R. Oppenheimer, Jean Charon, consid\u00e8rent que l&rsquo;intelligence et la conscience sous leurs formes les plus pures, sont li\u00e9es au mouvement, \u00e0 la vigilance, \u00e0 la cr\u00e9ation.<\/p>\n<p style=\"text-align: justify;\">Ce mouvement extraordinairement intense, cette cr\u00e9ation continuelle, cette vigilance, sont pr\u00e9cis\u00e9ment les caract\u00e8res sp\u00e9cifiques de zones ultimes de la Mat\u00e9rialit\u00e9.<\/p>\n<p style=\"text-align: justify;\">La place nous manque pour faire \u00e9tat des travaux nombreux de penseurs \u00e9minents des opinions les plus nuanc\u00e9es, depuis Jean Charon jusqu&rsquo;au math\u00e9maticien Fred Hoyle.<\/p>\n<p style=\"text-align: justify;\">Nous citerons ici Jean Charon, \u00e9crivant dans \u00ab Du Temps, de l&rsquo;Espace et des hommes \u00bb, p. 27 : \u00ab On voit nettement appara\u00eetre deux effets, bien confirm\u00e9s par la Physique : influence de toute la r\u00e9alit\u00e9 ext\u00e9rieure sur la structure et le comportement d&rsquo;un seul point de l&rsquo;espace-temps et, inversement, influence de chaque point sur la structure de toute la r\u00e9alit\u00e9 ext\u00e9rieure. L&rsquo;UN est coextensif au Tout et le Tout converge dans l&rsquo;UN&#8230; Ce que vous nommez votre pens\u00e9e n&rsquo;est pas autre chose qu&rsquo;une\u00a0 intensification, une am\u00e9lioration de cette interconnexion de chacun de nous avec le reste de l&rsquo;Univers. \u00bb<\/p>\n<p style=\"text-align: justify;\">Il appara\u00eet de plus en plus \u00e9vident qu&rsquo;il n&rsquo;existe qu&rsquo;une R\u00e9alit\u00e9. Elle se r\u00e9v\u00e8le mat\u00e9rielle ou spirituelle suivant l&rsquo;angle sous laquelle on l&rsquo;examine. Esprit et Mati\u00e8re sont les faces apparemment oppos\u00e9es mais compl\u00e9mentaires d&rsquo;une m\u00eame Energie. Une analyse attentive du comportement de cette derni\u00e8re tant en profondeur qu&rsquo;en surface parmi les \u00eatres et les choses qui sont faits d&rsquo;Elle, nous l&rsquo;a fait entrevoir comme un champ unifi\u00e9 de cr\u00e9ation pure et de conscience cosmique. Il y a non seulement le fait \u00e9l\u00e9mentaire que vous et moi, constitu\u00e9s par cette \u00e9nergie, sommes l\u00e0 dou\u00e9s d&rsquo;une conscience personnelle qui tente d&rsquo;en saisir lucidement tous les aspects.<\/p>\n<p style=\"text-align: justify;\">Mais il y a aussi le fait que des math\u00e9maticiens ont mis en \u00e9quation le nombre \u00e9norme et connu des particules du Cosmos en examinant leurs possibilit\u00e9s d&rsquo;associations au cours d&rsquo;un temps record de douze milliards d&rsquo;ann\u00e9es et le calcul des probabilit\u00e9s nous d\u00e9montre p\u00e9remptoirement que le comportement de l&rsquo;Energie dans l&rsquo;Univers est celui d&rsquo;un anti-hasard.<\/p>\n<p style=\"text-align: justify;\"><strong>L&rsquo;art de vivre.<\/strong><\/p>\n<p style=\"text-align: justify;\">Quels sont la signification et le r\u00f4le de l&rsquo;existence humaine au c\u0153ur de cette immensit\u00e9 cosmique d&rsquo;un Univers fondamentalement UN en \u00ab profondeur \u00bb et extraordinairement multiple en \u00ab surface \u00bb.<\/p>\n<p style=\"text-align: justify;\">Ce grand art de vivre consisterait \u00e0 jouer le jeu du monde sans s&rsquo;identifier aux formes \u00e9vanescentes qui en constituent la part la plus importante.<\/p>\n<p style=\"text-align: justify;\">Pour ce faire, nous devons p\u00e9n\u00e9trer dans les couches les plus profondes de la conscience personnelle pour les d\u00e9passer ensuite et nous immerger par int\u00e9gration dans\u00a0 \u00ab l&rsquo; Oc\u00e9an \u00bb de conscience cosmique.<\/p>\n<p style=\"text-align: justify;\">Nous ne pouvons pleinement jouer le jeu du monde qu&rsquo;en \u00e9tant totalement libres, non identifi\u00e9s aux formes \u00e9vanescentes. Mais pour \u00eatre libres de l&rsquo;identification et de l&rsquo;attachement aux formes, nous devons r\u00e9aliser un \u00e9tat de conscience et de perception int\u00e9grale d\u00e9passant de loin les horizons qui nous \u00e9taient familiers.<\/p>\n<p style=\"text-align: justify;\">A l&rsquo;int\u00e9rieur du temps, au c\u0153ur de chaque seconde, nous pouvons d\u00e9couvrir l&rsquo;\u00e9ternit\u00e9.<\/p>\n<p style=\"text-align: justify;\">A l&rsquo;int\u00e9rieur du fini de chaque instant nous pouvons d\u00e9couvrir l&rsquo;infini.<\/p>\n<p style=\"text-align: justify;\">A l&rsquo;int\u00e9rieur de ce qui para\u00eet immobile nous pouvons d\u00e9couvrir l&rsquo;essence supr\u00eame de tous les mouvements.<\/p>\n<p style=\"text-align: justify;\">A l&rsquo;int\u00e9rieur de ce qui est r\u00e9gi par des lois m\u00e9caniques nous pouvons d\u00e9couvrir une supr\u00eame spontan\u00e9it\u00e9.<\/p>\n<p style=\"text-align: justify;\">A l&rsquo;int\u00e9rieur de ce qui na\u00eet et qui meurt, en nous, comme autour de nous, nous pouvons d\u00e9couvrir CE qui est au-del\u00e0 de la naissance et de la mort.<\/p>\n<p style=\"text-align: justify;\">A l&rsquo;int\u00e9rieur de tous les devenirs nous pouvons d\u00e9couvrir l&rsquo;Etre.<\/p>\n<p style=\"text-align: justify;\">Mais, finalement, il n&rsquo;y aura plus, ni int\u00e9rieur, ni ext\u00e9rieur. Toutes dualit\u00e9s seront abolies. Toutes les paroles, tous les \u00e9crits seront inutiles. Non par pauvret\u00e9, mais par exc\u00e8s d&rsquo;une richesse supramentale, que seuls le silence et l&rsquo;amour peuvent exprimer.<\/p>\n<p style=\"text-align: justify;\">Un grand myst\u00e8re demeure, absolument inattendu et merveilleux.<\/p>\n<p style=\"text-align: justify;\">Lorsque nous mourrons \u00e0 nous-m\u00eames, lorsque tous les souvenirs du pass\u00e9 sont br\u00fbl\u00e9s dans l&rsquo;incandescence d&rsquo;un Pr\u00e9sent Eternel, lorsque toutes les illusions d&rsquo;une continuit\u00e9 personnelle se sont \u00e9vanouies, l&rsquo;homme, loin d&rsquo;\u00eatre d\u00e9shumanis\u00e9, r\u00e9alise la pl\u00e9nitude de son humanit\u00e9.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;histoire d&rsquo;un Univers peut \u00eatre compar\u00e9e au jeu d&rsquo;une symphonie cosmique. Quoique fondamentalement Une, la symphonie est compos\u00e9e de milliards de notes, chacune dou\u00e9e d&rsquo;une originalit\u00e9, d&rsquo;une unicit\u00e9.<\/p>\n<p style=\"text-align: justify;\">Nous laissons r\u00e9sonner la note particuli\u00e8re inh\u00e9rente \u00e0 notre unicit\u00e9 dans la grande symphonie cosmique, d\u00e8s l&rsquo;instant o\u00f9 nous mourrons \u00e0 nous-m\u00eames. L\u00e0 r\u00e9side le grand paradoxe. Loin de sombrer dans une uniformit\u00e9 st\u00e9rile, nous nous int\u00e9grons aux rythmes d&rsquo;une cr\u00e9ation de tous les instants. D\u00e8s cet instant, notre singularit\u00e9 n&rsquo;est plus la singularit\u00e9 boiteuse que nous nous construisions de propos d\u00e9lib\u00e9r\u00e9s dans un \u00e9tat d&rsquo;\u00e9go\u00efsme, d&rsquo;ignorance et de sous-conscience. Au contraire. Si nous mourrons \u00e0 nous-m\u00eames, nous laissons appara\u00eetre en nous une singularit\u00e9, une originalit\u00e9 cr\u00e9atrice exprimant pleinement les potentialit\u00e9s infinies de la vie universelle en un point donn\u00e9.<\/p>\n<p style=\"text-align: justify;\">Telles sont les plus hautes possibilit\u00e9s de la nature totale de l&rsquo;homme. Elles sont in\u00e9puisables.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le concept d&rsquo;Unit\u00e9 fondamentale d&rsquo;un Univers Homog\u00e8ne, la nature absolument nouvelle de cet Univers, qui n&rsquo;est plus mat\u00e9riel comme nous concevions la mati\u00e8re, ni spirituel comme traditionnellement nous concevions l&rsquo;esprit, sont autant d&rsquo;\u00e9l\u00e9ments attirant l&rsquo;attention des esprits attentifs.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[66],"tags":[9],"class_list":["post-131","post","type-post","status-publish","format-standard","hentry","category-r-linssen","tag-science-et-spiritualite"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Intelligence de l&#039;Energie par Robert Linssen - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.revue3emillenaire.com\/blog\/intelligence-de-lenergie-par-robert-linssen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intelligence de l&#039;Energie par Robert Linssen - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\" \/>\n<meta property=\"og:description\" content=\"Le concept d&#039;Unit\u00e9 fondamentale d&#039;un Univers Homog\u00e8ne, la nature absolument nouvelle de cet Univers, qui n&#039;est plus mat\u00e9riel comme nous concevions la mati\u00e8re, ni spirituel comme traditionnellement nous concevions l&#039;esprit, sont autant d&#039;\u00e9l\u00e9ments attirant l&#039;attention des esprits attentifs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.revue3emillenaire.com\/blog\/intelligence-de-lenergie-par-robert-linssen\/\" \/>\n<meta property=\"og:site_name\" content=\"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\" \/>\n<meta property=\"article:published_time\" content=\"2008-09-27T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2010-01-09T17:42:05+00:00\" \/>\n<meta name=\"author\" content=\"3e mill\u00e9naire\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"3e mill\u00e9naire\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"28 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/intelligence-de-lenergie-par-robert-linssen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/intelligence-de-lenergie-par-robert-linssen\\\/\"},\"author\":{\"name\":\"3e mill\u00e9naire\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#\\\/schema\\\/person\\\/9a3a7cc4ccaa707f402d4394327106d5\"},\"headline\":\"Intelligence de l&#39;Energie par Robert Linssen\",\"datePublished\":\"2008-09-27T00:00:00+00:00\",\"dateModified\":\"2010-01-09T17:42:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/intelligence-de-lenergie-par-robert-linssen\\\/\"},\"wordCount\":5657,\"commentCount\":0,\"keywords\":[\"Science et spiritualit\u00e9\"],\"articleSection\":[\"Linssen Robert\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/intelligence-de-lenergie-par-robert-linssen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/intelligence-de-lenergie-par-robert-linssen\\\/\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/intelligence-de-lenergie-par-robert-linssen\\\/\",\"name\":\"Intelligence de l&#39;Energie par Robert Linssen - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#website\"},\"datePublished\":\"2008-09-27T00:00:00+00:00\",\"dateModified\":\"2010-01-09T17:42:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#\\\/schema\\\/person\\\/9a3a7cc4ccaa707f402d4394327106d5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/intelligence-de-lenergie-par-robert-linssen\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/intelligence-de-lenergie-par-robert-linssen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/intelligence-de-lenergie-par-robert-linssen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intelligence de l&#39;Energie par Robert Linssen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/\",\"name\":\"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\",\"description\":\"L&#039;Homme en devenir\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#\\\/schema\\\/person\\\/9a3a7cc4ccaa707f402d4394327106d5\",\"name\":\"3e mill\u00e9naire\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intelligence de l&#39;Energie par Robert Linssen - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.revue3emillenaire.com\/blog\/intelligence-de-lenergie-par-robert-linssen\/","og_locale":"fr_FR","og_type":"article","og_title":"Intelligence de l&#39;Energie par Robert Linssen - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","og_description":"Le concept d'Unit\u00e9 fondamentale d'un Univers Homog\u00e8ne, la nature absolument nouvelle de cet Univers, qui n'est plus mat\u00e9riel comme nous concevions la mati\u00e8re, ni spirituel comme traditionnellement nous concevions l'esprit, sont autant d'\u00e9l\u00e9ments attirant l'attention des esprits attentifs.","og_url":"https:\/\/www.revue3emillenaire.com\/blog\/intelligence-de-lenergie-par-robert-linssen\/","og_site_name":"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","article_published_time":"2008-09-27T00:00:00+00:00","article_modified_time":"2010-01-09T17:42:05+00:00","author":"3e mill\u00e9naire","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"3e mill\u00e9naire","Dur\u00e9e de lecture estim\u00e9e":"28 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.revue3emillenaire.com\/blog\/intelligence-de-lenergie-par-robert-linssen\/#article","isPartOf":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/intelligence-de-lenergie-par-robert-linssen\/"},"author":{"name":"3e mill\u00e9naire","@id":"https:\/\/www.revue3emillenaire.com\/blog\/#\/schema\/person\/9a3a7cc4ccaa707f402d4394327106d5"},"headline":"Intelligence de l&#39;Energie par Robert Linssen","datePublished":"2008-09-27T00:00:00+00:00","dateModified":"2010-01-09T17:42:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/intelligence-de-lenergie-par-robert-linssen\/"},"wordCount":5657,"commentCount":0,"keywords":["Science et spiritualit\u00e9"],"articleSection":["Linssen Robert"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.revue3emillenaire.com\/blog\/intelligence-de-lenergie-par-robert-linssen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.revue3emillenaire.com\/blog\/intelligence-de-lenergie-par-robert-linssen\/","url":"https:\/\/www.revue3emillenaire.com\/blog\/intelligence-de-lenergie-par-robert-linssen\/","name":"Intelligence de l&#39;Energie par Robert Linssen - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","isPartOf":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/#website"},"datePublished":"2008-09-27T00:00:00+00:00","dateModified":"2010-01-09T17:42:05+00:00","author":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/#\/schema\/person\/9a3a7cc4ccaa707f402d4394327106d5"},"breadcrumb":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/intelligence-de-lenergie-par-robert-linssen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.revue3emillenaire.com\/blog\/intelligence-de-lenergie-par-robert-linssen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.revue3emillenaire.com\/blog\/intelligence-de-lenergie-par-robert-linssen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.revue3emillenaire.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Intelligence de l&#39;Energie par Robert Linssen"}]},{"@type":"WebSite","@id":"https:\/\/www.revue3emillenaire.com\/blog\/#website","url":"https:\/\/www.revue3emillenaire.com\/blog\/","name":"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","description":"L&#039;Homme en devenir","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.revue3emillenaire.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.revue3emillenaire.com\/blog\/#\/schema\/person\/9a3a7cc4ccaa707f402d4394327106d5","name":"3e mill\u00e9naire","url":"https:\/\/www.revue3emillenaire.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/posts\/131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/comments?post=131"}],"version-history":[{"count":0,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/posts\/131\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/media?parent=131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/categories?post=131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/tags?post=131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}