{"id":18131,"date":"2019-12-26T01:26:12","date_gmt":"2019-12-26T00:26:12","guid":{"rendered":"https:\/\/www.revue3emillenaire.com\/blog\/?p=18131"},"modified":"2019-12-26T01:26:12","modified_gmt":"2019-12-26T00:26:12","slug":"lanti-enseignement-de-u-g-krishnamurti","status":"publish","type":"post","link":"https:\/\/www.revue3emillenaire.com\/blog\/lanti-enseignement-de-u-g-krishnamurti\/","title":{"rendered":"L&rsquo;Anti-Enseignement de U.G. Krishnamurti"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">U.G. Krishnamurti (1918-2007) a v\u00e9cu une transformation totale en 1967. Selon un de ses biographes (Mukunda Rao) avec qui nous sommes en accord, son anti-enseignement est pass\u00e9 par trois phases : \u00ab Nous pouvons discerner approximativement trois phases dans la vie d&rsquo;U.G. et son anti-enseignement. La premi\u00e8re a dur\u00e9 de 1967 jusqu&rsquo;\u00e0 la fin des ann\u00e9es 70, o\u00f9 son approche peut \u00eatre qualifi\u00e9e de cru, douce, tendre et obligeante. \u00c0 cette \u00e9poque, U.G. parlait avec approbation, bien que prudemment, d&rsquo;autres sages et de leurs enseignements, ainsi que de certains textes religieux. C&rsquo;\u00e9tait, en un sens, un U.G. diff\u00e9rent, ouvert et persuasif, qui emmenait ou conduisait ses auditeurs, avec tant de sympathie et de sollicitude, dans un voyage d&rsquo;exploration du fonctionnement de l&rsquo;esprit et du corps. Il leur faisait remarquer la non-pertinence des m\u00e9thodes et des techniques de r\u00e9alisation de soi, l&rsquo;\u00e9tat non naturel et ses probl\u00e8mes, l&rsquo;\u00e9tat naturel en tant qu&rsquo;\u00e9tat physiologique de l&rsquo;\u00eatre et comment il pouvait avoir un impact ou changer la conscience du monde, etc. (Lire le livre \u00e9dit\u00e9 par Mukunda Rao <i>The biology of enlightenment<\/i>)<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\"><a name=\"__UnoMark__1125_1801223381\"><\/a> Pendant la deuxi\u00e8me phase, dans les ann\u00e9es 1980 et 1990, il a eu l&rsquo;air d&rsquo;un sage enrag\u00e9. Ses paroles \u00e9taient profondes, explosives et cathartiques. Il \u00e9tait comme un feu qui r\u00e9duisait tout en cendres pour qu&rsquo;un nouveau d\u00e9part puisse \u00eatre pris, sans la moindre trace de tristesse. C&rsquo;est aussi \u00e0 cette \u00e9poque qu&rsquo;il est devenu un personnage public en donnant des interviews \u00e0 la t\u00e9l\u00e9vision et des conf\u00e9rences \u00e0 la radio afin de toucher les gens du monde entier. Tous les grands r\u00e9cits et symboles des diverses religions et cultures, id\u00e9ologies et philosophies \u00e9taient subvertis ou rejet\u00e9s comme autant de d\u00e9chets. Il n&rsquo;y avait rien de sacr\u00e9 ou de sacro-saint, rien d&rsquo;indiscutable et d&rsquo;incontestable : la subversion \u00e9tait la voie, puis la subversion aussi \u00e9tait subvertie et d\u00e9molie. Il \u00e9tait l&rsquo;\u00eatre primordial, le membre non converti de la race humaine, faisant sauter tous les cadres de pens\u00e9e, remettant en question le fondement m\u00eame de la culture humaine. Pendant cette phase, les gens l&rsquo;appelaient, en particulier dans les m\u00e9dias, le sage enrag\u00e9, un naxalite cosmique, un anti-gourou, etc., et cette image de lui comme sage enrag\u00e9 a \u00e9t\u00e9 en quelque sorte surestim\u00e9e et fix\u00e9e m\u00eame dans l&rsquo;esprit des admirateurs d&rsquo;U.G., sans parler des m\u00e9dias et de ceux qui n&rsquo;avaient qu&rsquo;une vague id\u00e9e de qui il \u00e9tait et de son enseignement. Cela a seulement montr\u00e9 combien il \u00e9tait difficile de comprendre la v\u00e9rit\u00e9 non duelle qu&rsquo;il essayait de transmettre, pris dans un mode de pens\u00e9e et d&rsquo;\u00eatre dualiste et mari\u00e9 \u00e0 un id\u00e9al ou \u00e0 un autre. Comme le Bouddha \u2013 qui a fait tomber tous les r\u00e9cits comme de simples constructions mentales et une entrave \u00e0 l&rsquo;entr\u00e9e dans l&rsquo;\u00e9tat de nirvana \u2013 en faisant exploser toutes nos id\u00e9es et id\u00e9aux, il n&rsquo;a pas seulement arrach\u00e9 le tapis de sous nos pieds, mais il a aussi d\u00e9truit le sol illusoire sur lequel nous nous tenions. Il ne nous a pas permis de nous accrocher \u00e0 un quelconque mensonge, car un mensonge est une erreur qui a falsifi\u00e9 nos vies. La v\u00e9rit\u00e9, aussi dure, bouleversante et choquante soit-elle, devait nous \u00eatre apport\u00e9e. (Presque tous les livres publi\u00e9s des entretiens d&rsquo;U.G. viennent de cette p\u00e9riode).<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Les dix derni\u00e8res ann\u00e9es avant la mort d&rsquo;U.G. peuvent \u00eatre qualifi\u00e9es de phase d&rsquo;enjouement et de rire. Puisque toutes les expressions \u00e9taient fausses, m\u00eame dire que quelque chose \u00e9tait faux \u00e9tait faux, il n&rsquo;y avait que le rejet total et complet, et il y avait le rire. Il y avait les doux et d\u00e9licieux rires de Krishna, le buveur de lait, et l&rsquo;attahasa ou rire apocalyptique de Shiva, le buveur de poison. Cependant, l&rsquo;essentiel de son approche \u00e9tait toujours le m\u00eame. Il d\u00e9crit la fa\u00e7on dont nous fonctionnons \u00e0 l&rsquo;\u00e9tat non naturel, pris dans un monde d&rsquo;oppos\u00e9s, luttant constamment pour devenir autre chose que ce que nous sommes, et \u00e0 la recherche de dieux et de buts inexistants. Comment nous pensons et fonctionnons tous dans une sph\u00e8re de pens\u00e9e, tout comme nous partageons tous la m\u00eame atmosph\u00e8re pour respirer. Comment et pourquoi le soi, qui est de nature autoprotectrice et fasciste, n&rsquo;est pas l&rsquo;instrument qui nous aide \u00e0 vivre en harmonie avec la vie qui nous entoure. Pr\u00e9f\u00e9rant le terme \u00e9tat naturel \u00e0 celui d&rsquo;illumination, il a insist\u00e9 sur le fait que toute transformation qu&rsquo;il avait subie \u00e9tait \u00e0 l&rsquo;int\u00e9rieur de la structure du corps humain et pas du tout dans l&rsquo;esprit. Et il a d\u00e9crit l&rsquo;\u00e9tat naturel comme un \u00e9tat d&rsquo;\u00eatre physique et physiologique pur et simple. C&rsquo;est l&rsquo;\u00e9tat de conscience primordiale sans primitivisme, ou l&rsquo;\u00e9tat de conscience indivise, o\u00f9 tous les d\u00e9sirs et la peur, et la recherche du bonheur et du plaisir, de Dieu et de la v\u00e9rit\u00e9, ont pris fin. C&rsquo;est un \u00e9tat acausal de non-connaissance. Si il a marqu\u00e9 la continuit\u00e9 cr\u00e9ative des traditions d&rsquo;\u00e9veil du Bouddha, des Upanishads et des sages indiens ult\u00e9rieurs, U.G. a aussi marqu\u00e9 une rupture radicale avec les traditions d&rsquo;\u00e9veil dans la mani\u00e8re dont il a d\u00e9psychologis\u00e9 et d\u00e9mystifi\u00e9 la notion d&rsquo;\u00e9veil, et l&rsquo;a red\u00e9finie comme l&rsquo;\u00e9tat naturel en termes physiques et physiologiques. Plus important encore, en supprimant tous les grands r\u00e9cits et \u00e9pist\u00e9mologies, il nous a offert non seulement une lib\u00e9ration de la tyrannie des symboles et des id\u00e9es sacr\u00e9es, des dieux et des buts, mais aussi un avant-go\u00fbt de ce vaste vide. \u00bb<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">U.G. n\u2019\u00e9tait pas parent de l&rsquo;autre Krishnamurti, bien plus connu. Nombreux admirateurs des deux Krishnamurti croient que les deux enseignements sont tr\u00e8s diff\u00e9rents. Mais \u00e0 notre avis leurs critiques de la soci\u00e9t\u00e9 et essentiellement du fonctionnement du moi et de ses fuites sont exactement les m\u00eames. Avec quelques expressions diff\u00e9rentes et l&rsquo;insistance d&rsquo;U.G. sur la transformation physiologique corporelle (mais ce n&rsquo;est plus le corps que nous imaginons conna\u00eetre) et ses critiques r\u00e9p\u00e9t\u00e9s envers l&rsquo;autre Krishnamurti, cette similitude est brouill\u00e9e. Enfin du fait que nombreuses citations d&rsquo;U.G. sont produites abruptement sans explications, laisse croire qu&rsquo;elles sont plus r\u00e9volutionnaires que les dire de Krishnamurti qui lui prenait soin d&rsquo;expliquer les m\u00e9canismes du moi.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Une remarque finale sur la communaut\u00e9 des admirateurs d&rsquo;U.G. : \u00c0 part quelques personnes qui ont travaill\u00e9 sur eux-m\u00eames les cons\u00e9quences des dire d&rsquo;U.G., comme Mukunda Rao par exemple, beaucoup tombent dans un cynisme des plus \u00e9go\u00efstes. Ces admirateurs, par manque de maturit\u00e9 int\u00e9rieure, ne savent plus \u00e9couter qui que ce soit : Que quelqu&rsquo;un ose vivre ou dire quelque chose, c&rsquo;est assur\u00e9ment son \u00e9go. Cette situation est regrettable.<\/span><\/span><\/p>\n<p class=\"western\" align=\"right\">3M<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Extraits de Rao, Mukunda<i>. Belief and Beyond : Adventures in Consciousness from the Upanishads to Modern Times . <\/i>HarperCollins Publishers India<i>.<\/i><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\"><i>Traduction libre<\/i><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\"><a name=\"__DdeLink__206_2877624630\"><\/a> Je n&rsquo;ai pas d&rsquo;enseignement, et il n&rsquo;y en aura jamais. \u00ab Enseigner \u00bb n&rsquo;est pas le mot qui convient. Un enseignement implique une m\u00e9thode ou un syst\u00e8me, une technique ou un nouveau mode de pens\u00e9e \u00e0 appliquer pour provoquer une transformation dans votre mode de vie. Ce que je dis est en dehors du domaine de l&rsquo;enseignabilit\u00e9 ; c&rsquo;est simplement une description de la fa\u00e7on dont je fonctionne. C&rsquo;est juste une description de l&rsquo;\u00e9tat naturel de l&rsquo;homme \u2013 c&rsquo;est la fa\u00e7on dont vous, d\u00e9pouill\u00e9s des machinations de la pens\u00e9e, fonctionnez aussi.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">L&rsquo;\u00e9tat naturel n&rsquo;est pas l&rsquo;\u00e9tat d&rsquo;un homme qui s&rsquo;est r\u00e9alis\u00e9, ou qui a r\u00e9alis\u00e9 Dieu ; ce n&rsquo;est pas une chose \u00e0 r\u00e9aliser ou \u00e0 atteindre, ce n&rsquo;est pas une chose \u00e0 vouloir dans l&rsquo;existence ; c&rsquo;est l\u00e0 \u2013 c&rsquo;est l&rsquo;\u00e9tat vivant. Cet \u00e9tat n&rsquo;est que l&rsquo;activit\u00e9 fonctionnelle de la vie. Par \u00ab vie \u00bb, je ne veux pas dire quelque chose d&rsquo;abstrait ; c&rsquo;est la vie des sens, fonctionnant naturellement sans l&rsquo;interf\u00e9rence de la pens\u00e9e. La pens\u00e9e est un intrus, qui s&rsquo;immisce dans les affaires des sens. Elle a un motif de profit : la pens\u00e9e dirige l&rsquo;activit\u00e9 des sens pour en tirer quelque chose, et les utilise pour se donner une continuit\u00e9.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Votre \u00e9tat naturel n&rsquo;a aucun rapport avec les \u00e9tats religieux de bonheur, de b\u00e9atitude et d&rsquo;extase ; ces \u00e9tats se situent dans le champ de l&rsquo;exp\u00e9rience. Ceux qui ont conduit l&rsquo;homme dans sa recherche de la religiosit\u00e9 au cours des si\u00e8cles ont peut-\u00eatre fait l&rsquo;exp\u00e9rience de ces \u00e9tats religieux. Vous le pouvez aussi. Ce sont des \u00e9tats d&rsquo;\u00eatre induits par la pens\u00e9e, et comme ils viennent, ils s&rsquo;en vont. La Conscience de Krishna, la Conscience de Bouddha, la Conscience du Christ, ou de tout ce que vous voulez, induisent tous des voyages dans la mauvaise direction : ils sont tous dans le champ du temps. L&rsquo;intemporel ne peut jamais \u00eatre exp\u00e9riment\u00e9, ne peut jamais \u00eatre saisi, contenu et encore moins exprim\u00e9 par un homme. Ce sentier battu ne vous m\u00e8nera nulle part.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\"><b>Y a-t-il un au-del\u00e0 ou une intemporalit\u00e9 ? <\/b><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Y a-t-il un au-del\u00e0 ? Parce que vous n&rsquo;\u00eates pas int\u00e9ress\u00e9 par les choses du quotidien et les \u00e9v\u00e9nements qui vous entourent, vous avez invent\u00e9 une chose appel\u00e9e \u00ab l&rsquo;au-del\u00e0 \u00bb, ou \u00ab l&rsquo;intemporalit\u00e9 \u00bb, ou \u00ab Dieu \u00bb, \u00ab la V\u00e9rit\u00e9 \u00bb, \u00ab la R\u00e9alit\u00e9 \u00bb, \u00ab Brahman \u00bb, \u00ab l&rsquo;illumination \u00bb, ou quoi que ce soit, et vous cherchez cela. Il n&rsquo;y a peut-\u00eatre pas d&rsquo;au-del\u00e0. Vous ne savez rien de cet au-del\u00e0 ; tout ce que vous savez, c&rsquo;est ce qu&rsquo;on vous a racont\u00e9, la connaissance que vous avez \u00e0 ce sujet. Donc vous projetez cette connaissance.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Ce que vous appelez \u00ab l&rsquo;au-del\u00e0 \u00bb est cr\u00e9\u00e9 par la connaissance que vous avez de cet au-del\u00e0 ; et n&rsquo;importe quelle connaissance que vous avez d&rsquo;un au-del\u00e0 est exactement ce que vous allez exp\u00e9rimenter. La connaissance cr\u00e9e l&rsquo;exp\u00e9rience, et l&rsquo;exp\u00e9rience renforce ensuite la connaissance. Ce que vous savez ne peut jamais \u00eatre l&rsquo;au-del\u00e0. Quoi que vous exp\u00e9rimentez n&rsquo;est pas l&rsquo;au-del\u00e0. S&rsquo;il y a un au-del\u00e0, ce mouvement de \u00ab vous \u00bb est absent. L&rsquo;absence de ce mouvement est probablement l&rsquo;au-del\u00e0, mais l&rsquo;au-del\u00e0 ne peut jamais \u00eatre exp\u00e9riment\u00e9 par vous ; c&rsquo;est quand le \u00ab vous \u00bb n&rsquo;est pas l\u00e0. Pourquoi essayez-vous d&rsquo;avoir l&rsquo;exp\u00e9rience d&rsquo;une chose qui ne peut \u00eatre exp\u00e9riment\u00e9e ?<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Dans l&rsquo;\u00e9tat naturel, le mouvement du moi est absent. L&rsquo;absence de ce mouvement est probablement l&rsquo;au-del\u00e0 mais cela ne peut jamais \u00eatre exp\u00e9riment\u00e9 par vous. C&rsquo;est quand le \u00ab vous \u00bb est absent. D\u00e8s que vous traduisez, le \u00ab vous \u00bb est l\u00e0. Vous regardez quelque chose et vous le reconnaissez. La pens\u00e9e interf\u00e8re avec la sensation en traduisant. Soit vous pensez \u00e0 quelque chose qui n&rsquo;a rien \u00e0 voir avec le fonctionnement des sens en ce moment, soit vous \u00e9tiquetez. C&rsquo;est tout ce qu&rsquo;il y a. Le mot vous s\u00e9pare de ce que vous regardez, cr\u00e9ant ainsi le vous. Autrement, il n&rsquo;y a pas d&rsquo;espace entre les deux.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\"><b>L&rsquo;esprit est un mythe <\/b><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">La s\u00e9paration entre le corps et l&rsquo;esprit doit prendre fin. En fait, il n&rsquo;y a pas de s\u00e9paration. Je n&rsquo;ai pas d&rsquo;objection au mot esprit, mais il ne se trouve pas dans un endroit ou une r\u00e9gion en particulier. Chaque cellule de votre syst\u00e8me a son propre esprit et son fonctionnement est tr\u00e8s diff\u00e9rent de celui des autres cellules.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">L&rsquo;esprit ou la pens\u00e9e n&rsquo;est ni le v\u00f4tre ni le mien. C&rsquo;est notre h\u00e9ritage commun. Il n&rsquo;y a pas de chose telle que votre esprit et mon esprit (c&rsquo;est dans ce sens que l&rsquo;esprit est un mythe). Il n&rsquo;y a que l&rsquo;esprit, la totalit\u00e9 de tout ce qui a \u00e9t\u00e9 connu, ressenti et v\u00e9cu par l&rsquo;homme, transmis de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration. Nous pensons et fonctionnons tous dans cette sph\u00e8re de pens\u00e9e tout comme nous partageons tous la m\u00eame atmosph\u00e8re pour respirer.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">La pens\u00e9e dans sa naissance, dans son origine, dans son contenu, dans son expression, et dans son action est tr\u00e8s fasciste. Quand j&rsquo;utilise le mot \u00ab fasciste \u00bb, je ne l&#8217;emploie pas dans le sens politique, mais pour signifier que la pens\u00e9e contr\u00f4le et fa\u00e7onne nos sentiments et nos actions. C&rsquo;est donc un m\u00e9canisme tr\u00e8s protecteur. Cela nous a sans doute aid\u00e9 \u00e0 \u00eatre ce que nous sommes aujourd&rsquo;hui. Cela nous a aid\u00e9 \u00e0 cr\u00e9er notre haute technologie et a rendu notre vie tr\u00e8s confortable. Elle nous a \u00e9galement permis de d\u00e9couvrir les lois de la nature. Mais la pens\u00e9e est un m\u00e9canisme tr\u00e8s protecteur et s&rsquo;int\u00e9resse \u00e0 sa propre survie. En m\u00eame temps, la pens\u00e9e est fondamentalement oppos\u00e9e au fonctionnement de cet organisme vivant.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">C&rsquo;est la pens\u00e9e qui a invent\u00e9 les id\u00e9es de cause et effet. Il se peut qu&rsquo;il n&rsquo;y ait pas du tout une telle chose comme la cause. Chaque \u00e9v\u00e9nement est un \u00e9v\u00e9nement individuel et ind\u00e9pendant. Nous relions tous ces \u00e9v\u00e9nements et essayons de cr\u00e9er l\u2019histoire de nos vies. Mais en fait, chaque \u00e9v\u00e9nement est un \u00e9v\u00e9nement ind\u00e9pendant. Si nous acceptons le fait que chaque \u00e9v\u00e9nement est un \u00e9v\u00e9nement ind\u00e9pendant dans nos vies, cela cr\u00e9e un \u00e9norme probl\u00e8me de maintien de ce que nous appelons l&rsquo;identit\u00e9. Et l&rsquo;identit\u00e9 est le facteur le plus important dans nos vies. Nous sommes capables de maintenir cette identit\u00e9 par l&rsquo;utilisation constante de la m\u00e9moire, qui est aussi pens\u00e9e. Cette utilisation constante de la m\u00e9moire ou de l&rsquo;identit\u00e9, ou peu importe comment vous l&rsquo;appelez, consomme une \u00e9norme quantit\u00e9 d&rsquo;\u00e9nergie, et elle ne nous laisse aucune \u00e9nergie pour faire face aux probl\u00e8mes de notre vie. Y a-t-il un moyen de se lib\u00e9rer de l&rsquo;identit\u00e9 ? Comme je l&rsquo;ai dit, la pens\u00e9e ne peut que cr\u00e9er des probl\u00e8mes ; elle ne peut pas nous aider \u00e0 les r\u00e9soudre. Par la pens\u00e9e, r\u00e9flexive sur elle-m\u00eame, nous ne faisons qu&rsquo;aiguiser cet instrument. Toutes les philosophies ne nous aident qu&rsquo;\u00e0 aiguiser cet instrument.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">La pens\u00e9e est essentielle \u00e0 la survie dans ce monde. Mais elle ne peut nous aider \u00e0 atteindre les objectifs que nous nous sommes fix\u00e9s. Les objectifs sont inatteignables par la pens\u00e9e. La qu\u00eate du bonheur, comme vous l&rsquo;avez mentionn\u00e9, est impossible parce qu&rsquo;il n&rsquo;y a pas de bonheur permanent. Il y a des moments de bonheur, et il y a des moments de tristesse. Mais l&rsquo;exigence d&rsquo;\u00eatre dans un \u00e9tat permanent de bonheur est l&rsquo;ennemi de ce corps. Ce corps est int\u00e9ress\u00e9 \u00e0 maintenir la sensibilit\u00e9 des perceptions sensorielles et aussi la sensibilit\u00e9 du syst\u00e8me nerveux. C&rsquo;est tr\u00e8s essentiel pour la survie de ce corps. Lorsque nous utilisons l&rsquo;instrument de la pens\u00e9e pour essayer d&rsquo;atteindre l&rsquo;objectif impossible du bonheur permanent, la sensibilit\u00e9 de ce corps est d\u00e9truite. Par cons\u00e9quent, le corps rejette tout ce qui nous int\u00e9resse \u2013 le bonheur permanent et le plaisir permanent. Ainsi, nous ne pouvons pas r\u00e9ussir dans cette tentative d&rsquo;\u00eatre dans un \u00e9tat de bonheur permanent.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">La pens\u00e9e ne peut jamais saisir le mouvement de la vie, elle est beaucoup trop lente. C&rsquo;est comme l&rsquo;\u00e9clair et le tonnerre. Ils se produisent simultan\u00e9ment, mais le son, qui voyage plus lentement que la lumi\u00e8re, vous atteint plus tard, cr\u00e9ant l&rsquo;illusion de deux \u00e9v\u00e9nements distincts. Seules les sensations et perceptions physiologiques naturelles peuvent suivre le cours de la vie.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Vous avez, par l&rsquo;id\u00e9ation et la mentation, cr\u00e9\u00e9 vos propres pens\u00e9es que vous consid\u00e9rez comme les v\u00f4tres, tout comme lorsque diff\u00e9rentes couleurs sont m\u00e9lang\u00e9es en diverses teintes, mais toutes peuvent \u00eatre r\u00e9duites aux sept couleurs de base que l&rsquo;on trouve dans la nature. Ce que vous pensez \u00eatre vos pens\u00e9es ne sont en fait que des combinaisons et des permutations des pens\u00e9es des autres.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\"><b>Connaissances et exp\u00e9rience <\/b><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Tout ce que vous exp\u00e9rimentez \u2013 paix, bonheur, silence, b\u00e9atitude, extase, joie, et Dieu sait quoi \u2013 sera d\u00e9pass\u00e9 et de seconde main. Vous avez d\u00e9j\u00e0 des connaissances sur toutes ces choses. Le fait que vous soyez dans un \u00e9tat de b\u00e9atitude ou dans un \u00e9tat de grand silence signifie que vous en avez connaissance. Il faut conna\u00eetre une chose pour en avoir l&rsquo;exp\u00e9rience. Cette connaissance n&rsquo;a rien de merveilleux ou de m\u00e9taphysique ; \u00ab banc \u00bb, \u00ab sac \u00bb, \u00ab sac rouge \u00bb, c&rsquo;est de la connaissance. La connaissance est quelque chose qui est mis en vous par quelqu&rsquo;un d&rsquo;autre, qui l&rsquo;a obtenu de quelqu&rsquo;un d&rsquo;autre ; ce n&rsquo;est pas la v\u00f4tre. Pouvez-vous faire l&rsquo;exp\u00e9rience d&rsquo;une chose simple comme ce banc qui se trouve en face de vous ? Non, vous ne faites l&rsquo;exp\u00e9rience que des connaissances que vous avez sur lui. Et la connaissance est venue d&rsquo;une agence ext\u00e9rieure, toujours. Vous pensez les pens\u00e9es de votre soci\u00e9t\u00e9, vous ressentez les sentiments de votre soci\u00e9t\u00e9 et vous faites l&rsquo;exp\u00e9rience des exp\u00e9riences de votre soci\u00e9t\u00e9 ; il n&rsquo;y a pas de nouvelle exp\u00e9rience.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">La connaissance n&rsquo;est pas quelque chose de myst\u00e9rieux ou de mystique. Vous savez que vous \u00eates heureux, et vous avez des th\u00e9ories sur le fonctionnement du ventilateur, de la lumi\u00e8re \u2013 c&rsquo;est la connaissance dont nous parlons. Vous introduisez une autre connaissance, la \u00ab connaissance spirituelle \u00bb, mais \u2013 connaissance spirituelle, connaissance sensuelle \u2013 quelle est la diff\u00e9rence ? Nous leur donnons des noms. Les fantasmes sur Dieu sont acceptables, mais les fantasmes sur le sexe sont appel\u00e9s \u00ab sensuels \u00bb, \u00ab physiques \u00bb. Il n&rsquo;y a pas de diff\u00e9rence entre les deux ; l&rsquo;un est socialement acceptable, l&rsquo;autre non. Vous limitez la connaissance \u00e0 un domaine particulier de l&rsquo;exp\u00e9rience, alors elle devient \u00ab sensuelle \u00bb, et l&rsquo;autre devient \u00ab spirituelle \u00bb ? En fait, tout est sensuel.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\"><b>D\u00e9sir et \u00e9go\u00efsme <\/b><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">L&rsquo;homme est toujours \u00e9go\u00efste, et il le restera tant qu&rsquo;il pratiquera l&rsquo;altruisme en tant que vertu. Je n&rsquo;ai rien contre les \u00e9go\u00efstes. Je ne veux pas parler de l&rsquo;altruisme \u2013 il n&rsquo;a aucun fondement \u00e0 tout cela. Vous dites : \u00ab Je serai un homme d\u00e9sint\u00e9ress\u00e9 demain. Demain, je serai un homme merveilleux \u00bb \u2013 mais jusqu&rsquo;\u00e0 ce que demain arrive (ou apr\u00e8s-demain, ou la vie suivante), vous resterez \u00e9go\u00efste. Qu&rsquo;entendez-vous par \u00ab d\u00e9sint\u00e9ressement \u00bb ? Vous r\u00e9p\u00e9tez \u00e0 tout le monde d&rsquo;\u00eatre d\u00e9sint\u00e9ress\u00e9. Quel en est le but ? Je n&rsquo;ai jamais dit \u00e0 personne \u00ab Ne soyez pas \u00e9go\u00efste \u00bb. Soyez \u00e9go\u00efste, restez \u00e9go\u00efste ! \u2013 c&rsquo;est mon message. Vouloir l&rsquo;illumination est de l&rsquo;\u00e9go\u00efsme. La charit\u00e9 distribu\u00e9e par le riche est aussi de l&rsquo;\u00e9go\u00efsme : on se souviendra de lui comme d\u2019un homme g\u00e9n\u00e9reux ; et vous \u00e9l\u00e8verez une statue \u00e0 son effigie.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">On vous a dit que vous devriez pratiquer l&rsquo;absence de d\u00e9sir. Vous avez pratiqu\u00e9 l&rsquo;absence de d\u00e9sir pendant trente ou quarante ans, mais les d\u00e9sirs sont toujours l\u00e0. Donc quelque chose doit clocher quelque part. Il n&rsquo;y a rien de faux avec le d\u00e9sir ; quelque chose doit \u00eatre faux avec celui qui vous a dit de pratiquer l&rsquo;absence de d\u00e9sir. Ceci (le d\u00e9sir) est une r\u00e9alit\u00e9 ; cela (l&rsquo;absence de d\u00e9sir) est faux \u2013 cela vous falsifie. Le d\u00e9sir est l\u00e0. Le d\u00e9sir en tant que tel ne peut pas \u00eatre faux, ne peut pas \u00eatre faux, parce qu&rsquo;il est l\u00e0.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Vous esp\u00e9rez que vous pourrez r\u00e9soudre le probl\u00e8me du d\u00e9sir par la pens\u00e9e, \u00e0 cause de ce mod\u00e8le de saint qui, croyez-vous, a contr\u00f4l\u00e9 ou \u00e9limin\u00e9 le d\u00e9sir. Si cet homme n&rsquo;a aucun d\u00e9sir comme vous l&rsquo;imaginez, c&rsquo;est un cadavre. Ne croyez pas du tout cet homme ! Un tel homme construit une certaine organisation, et vit dans le luxe, que vous lui payez. Vous l&rsquo;entretenez. Il le fait pour gagner sa vie. Il y a toujours un fou dans le monde qui se fait avoir. De temps en temps, il vous permet de vous prosterner devant lui. Vous seriez surpris si vous viviez avec lui. Vous auriez le choc de votre vie si vous le voyiez l\u00e0. C&rsquo;est pourquoi ces gens restent distants \u2013 parce qu&rsquo;ils ont peur que vous les attrapiez un jour ou l&rsquo;autre. L&rsquo;homme riche a toujours peur que vous le touchiez pour de l&rsquo;argent. De m\u00eame que l&rsquo;homme religieux \u2013 il n&rsquo;entre jamais, jamais en contact avec vous. Le voir est beaucoup plus difficile que de voir le pr\u00e9sident de votre pays \u2013 c&rsquo;est beaucoup plus facile que de voir un saint homme. Il est ni ce qu&rsquo;il dit, ni ce qu&rsquo;il pr\u00e9tend \u00eatre.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\"><b>Le corps est immortel <\/b><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">C&rsquo;est le corps qui est immortel. Il ne change de forme qu&rsquo;apr\u00e8s la mort clinique, restant dans le flux de la vie sous de nouvelles formes. Le corps n&rsquo;est pas concern\u00e9 par \u00ab l&rsquo;apr\u00e8s-vie \u00bb ou toute autre forme de permanence. Il lutte pour survivre et se multiplier MAINTENANT. L&rsquo;au-del\u00e0 fictif, cr\u00e9\u00e9 par la pens\u00e9e par peur, est en r\u00e9alit\u00e9 l\u2019espoir de la m\u00eame chose, sous une forme modifi\u00e9e. Cette exigence de r\u00e9p\u00e9tition de la m\u00eame chose encore et encore est l&rsquo;exigence de la permanence. Une telle permanence est \u00e9trang\u00e8re au corps. Cette exigence de permanence par la pens\u00e9e \u00e9touffe le corps et d\u00e9forme la perception. La pens\u00e9e se voit comme le protecteur non seulement de sa propre continuit\u00e9, mais aussi de la continuit\u00e9 du corps. Les deux sont compl\u00e8tement fausses.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Au moment o\u00f9 vous mourrez, le corps commence \u00e0 se d\u00e9composer, retournant \u00e0 d&rsquo;autres formes de vie, diff\u00e9remment organis\u00e9es, ne mettant fin \u00e0 rien. La vie n&rsquo;a ni d\u00e9but ni fin. Un corps mort et mourant nourrit les fourmis affam\u00e9es qui se trouvent dans la tombe, et les cadavres en d\u00e9composition d\u00e9gagent des produits chimiques qui enrichissent le sol et qui, \u00e0 leur tour, nourrissent d&rsquo;autres formes de vie. Vous ne pouvez pas mettre fin \u00e0 votre vie, c&rsquo;est impossible. Le corps est immortel et ne pose jamais de questions stupides comme \u00ab Y a-t-il une immortalit\u00e9 ? \u00bb Il sait qu&rsquo;il prendra fin sous cette forme particuli\u00e8re, pour continuer dans d&rsquo;autres. Les questions sur la vie apr\u00e8s la mort sont toujours pos\u00e9es par peur.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Le corps humain, lorsqu&rsquo;il est d\u00e9compos\u00e9 en ses \u00e9l\u00e9ments constitutifs, n&rsquo;est pas diff\u00e9rent de l&rsquo;arbre l\u00e0 dehors ou du moustique qui suce votre sang. En gros, c&rsquo;est exactement la m\u00eame chose. Les proportions des \u00e9l\u00e9ments peuvent \u00eatre plus \u00e9lev\u00e9es dans un cas et plus faibles dans d&rsquo;autres. Vous avez quatre-vingt pour cent d&rsquo;eau dans le corps, et il y a quatre-vingt pour cent d&rsquo;eau dans les arbres et quatre-vingt pour cent d\u2019eau sur cette plan\u00e8te. C&rsquo;est donc la raison pour laquelle je maintiens que nous ne sommes rien d&rsquo;autre qu&rsquo;un concours fortuit d&rsquo;atomes. Si et quand la mort a lieu, le corps est r\u00e9organis\u00e9, ces atomes sont alors utilis\u00e9s pour maintenir les niveaux d&rsquo;\u00e9nergie dans l&rsquo;univers. \u00c0 part \u00e7a, il n&rsquo;y a pas de mort \u00e0 ce corps.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">La pens\u00e9e n&rsquo;est qu&rsquo;une r\u00e9ponse \u00e0 des stimuli. Le cerveau n&rsquo;est pas vraiment un cr\u00e9ateur, c&rsquo;est juste un contenant. La fonction du cerveau dans ce corps est seulement de prendre soin des besoins de l&rsquo;organisme physique et de maintenir sa sensibilit\u00e9, alors que la pens\u00e9e, par son interf\u00e9rence constante avec l&rsquo;activit\u00e9 sensorielle, d\u00e9truit la sensibilit\u00e9 du corps. C&rsquo;est l\u00e0 que se situe le conflit. Le conflit est entre le besoin du corps de maintenir sa sensibilit\u00e9 et l&rsquo;exigence de la pens\u00e9e de traduire chaque sensation dans le cadre de l&rsquo;activit\u00e9 sensuelle. Je ne condamne pas l&rsquo;activit\u00e9 sensuelle. L&rsquo;esprit, ou quel que soit le nom qu&rsquo;on lui donne, na\u00eet de cette sensualit\u00e9. Ainsi, toutes les activit\u00e9s de l&rsquo;esprit sont de nature sensuelle, alors que l&rsquo;activit\u00e9 du corps consiste \u00e0 r\u00e9pondre aux stimuli de l\u2019environnement. C&rsquo;est vraiment le conflit fondamental entre ce que vous appelez l&rsquo;esprit et le corps.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\"><b>Vous \u00eates ind\u00e9pendants<\/b><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Vous \u00eates perdu dans la jungle et vous n&rsquo;avez aucun moyen de trouver la sortie. La nuit approche \u00e0 grands pas. Les animaux sauvages sont l\u00e0, y compris les cobras, et vous \u00eates toujours perdu. Que faites-vous dans une telle situation ? Vous vous arr\u00eatez. Vous ne bougez plus. Tant qu&rsquo;il y a cet espoir que vous pouvez d&rsquo;une mani\u00e8re ou d&rsquo;une autre sortir de la jungle, vous continuerez ce que vous faites, \u00e0 chercher, et \u00e0 vous sentir perdu. Vous \u00eates perdu seulement parce que vous cherchez. Vous n&rsquo;avez aucun moyen de trouver votre chemin pour sortir de la jungle.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Vous pouvez l&rsquo;arr\u00eater en vous. Lib\u00e9rez-vous de cette structure sociale qui op\u00e8re en vous sans devenir antisocial, sans devenir r\u00e9formateur, sans devenir anti ceci, anti cela. Vous pouvez jeter le tout hors de votre syst\u00e8me et vous lib\u00e9rer du fardeau de cette culture, pour vous-m\u00eame et par vous-m\u00eame. Que cela soit utile ou non \u00e0 la soci\u00e9t\u00e9 ne vous concerne pas. S&rsquo;il y a un individu qui marche librement, vous n&rsquo;avez plus le sentiment \u00e9touffant de ce que cette horrible culture vous a fait. Ce n&rsquo;est ni l&rsquo;Est ni l&rsquo;Ouest, c&rsquo;est pareil. La nature humaine est exactement la m\u00eame \u2013 il n&rsquo;y a pas de diff\u00e9rence.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Je vous dis de voler de vos propres ailes. Vous pouvez marcher. Vous pouvez nager. Vous n&rsquo;allez pas couler. C&rsquo;est tout ce que je peux dire. Tant qu&rsquo;il y a de la peur, le danger de votre naufrage est presque certain. Autrement, il y a un dynamisme dans l&rsquo;eau qui vous maintient \u00e0 flot. La peur de couler est ce qui vous emp\u00eache de laisser le mouvement se produire \u00e0 sa mani\u00e8re. Vous voyez, il n&rsquo;a pas de direction. C&rsquo;est juste un mouvement sans direction. Vous essayez de manipuler et de canaliser ce mouvement dans une direction particuli\u00e8re afin d&rsquo;en tirer certains avantages. Vous n&rsquo;\u00eates qu&rsquo;un mouvement sans direction.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Le courage consiste \u00e0 \u00e9carter tout ce que l&rsquo;homme a v\u00e9cu et ressenti avant vous. Vous \u00eates le seul, plus grand que toutes ces choses. Tout est termin\u00e9, toute la tradition est termin\u00e9e, aussi sacr\u00e9e et sainte soit-elle \u2013 alors seulement vous pouvez \u00eatre vous-m\u00eame \u2013 c&rsquo;est \u00e7a l&rsquo;individualit\u00e9. Pour la premi\u00e8re fois, vous devenez un individu.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\"><b>En bref, le dire comme c&rsquo;est <\/b><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Un messie est celui qui laisse un d\u00e9sordre (<i>mess<\/i> en anglais) derri\u00e8re lui dans ce monde.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Les religions ont promis des roses, mais on finit par n&rsquo;avoir que des \u00e9pines.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Tout ce dont vous voulez \u00eatre libre pour quelque raison que ce soit est la chose m\u00eame qui peut vous lib\u00e9rer.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Dieu et le sexe vont ensemble. Si Dieu s&rsquo;en va, le sexe s&rsquo;en va aussi.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Quand on ne sait rien, on dit beaucoup de choses. Quand vous savez quelque chose, il n&rsquo;y a rien \u00e0 dire.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Toutes les exp\u00e9riences, aussi extraordinaires soient-elles, sont dans le domaine de la sensualit\u00e9.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">L&rsquo;homme ne peut \u00eatre autre chose que ce qu&rsquo;il est. Quoi qu&rsquo;il soit, il va cr\u00e9er une soci\u00e9t\u00e9 qui lui ressemble.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">L&rsquo;inspiration est une chose insignifiante. Les gens perdus et d\u00e9sesp\u00e9r\u00e9s cr\u00e9ent un march\u00e9 pour l&rsquo;inspiration. Toute action inspir\u00e9e finira par vous d\u00e9truire, vous et les v\u00f4tres.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">L&rsquo;amour et la haine ne sont pas des extr\u00e9mit\u00e9s oppos\u00e9es du m\u00eame spectre ; ils sont une seule et m\u00eame chose. Ils sont beaucoup plus proches que des jumeaux.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">En utilisant les mod\u00e8les de J\u00e9sus, de Bouddha ou de Krishna, nous avons d\u00e9truit la possibilit\u00e9 que la nature produise des individus uniques.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Tant que vous ferez quelque chose pour \u00eatre d\u00e9sint\u00e9ress\u00e9, vous serez un individu \u00e9gocentrique.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">La vie doit \u00eatre d\u00e9crite en termes physiques et physiologiques purs et simples. Elle doit \u00eatre d\u00e9mystifi\u00e9e et d\u00e9-psychologis\u00e9e.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">La soci\u00e9t\u00e9 est construite sur une base conflictuelle, et vous \u00eates la soci\u00e9t\u00e9. C&rsquo;est pourquoi vous devez toujours \u00eatre en conflit avec la soci\u00e9t\u00e9.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">L&rsquo;apog\u00e9e de l&rsquo;exp\u00e9rience sexuelle est la seule chose dans la vie que vous avez qui se rapproche d&rsquo;une exp\u00e9rience de premi\u00e8re main ; tout le reste de vos exp\u00e9riences est de seconde main, celle de quelqu&rsquo;un d&rsquo;autre.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Nourriture, v\u00eatements et logement \u2013 ce sont les besoins de base. Si vous voulez quelque chose au-del\u00e0 de \u00e7a, c&rsquo;est le d\u00e9but de l&rsquo;auto-illusion.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Le jour o\u00f9 l&rsquo;homme a fait l&rsquo;exp\u00e9rience de la conscience qui le faisait se sentir s\u00e9par\u00e9 et sup\u00e9rieur aux autres formes de vie, \u00e0 ce moment il a commenc\u00e9 \u00e0 semer les graines de sa propre destruction.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Vous ne mangez pas de la nourriture mais des id\u00e9es. Ce que vous portez n&rsquo;est pas des v\u00eatements, mais des \u00e9tiquettes et des noms.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Si vous ne savez pas ce qu&rsquo;est le bonheur, vous ne serez jamais malheureux.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Les pens\u00e9es viennent par vagues, c&rsquo;est partout, vous ne choisissez que les pens\u00e9es que vous voulez.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">La cause et l&rsquo;effet ne sont pas deux choses diff\u00e9rentes, ils ne font qu&rsquo;une. C&rsquo;est l&rsquo;esprit qui les s\u00e9pare.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Vous formulez les questions \u00e0 partir des r\u00e9ponses que vous avez d\u00e9j\u00e0.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Vous n&rsquo;\u00eates pas en paix avec vous-m\u00eame, alors comment pouvez-vous cr\u00e9er la paix dans le monde ?<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Il n&rsquo;y a aucune relation entre ce que vous pensez et la fa\u00e7on dont vous vivez et c&rsquo;est cela qui vous isole du mouvement de la vie et qui cause la douleur et la souffrance.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Vous n&rsquo;\u00e9coutez jamais personne, vous vous \u00e9coutez toujours. Vous traduisez tout en fonction de vos propres savoirs et exp\u00e9riences.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Tous les absolus moraux, toutes les abstractions morales vous falsifient.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">C&rsquo;est la recherche qui cr\u00e9e la perturbation, la division dans votre \u00e9tat de conscience. C&rsquo;est de la violence. Vos pens\u00e9es sacr\u00e9es sont les m\u00eames que celles d&rsquo;un dictateur fasciste.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Pour devenir quelqu&rsquo;un d&rsquo;autre, il faut du temps, pour \u00eatre soi-m\u00eame, il n&rsquo;y a pas besoin de temps.<\/span><\/span><\/p>\n<p class=\"western\" align=\"center\">~<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"font-size: medium;\">Jetez toutes les b\u00e9quilles, vous n&rsquo;avez pas besoin d&rsquo;aide, vous pouvez marcher tout seul.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>U.G. Krishnamurti (1918-2007) a v\u00e9cu une transformation totale en 1967. Selon un de ses biographes (Mukunda Rao) avec qui nous sommes en accord, son anti-enseignement est pass\u00e9 par trois phases : \u00ab Nous pouvons discerner approximativement trois phases dans la vie d&rsquo;U.G. et son anti-enseignement. La premi\u00e8re a dur\u00e9 de 1967 jusqu&rsquo;\u00e0 la fin des [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17752,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[60],"tags":[],"class_list":["post-18131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-u-g"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;Anti-Enseignement de U.G. Krishnamurti - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.revue3emillenaire.com\/blog\/lanti-enseignement-de-u-g-krishnamurti\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Anti-Enseignement de U.G. Krishnamurti - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\" \/>\n<meta property=\"og:description\" content=\"U.G. Krishnamurti (1918-2007) a v\u00e9cu une transformation totale en 1967. Selon un de ses biographes (Mukunda Rao) avec qui nous sommes en accord, son anti-enseignement est pass\u00e9 par trois phases : \u00ab Nous pouvons discerner approximativement trois phases dans la vie d&rsquo;U.G. et son anti-enseignement. La premi\u00e8re a dur\u00e9 de 1967 jusqu&rsquo;\u00e0 la fin des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.revue3emillenaire.com\/blog\/lanti-enseignement-de-u-g-krishnamurti\/\" \/>\n<meta property=\"og:site_name\" content=\"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-26T00:26:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.revue3emillenaire.com\/blog\/wp-content\/uploads\/2018\/05\/ug.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"291\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"3e mill\u00e9naire\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"3e mill\u00e9naire\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"25 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/lanti-enseignement-de-u-g-krishnamurti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/lanti-enseignement-de-u-g-krishnamurti\\\/\"},\"author\":{\"name\":\"3e mill\u00e9naire\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#\\\/schema\\\/person\\\/b692dacff720a5344a6190bc714397eb\"},\"headline\":\"L&rsquo;Anti-Enseignement de U.G. Krishnamurti\",\"datePublished\":\"2019-12-26T00:26:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/lanti-enseignement-de-u-g-krishnamurti\\\/\"},\"wordCount\":5079,\"image\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/lanti-enseignement-de-u-g-krishnamurti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/ug.jpg\",\"articleSection\":[\"U. G.\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/lanti-enseignement-de-u-g-krishnamurti\\\/\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/lanti-enseignement-de-u-g-krishnamurti\\\/\",\"name\":\"L'Anti-Enseignement de U.G. Krishnamurti - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/lanti-enseignement-de-u-g-krishnamurti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/lanti-enseignement-de-u-g-krishnamurti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/ug.jpg\",\"datePublished\":\"2019-12-26T00:26:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#\\\/schema\\\/person\\\/b692dacff720a5344a6190bc714397eb\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/lanti-enseignement-de-u-g-krishnamurti\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/lanti-enseignement-de-u-g-krishnamurti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/lanti-enseignement-de-u-g-krishnamurti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/ug.jpg\",\"contentUrl\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/ug.jpg\",\"width\":291,\"height\":259},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/lanti-enseignement-de-u-g-krishnamurti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;Anti-Enseignement de U.G. Krishnamurti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/\",\"name\":\"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\",\"description\":\"L&#039;Homme en devenir\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#\\\/schema\\\/person\\\/b692dacff720a5344a6190bc714397eb\",\"name\":\"3e mill\u00e9naire\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/author\\\/scoussa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Anti-Enseignement de U.G. Krishnamurti - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.revue3emillenaire.com\/blog\/lanti-enseignement-de-u-g-krishnamurti\/","og_locale":"fr_FR","og_type":"article","og_title":"L'Anti-Enseignement de U.G. Krishnamurti - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","og_description":"U.G. Krishnamurti (1918-2007) a v\u00e9cu une transformation totale en 1967. Selon un de ses biographes (Mukunda Rao) avec qui nous sommes en accord, son anti-enseignement est pass\u00e9 par trois phases : \u00ab Nous pouvons discerner approximativement trois phases dans la vie d&rsquo;U.G. et son anti-enseignement. La premi\u00e8re a dur\u00e9 de 1967 jusqu&rsquo;\u00e0 la fin des [&hellip;]","og_url":"https:\/\/www.revue3emillenaire.com\/blog\/lanti-enseignement-de-u-g-krishnamurti\/","og_site_name":"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","article_published_time":"2019-12-26T00:26:12+00:00","og_image":[{"width":291,"height":259,"url":"https:\/\/www.revue3emillenaire.com\/blog\/wp-content\/uploads\/2018\/05\/ug.jpg","type":"image\/jpeg"}],"author":"3e mill\u00e9naire","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"3e mill\u00e9naire","Dur\u00e9e de lecture estim\u00e9e":"25 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.revue3emillenaire.com\/blog\/lanti-enseignement-de-u-g-krishnamurti\/#article","isPartOf":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/lanti-enseignement-de-u-g-krishnamurti\/"},"author":{"name":"3e mill\u00e9naire","@id":"https:\/\/www.revue3emillenaire.com\/blog\/#\/schema\/person\/b692dacff720a5344a6190bc714397eb"},"headline":"L&rsquo;Anti-Enseignement de U.G. Krishnamurti","datePublished":"2019-12-26T00:26:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/lanti-enseignement-de-u-g-krishnamurti\/"},"wordCount":5079,"image":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/lanti-enseignement-de-u-g-krishnamurti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revue3emillenaire.com\/blog\/wp-content\/uploads\/2018\/05\/ug.jpg","articleSection":["U. G."],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.revue3emillenaire.com\/blog\/lanti-enseignement-de-u-g-krishnamurti\/","url":"https:\/\/www.revue3emillenaire.com\/blog\/lanti-enseignement-de-u-g-krishnamurti\/","name":"L'Anti-Enseignement de U.G. Krishnamurti - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","isPartOf":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/lanti-enseignement-de-u-g-krishnamurti\/#primaryimage"},"image":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/lanti-enseignement-de-u-g-krishnamurti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revue3emillenaire.com\/blog\/wp-content\/uploads\/2018\/05\/ug.jpg","datePublished":"2019-12-26T00:26:12+00:00","author":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/#\/schema\/person\/b692dacff720a5344a6190bc714397eb"},"breadcrumb":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/lanti-enseignement-de-u-g-krishnamurti\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.revue3emillenaire.com\/blog\/lanti-enseignement-de-u-g-krishnamurti\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.revue3emillenaire.com\/blog\/lanti-enseignement-de-u-g-krishnamurti\/#primaryimage","url":"https:\/\/www.revue3emillenaire.com\/blog\/wp-content\/uploads\/2018\/05\/ug.jpg","contentUrl":"https:\/\/www.revue3emillenaire.com\/blog\/wp-content\/uploads\/2018\/05\/ug.jpg","width":291,"height":259},{"@type":"BreadcrumbList","@id":"https:\/\/www.revue3emillenaire.com\/blog\/lanti-enseignement-de-u-g-krishnamurti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.revue3emillenaire.com\/blog\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;Anti-Enseignement de U.G. Krishnamurti"}]},{"@type":"WebSite","@id":"https:\/\/www.revue3emillenaire.com\/blog\/#website","url":"https:\/\/www.revue3emillenaire.com\/blog\/","name":"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","description":"L&#039;Homme en devenir","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.revue3emillenaire.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.revue3emillenaire.com\/blog\/#\/schema\/person\/b692dacff720a5344a6190bc714397eb","name":"3e mill\u00e9naire","url":"https:\/\/www.revue3emillenaire.com\/blog\/author\/scoussa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/posts\/18131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/comments?post=18131"}],"version-history":[{"count":0,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/posts\/18131\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/media\/17752"}],"wp:attachment":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/media?parent=18131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/categories?post=18131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/tags?post=18131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}