{"id":20576,"date":"2025-04-22T15:29:48","date_gmt":"2025-04-22T14:29:48","guid":{"rendered":"https:\/\/www.revue3emillenaire.com\/blog\/?p=20576"},"modified":"2025-04-22T15:29:48","modified_gmt":"2025-04-22T14:29:48","slug":"comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson","status":"publish","type":"post","link":"https:\/\/www.revue3emillenaire.com\/blog\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\/","title":{"rendered":"Comment \u00eatre ici maintenant ? Que devrais-je faire\u00a0? par Joan Tollifson"},"content":{"rendered":"<p class=\"western\" align=\"justify\"><strong><span style=\"font-size: medium;\"><i><b>R\u00e9ponse \u00e0 une question sur o\u00f9 porter son attention\u00a0:<\/b><\/i><\/span><\/strong><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">Je dirais, juste comme exp\u00e9rience, d\u2019oublier les \u00ab\u00a0devoirs\u00a0\u00bb et de rel\u00e2cher tous les efforts pour \u00ab\u00a0faire\u00a0\u00bb une quelconque tentative intentionnelle d\u2019\u00ab\u00a0\u00eatre ici maintenant\u00a0\u00bb. Laissez votre attention aller l\u00e0 o\u00f9 elle va naturellement. Approchez cela de fa\u00e7on ludique, de mani\u00e8re facile, d\u00e9tendue, ouverte, sans essayer d\u2019obtenir un r\u00e9sultat, sans essayer de vivre une exp\u00e9rience sp\u00e9ciale ou particuli\u00e8re, sans essayer de s\u2019accrocher \u00e0 quoi que ce soit ou de se d\u00e9barrasser de quoi que ce soit, en appr\u00e9ciant simplement le flux de l\u2019exp\u00e9rience exactement tel qu\u2019il est. Juste cela.<\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">Remarquez que, quelle que soit la mani\u00e8re dont cela se pr\u00e9sente momentan\u00e9ment (\u00e9tendu, contract\u00e9, agr\u00e9able, d\u00e9sagr\u00e9able, d\u00e9prim\u00e9, exalt\u00e9), c\u2019est toujours simplement cette exp\u00e9rience pr\u00e9sente, et peu importe combien cela change, cela ne quitte jamais l\u2019imm\u00e9diatet\u00e9 intemporelle de l\u2019instant pr\u00e9sent, ici m\u00eame, maintenant m\u00eame. O\u00f9 que vous alliez, et, quel que soit votre \u00e2ge, cela se manifeste toujours dans et comme cette pr\u00e9sence consciente immuable, cette exp\u00e9rience sans limites, fluide, sans centre, qui est toujours ici m\u00eame, maintenant m\u00eame.<\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">Observez que tout se produit de lui-m\u00eame. Vous n\u2019avez pas \u00e0 \u00ab\u00a0faire\u00a0\u00bb quoi que ce soit. En fait, qu\u2019est exactement ce \u00ab\u00a0vous\u00a0\u00bb qui semble parfois \u00eatre au centre de votre exp\u00e9rience, l\u2019auteur de vos pens\u00e9es, faisant vos choix et accomplissant vos actions\u00a0?<\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">Explorez cette sensation mentale d\u2019un \u00ab\u00a0vous\u00a0\u00bb et voyez de quoi elle est faite. Pouvez-vous r\u00e9ellement trouver ce \u00ab\u00a0vous\u00a0\u00bb\u00a0? Ou trouvez-vous simplement une pr\u00e9sence consciente et une exp\u00e9rience pr\u00e9sente\u00a0? Il peut y avoir une <\/span><em><span style=\"font-size: medium;\">id\u00e9e<\/span><\/em><span style=\"font-size: medium;\"> (par exemple, \u00ab\u00a0Je suis dans ma t\u00eate, regardant \u00e0 travers mes yeux\u00a0\u00bb). Il peut y avoir une <\/span><em><span style=\"font-size: medium;\">sensation<\/span><\/em><span style=\"font-size: medium;\">, peut-\u00eatre dans la poitrine, qui semble \u00eatre vous. Il peut y avoir une s\u00e9rie <\/span><em><span style=\"font-size: medium;\">de r\u00e9cits<\/span><\/em><span style=\"font-size: medium;\"> (je suis ce nom, ce corps, cette histoire, ce genre, cette nationalit\u00e9, cet \u00e2ge, ce m\u00e9tier). Il peut y avoir une <\/span><em><span style=\"font-size: medium;\">image mentale<\/span><\/em><span style=\"font-size: medium;\"> (votre apparence dans le miroir). Mais qu\u2019est-ce qui per\u00e7oit tout cela\u00a0? O\u00f9 cela appara\u00eet-il\u00a0? Quelle est la consistance de tout cela\u00a0? Cette pr\u00e9sence consciente que vous \u00eates fondamentalement a-t-elle un \u00e2ge, un genre, une nationalit\u00e9, une histoire de vie, une fronti\u00e8re ou un emplacement\u00a0? Est-elle enferm\u00e9e dans le corps, ou est-ce le corps qui appara\u00eet en elle\u00a0? N\u2019est-ce pas cette pr\u00e9sence-conscience qui est le facteur commun \u00e0 chaque exp\u00e9rience diff\u00e9rente\u00a0?<\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">Explorez \u00ab\u00a0le corps\u00a0\u00bb en fermant les yeux et en le <\/span><em><span style=\"font-size: medium;\">ressentant<\/span><\/em><span style=\"font-size: medium;\"> r\u00e9ellement. \u00c0 quel point est-il solide\u00a0? Y a-t-il une fronti\u00e8re d\u00e9finie entre l\u2019int\u00e9rieur et l\u2019ext\u00e9rieur\u00a0?<\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">Ne <\/span><em><span style=\"font-size: medium;\">r\u00e9fl\u00e9chissez<\/span><\/em><span style=\"font-size: medium;\"> pas \u00e0 tout cela et ne cherchez pas \u00e0 le comprendre rationnellement. Explorez-le plut\u00f4t de mani\u00e8re exp\u00e9rientielle avec une attention ouverte. Ressentez. Regardez, \u00e9coutez, sentez, soyez conscient. La pens\u00e9e est toujours dualiste et partielle, elle divise et chosifie. La pr\u00e9sence\/la conscience\/l\u2019exp\u00e9rience v\u00e9cue est non-duelle, infiniment vari\u00e9e, mais non divis\u00e9e et indivisible. Enti\u00e8re. Ne vous attardez pas sur les mots. Ce ne sont que des indications. Revenez toujours \u00e0 l\u2019exp\u00e9rience directe, au ressenti d\u2019\u00eatre ici maintenant, \u00e0 la r\u00e9alit\u00e9 d\u00e9pouill\u00e9e de l\u2019exp\u00e9rience pr\u00e9sente, telle qu\u2019elle est.<\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">\u00c0 mesure que vous portez une attention ouverte \u00e0 votre exp\u00e9rience actuelle, il peut devenir \u00e9vident que la r\u00e9alit\u00e9 n\u2019est pas ce que nous croyons. La pens\u00e9e est une sorte de processus d\u2019abstraction qui d\u00e9coupe mentalement la r\u00e9alit\u00e9 en parties distinctes, les \u00e9tiquetant et les cat\u00e9gorisant, faisant ainsi appara\u00eetre ces choses comme r\u00e9elles, ind\u00e9pendantes, s\u00e9par\u00e9es et limit\u00e9es. C\u2019est une illusion utile, une carte utile pour fonctionner au quotidien, mais la carte n\u2019est pas le territoire. La r\u00e9alit\u00e9 est bien plus fluide, \u00e9vanescente, insaisissable, vivante, non-substantielle et pourtant intens\u00e9ment pr\u00e9sente, insaisissable, semblable \u00e0 un r\u00eave, en perp\u00e9tuel changement et pourtant toujours ici-maintenant dans cette imm\u00e9diatet\u00e9 intemporelle.<\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">Le \u00ab\u00a0vous\u00a0\u00bb qui semble vivre cette exp\u00e9rience pr\u00e9sente et essayer de la contr\u00f4ler est une illusion, une cr\u00e9ation de fum\u00e9e et de miroirs, un mirage fait de pens\u00e9es, de sensations, d\u2019images mentales, d\u2019histoires, de souvenirs et d\u2019id\u00e9es \u00e9ph\u00e9m\u00e8res. Il n\u2019y a pas de penseur derri\u00e8re les pens\u00e9es, pas d\u2019observateur derri\u00e8re l\u2019observation. Explorez le processus de \u00ab\u00a0prise de d\u00e9cision\u00a0\u00bb apparente et voyez comment il se d\u00e9roule r\u00e9ellement. Il peut devenir \u00e9vident que tout se produit spontan\u00e9ment, y compris toutes vos envies, impulsions, d\u00e9sirs, peurs, int\u00e9r\u00eats, aversions, pr\u00e9f\u00e9rences, capacit\u00e9s, opinions, pens\u00e9es, choix et actions. \u00ab\u00a0Vous\u00a0\u00bb \u00eates ins\u00e9parable de l\u2019univers entier. C\u2019est un tout indivisible, un mouvement <\/span><span style=\"font-size: medium;\">fluide<\/span><span style=\"font-size: medium;\">.<\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">Alors, si cela vous int\u00e9resse, exp\u00e9rimentez simplement le fait d\u2019\u00eatre ici, sans effort, sans intention ni but, en appr\u00e9ciant le fait d\u2019\u00eatre vivant et en \u00e9tant curieux de <\/span><span style=\"font-size: medium;\">comment<\/span><span style=\"font-size: medium;\"> c\u2019est, comment la souffrance survient, comment les choix et les d\u00e9cisions <\/span><span style=\"font-size: medium;\">se produisent<\/span><span style=\"font-size: medium;\">. Vous pourriez vous retrouver \u00e0 \u00e9couter les bruits de la circulation ou \u00e0 ressentir la respiration, puis un chant d\u2019oiseau attire votre attention et vous l\u2019\u00e9coutez, puis vous voyez une belle formation nuageuse et votre attention se tourne vers cela, puis une pens\u00e9e surgit sur ce que vous devez faire demain, et peut-\u00eatre que d\u2019autres pens\u00e9es suivent, mais finalement cette c<\/span><span style=\"font-size: medium;\">ascad<\/span><span style=\"font-size: medium;\">e de pens\u00e9es se termine et vous entendez un avion qui passe au-dessus, et vous l\u2019\u00e9coutez, puis peut-\u00eatre <\/span><span style=\"font-size: medium;\">\u00e9merge <\/span><span style=\"font-size: medium;\">une <\/span><span style=\"font-size: medium;\">vaste <\/span><span style=\"font-size: medium;\">ouverture globale <\/span><span style=\"font-size: medium;\">qui <\/span><span style=\"font-size: medium;\">semble <\/span><span style=\"font-size: medium;\">tout <\/span><span style=\"font-size: medium;\">embrasser et contempler, <\/span><span style=\"font-size: medium;\">avant que<\/span><span style=\"font-size: medium;\"> l\u2019attention se concentre sur une sensation vive dans votre jambe.<\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">Tout cela se produit de lui-m\u00eame, <\/span><em><span style=\"font-size: medium;\">y compris<\/span><\/em><span style=\"font-size: medium;\"> les tentatives p\u00e9riodiques de le contr\u00f4ler, et <\/span><em><span style=\"font-size: medium;\">y compris<\/span><\/em><span style=\"font-size: medium;\"> les pens\u00e9es \u00e0 propos des pens\u00e9es (par exemple, \u00ab\u00a0Je ne devrais pas penser\u00a0\u00bb).<\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">Parfois, l\u2019attention est compl\u00e8tement absorb\u00e9e par une cha\u00eene de pens\u00e9es, une histoire, une imagination ou un film mental quelconque, puis \u00e0 un moment donn\u00e9, il y a un r\u00e9veil spontan\u00e9. \u00ab\u00a0Vous\u00a0\u00bb ne faites pas ce r\u00e9veil. Il se produit de lui-m\u00eame, tout comme <\/span><span style=\"font-size: medium;\">le flot<\/span><span style=\"font-size: medium;\"> de pens\u00e9es ou le film mental.<\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">Lorsque la conscience se r\u00e9veille spontan\u00e9ment d\u2019une cha\u00eene de pens\u00e9es dans laquelle elle \u00e9tait absorb\u00e9e, imm\u00e9diatement une nouvelle pens\u00e9e, se faisant passer pour \u00ab\u00a0vous\u00a0\u00bb, peut surgir et vous r\u00e9primander d\u2019avoir \u00e9t\u00e9 perdu dans vos pens\u00e9es. Cette pens\u00e9e secondaire pourrait vous ordonner d\u2019arr\u00eater de penser et de pr\u00eater attention de nouveau au monde sensoriel, mais il n\u2019y a pas de \u00ab\u00a0vous\u00a0\u00bb qui soit l\u2019auteur de cette pens\u00e9e non plus \u2014 elle surgit, elle aussi, spontan\u00e9ment. Peut-\u00eatre que votre attention revient effectivement au monde sensoriel, ou peut-\u00eatre que l\u2019histoire est si captivante que l\u2019attention y retourne encore un moment. Et si cela arrive, il y aura \u00e0 nouveau un r\u00e9veil spontan\u00e9 de cette cha\u00eene de pens\u00e9es. Peut-\u00eatre qu\u2019une autre pens\u00e9e surgit alors, vous jugeant d\u2019avoir encore \u00e9t\u00e9 perdu dans vos pens\u00e9es, vous disant peut-\u00eatre que vous \u00eates un rat\u00e9 en m\u00e9ditation.<\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">Il peut \u00eatre remarqu\u00e9 comment la pens\u00e9e cr\u00e9e l\u2019id\u00e9e d\u2019un \u00ab\u00a0vous\u00a0\u00bb qui est un \u00e9chec et d\u2019un autre \u00ab\u00a0vous\u00a0\u00bb qui juge, instruit et essaie d\u2019am\u00e9liorer le premier \u00ab\u00a0vous\u00a0\u00bb. C\u2019est comme s\u2019il y avait un mauvais vous et un bon vous. Est-il possible que <\/span><em><span style=\"font-size: medium;\">ces deux<\/span><\/em><span style=\"font-size: medium;\"> versions de \u00ab\u00a0vous\u00a0\u00bb ne soient rien de plus que des pens\u00e9es, des id\u00e9es, des images mentales, des imaginations\u00a0? V\u00e9rifiez-le. Regardez et voyez. Ressentez cela. Remarquez comment la pens\u00e9e se fait continuellement passer pour \u00ab\u00a0vous\u00a0\u00bb, le centre apparent de l\u2019exp\u00e9rience, le penseur-auteur-choi<\/span><span style=\"font-size: medium;\">sisseur<\/span><span style=\"font-size: medium;\">-d\u00e9cideur-observateur-exp\u00e9rimentateur apparent, puis comment elle vous juge, vous \u00e9value et vous instruit.<\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">Il se peut que vous d\u00e9couvriez qu\u2019aucun \u00ab\u00a0vous\u00a0\u00bb ne peut r\u00e9ellement \u00eatre trouv\u00e9. Il n\u2019y a pas de substance l\u00e0, pas de \u00ab\u00a0vous\u00a0\u00bb r\u00e9el s\u00e9par\u00e9 du flot d<\/span><span style=\"font-size: medium;\">e l<\/span><span style=\"font-size: medium;\">\u2019exp\u00e9rience. Il n\u2019y a pas de centre \u00e0 l\u2019exp\u00e9rience. Tout se produit de lui-m\u00eame. Le \u00ab\u00a0vous\u00a0\u00bb n\u2019est qu\u2019une pens\u00e9e, une sensation neurologique, une convention grammaticale, un personnage dans une histoire, un mirage qui appara\u00eet par intermittence, mais qui n\u2019est jamais ce qu\u2019il semble \u00eatre. Il surgit avant ou apr\u00e8s <\/span><span style=\"font-size: medium;\">l<\/span><span style=\"font-size: medium;\">es actions et en <\/span><span style=\"font-size: medium;\">s\u2019en attribue<\/span><span style=\"font-size: medium;\"> le m\u00e9rite ou le bl\u00e2me.<\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">Parce que nous vivons t<\/span><span style=\"font-size: medium;\">ellemen<\/span><span style=\"font-size: medium;\">t dans le monde de la pens\u00e9e et de la conceptualisation, absorbant tant d\u2019informations verbales et \u00e9crites, il peut \u00eatre tr\u00e8s lib\u00e9rateur de prendre consciemment le temps, chaque fois que cela vous invite, de d\u00e9placer l\u2019attention vers le domaine sensoriel \u00e0 la place. Ce n\u2019est pas que ressentir <\/span><span style=\"font-size: medium;\">est<\/span><span style=\"font-size: medium;\"> bon et penser <\/span><span style=\"font-size: medium;\">est <\/span><span style=\"font-size: medium;\">mauvais. Et bien s\u00fbr, la pens\u00e9e se produira encore, et lorsqu\u2019elle le fait, remarquez que ce n\u2019est qu\u2019une autre forme que prend momentan\u00e9ment l\u2019exp\u00e9rience. Ne la combattez pas. Ne vous perdez pas dans les pens\u00e9es \u00e0 propos des pens\u00e9es.<\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">Ressentez simplement la respiration, \u00e9coutez <\/span><span style=\"font-size: medium;\">le bruit de <\/span><span style=\"font-size: medium;\">la circulation ou <\/span><span style=\"font-size: medium;\">d<\/span><span style=\"font-size: medium;\">es oiseaux, go\u00fbtez le caf\u00e9 ou le th\u00e9, explorez toutes les sensations dans le corps. Si une douleur surgit, explorez les sensations r\u00e9elles. Si une d\u00e9pression, une anxi\u00e9t\u00e9, une agitation ou un ennui surgit, ressentez-le dans le corps, remarquez les histoires mentales, d\u00e9couvrez ce qui se passe d\u2019autre (les chants d\u2019oiseaux, les bruits de <\/span><span style=\"font-size: medium;\">la rue<\/span><span style=\"font-size: medium;\">, la respiration). Appr\u00e9ciez la merveille d\u2019\u00eatre simplement vivant, d\u2019\u00eatre ce moment sans fond, ici m\u00eame, maintenant m\u00eame, tel qu\u2019il est. \u00catre ce que vous ne pouvez pas ne pas \u00eatre. Juste cela.<\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">Vous ne pouvez pas vous tromper. En fait, il n\u2019y a vraiment pas de \u00ab\u00a0vous\u00a0\u00bb qui fait quoi que ce soit\u00a0! C\u2019est simplement comme c\u2019est.<\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">Jouez avec tout cela. Explorez-le. Soyez curieux. Peu importe ce que tous les soi-disant experts en ont dit. Laissez tomber toutes vos croyances et pr\u00e9jug\u00e9s, ne serait-ce qu\u2019un instant. Regardez par vous-m\u00eame. Regardez fra\u00eechement EN CE<\/span><span style=\"font-size: medium;\">T instant<\/span><span style=\"font-size: medium;\">, MAINTENANT. Soyez ouvert \u00e0 la surprise.<\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">Il n\u2019y a pas de r\u00e9ponse finale, pas de ligne d\u2019arriv\u00e9e. C\u2019est toujours JUSTE CELA. Ce moment sans fond. \u00c9ternel. Intemporel. Insondable. Insaisissable. In\u00e9vitable. Ici. Maintenant. Juste Cela\u00a0!<\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">Si vous demandez, \u00ab\u00a0Qu\u2019est-ce que c\u2019est\u00a0?\u00a0\u00bb (Est-ce la conscience, est-ce un r\u00eave, est-ce la r\u00e9alit\u00e9 mat\u00e9rielle, est-ce Un, est-ce multiple\u00a0?), vous \u00eates d\u00e9j\u00e0 parti dans le dualisme de la pens\u00e9e. Et oui, <\/span><em><span style=\"font-size: medium;\">cela aussi<\/span><\/em><span style=\"font-size: medium;\">, c\u2019est Cela. Ce sans-nom indivisible ne se s\u00e9pare jamais de lui-m\u00eame, peu importe comment il se manifeste momentan\u00e9ment. Mais peut-\u00eatre qu\u2019il n\u2019est pas n\u00e9cessaire de <\/span><span style=\"font-size: medium;\">s\u2019\u00e9gare<\/span><span style=\"font-size: medium;\">r dans une pens\u00e9e inutile, confuse, douloureuse. Peut-\u00eatre est-il possible, maintenant, de S\u2019ARR\u00caTER et simplement d\u2019\u00eatre. Juste Cela\u00a0!<\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\">Amour \u00e0 tous\u2026<\/span><\/p>\n<p class=\"western\" align=\"justify\"><a href=\"https:\/\/joantollifson.substack.com\/p\/how-to-be-here-now\"><span style=\"font-size: medium;\">Texte original publi\u00e9 le 20\u00a0avril 2025\u00a0: <\/span><\/a><span style=\"color: #000080;\"><u><a href=\"https:\/\/joantollifson.substack.com\/p\/how-to-be-here-now\" target=\"_blank\" rel=\"noopener\"><span style=\"font-size: medium;\">https:\/\/joantollifson.substack.com\/p\/how-to-be-here-now<\/span><\/a><\/u><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 mesure que vous portez une attention ouverte \u00e0 votre exp\u00e9rience actuelle, il peut devenir \u00e9vident que la r\u00e9alit\u00e9 n\u2019est pas ce que nous croyons. La pens\u00e9e est une sorte de processus d\u2019abstraction qui d\u00e9coupe mentalement la r\u00e9alit\u00e9 en parties distinctes, les \u00e9tiquetant et les cat\u00e9gorisant, faisant ainsi appara\u00eetre ces choses comme r\u00e9elles, ind\u00e9pendantes, s\u00e9par\u00e9es et limit\u00e9es. C\u2019est une illusion utile, une carte utile pour fonctionner au quotidien, mais la carte n\u2019est pas le territoire. La r\u00e9alit\u00e9 est bien plus fluide, \u00e9vanescente, insaisissable, vivante, non-substantielle et pourtant intens\u00e9ment pr\u00e9sente, insaisissable, semblable \u00e0 un r\u00eave, en perp\u00e9tuel changement et pourtant toujours ici-maintenant dans cette imm\u00e9diatet\u00e9 intemporelle.<\/p>\n","protected":false},"author":2,"featured_media":20534,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1558],"tags":[8,44,104,210,240],"class_list":["post-20576","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tollifson-joan","tag-non-dualite","tag-observation","tag-pensee","tag-pratique-interieure","tag-processus-du-moi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment \u00eatre ici maintenant ? Que devrais-je faire\u00a0? par Joan Tollifson - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.revue3emillenaire.com\/blog\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment \u00eatre ici maintenant ? Que devrais-je faire\u00a0? par Joan Tollifson - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\" \/>\n<meta property=\"og:description\" content=\"\u00c0 mesure que vous portez une attention ouverte \u00e0 votre exp\u00e9rience actuelle, il peut devenir \u00e9vident que la r\u00e9alit\u00e9 n\u2019est pas ce que nous croyons. La pens\u00e9e est une sorte de processus d\u2019abstraction qui d\u00e9coupe mentalement la r\u00e9alit\u00e9 en parties distinctes, les \u00e9tiquetant et les cat\u00e9gorisant, faisant ainsi appara\u00eetre ces choses comme r\u00e9elles, ind\u00e9pendantes, s\u00e9par\u00e9es et limit\u00e9es. C\u2019est une illusion utile, une carte utile pour fonctionner au quotidien, mais la carte n\u2019est pas le territoire. La r\u00e9alit\u00e9 est bien plus fluide, \u00e9vanescente, insaisissable, vivante, non-substantielle et pourtant intens\u00e9ment pr\u00e9sente, insaisissable, semblable \u00e0 un r\u00eave, en perp\u00e9tuel changement et pourtant toujours ici-maintenant dans cette imm\u00e9diatet\u00e9 intemporelle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.revue3emillenaire.com\/blog\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\/\" \/>\n<meta property=\"og:site_name\" content=\"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-22T14:29:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.revue3emillenaire.com\/blog\/wp-content\/uploads\/2025\/03\/Joan-Tollifson2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"305\" \/>\n\t<meta property=\"og:image:height\" content=\"369\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"3e mill\u00e9naire\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"3e mill\u00e9naire\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\\\/\"},\"author\":{\"name\":\"3e mill\u00e9naire\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#\\\/schema\\\/person\\\/b692dacff720a5344a6190bc714397eb\"},\"headline\":\"Comment \u00eatre ici maintenant ? Que devrais-je faire\u00a0? par Joan Tollifson\",\"datePublished\":\"2025-04-22T14:29:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\\\/\"},\"wordCount\":1949,\"image\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Joan-Tollifson2.jpg\",\"keywords\":[\"Non-dualit\u00e9\",\"Observation\",\"Pens\u00e9e\",\"pratique int\u00e9rieure\",\"processus du moi\"],\"articleSection\":[\"Tollifson Joan\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\\\/\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\\\/\",\"name\":\"Comment \u00eatre ici maintenant ? Que devrais-je faire\u00a0? par Joan Tollifson - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Joan-Tollifson2.jpg\",\"datePublished\":\"2025-04-22T14:29:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#\\\/schema\\\/person\\\/b692dacff720a5344a6190bc714397eb\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Joan-Tollifson2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Joan-Tollifson2.jpg\",\"width\":305,\"height\":369},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment \u00eatre ici maintenant ? Que devrais-je faire\u00a0? par Joan Tollifson\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/\",\"name\":\"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\",\"description\":\"L&#039;Homme en devenir\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#\\\/schema\\\/person\\\/b692dacff720a5344a6190bc714397eb\",\"name\":\"3e mill\u00e9naire\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/author\\\/scoussa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment \u00eatre ici maintenant ? Que devrais-je faire\u00a0? par Joan Tollifson - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.revue3emillenaire.com\/blog\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment \u00eatre ici maintenant ? Que devrais-je faire\u00a0? par Joan Tollifson - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","og_description":"\u00c0 mesure que vous portez une attention ouverte \u00e0 votre exp\u00e9rience actuelle, il peut devenir \u00e9vident que la r\u00e9alit\u00e9 n\u2019est pas ce que nous croyons. La pens\u00e9e est une sorte de processus d\u2019abstraction qui d\u00e9coupe mentalement la r\u00e9alit\u00e9 en parties distinctes, les \u00e9tiquetant et les cat\u00e9gorisant, faisant ainsi appara\u00eetre ces choses comme r\u00e9elles, ind\u00e9pendantes, s\u00e9par\u00e9es et limit\u00e9es. C\u2019est une illusion utile, une carte utile pour fonctionner au quotidien, mais la carte n\u2019est pas le territoire. La r\u00e9alit\u00e9 est bien plus fluide, \u00e9vanescente, insaisissable, vivante, non-substantielle et pourtant intens\u00e9ment pr\u00e9sente, insaisissable, semblable \u00e0 un r\u00eave, en perp\u00e9tuel changement et pourtant toujours ici-maintenant dans cette imm\u00e9diatet\u00e9 intemporelle.","og_url":"https:\/\/www.revue3emillenaire.com\/blog\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\/","og_site_name":"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","article_published_time":"2025-04-22T14:29:48+00:00","og_image":[{"width":305,"height":369,"url":"https:\/\/www.revue3emillenaire.com\/blog\/wp-content\/uploads\/2025\/03\/Joan-Tollifson2.jpg","type":"image\/jpeg"}],"author":"3e mill\u00e9naire","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"3e mill\u00e9naire","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.revue3emillenaire.com\/blog\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\/#article","isPartOf":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\/"},"author":{"name":"3e mill\u00e9naire","@id":"https:\/\/www.revue3emillenaire.com\/blog\/#\/schema\/person\/b692dacff720a5344a6190bc714397eb"},"headline":"Comment \u00eatre ici maintenant ? Que devrais-je faire\u00a0? par Joan Tollifson","datePublished":"2025-04-22T14:29:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\/"},"wordCount":1949,"image":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revue3emillenaire.com\/blog\/wp-content\/uploads\/2025\/03\/Joan-Tollifson2.jpg","keywords":["Non-dualit\u00e9","Observation","Pens\u00e9e","pratique int\u00e9rieure","processus du moi"],"articleSection":["Tollifson Joan"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.revue3emillenaire.com\/blog\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\/","url":"https:\/\/www.revue3emillenaire.com\/blog\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\/","name":"Comment \u00eatre ici maintenant ? Que devrais-je faire\u00a0? par Joan Tollifson - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","isPartOf":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\/#primaryimage"},"image":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revue3emillenaire.com\/blog\/wp-content\/uploads\/2025\/03\/Joan-Tollifson2.jpg","datePublished":"2025-04-22T14:29:48+00:00","author":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/#\/schema\/person\/b692dacff720a5344a6190bc714397eb"},"breadcrumb":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.revue3emillenaire.com\/blog\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.revue3emillenaire.com\/blog\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\/#primaryimage","url":"https:\/\/www.revue3emillenaire.com\/blog\/wp-content\/uploads\/2025\/03\/Joan-Tollifson2.jpg","contentUrl":"https:\/\/www.revue3emillenaire.com\/blog\/wp-content\/uploads\/2025\/03\/Joan-Tollifson2.jpg","width":305,"height":369},{"@type":"BreadcrumbList","@id":"https:\/\/www.revue3emillenaire.com\/blog\/comment-etre-ici-maintenant-que-devrais-je-faire-par-joan-tollifson\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.revue3emillenaire.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Comment \u00eatre ici maintenant ? Que devrais-je faire\u00a0? par Joan Tollifson"}]},{"@type":"WebSite","@id":"https:\/\/www.revue3emillenaire.com\/blog\/#website","url":"https:\/\/www.revue3emillenaire.com\/blog\/","name":"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","description":"L&#039;Homme en devenir","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.revue3emillenaire.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.revue3emillenaire.com\/blog\/#\/schema\/person\/b692dacff720a5344a6190bc714397eb","name":"3e mill\u00e9naire","url":"https:\/\/www.revue3emillenaire.com\/blog\/author\/scoussa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/posts\/20576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/comments?post=20576"}],"version-history":[{"count":0,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/posts\/20576\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/media\/20534"}],"wp:attachment":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/media?parent=20576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/categories?post=20576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/tags?post=20576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}