{"id":20894,"date":"2025-10-15T22:03:57","date_gmt":"2025-10-15T21:03:57","guid":{"rendered":"https:\/\/www.revue3emillenaire.com\/blog\/?p=20894"},"modified":"2025-10-16T18:30:19","modified_gmt":"2025-10-16T17:30:19","slug":"temps-mythe-et-matiere-entretien-avec-ld-deutsch","status":"publish","type":"post","link":"https:\/\/www.revue3emillenaire.com\/blog\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\/","title":{"rendered":"Temps, mythe et mati\u00e8re. Entretien avec LD Deutsch"},"content":{"rendered":"<p class=\"western\" align=\"justify\"><em><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><i><b>L\u2019auteure L.D. Deutsch, bas\u00e9e \u00e0 Los Angeles<\/b><\/i><\/span><\/span><\/span><\/em><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>,<\/b><\/span><\/span><\/span><em><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><i><b> parle de son dernier ouvrage<\/b><\/i><\/span><\/span><\/span><\/em><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>, Time, Myth and Matter: Essays on the Natures and Narratives of Reality (Temps, mythe et mati\u00e8re\u00a0: essais sur la nature et les r\u00e9cits de la r\u00e9alit\u00e9), <\/b><\/span><\/span><\/span><em><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><i><b>dans lequel elle tisse le mythe et la science en un r\u00e9cit coh\u00e9rent et examine l\u2019imbrication de la dimension int\u00e9rieure ou psychique avec le monde ext\u00e9rieur de la physique. <\/b><\/i><\/span><\/span><\/span><\/em><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Nick : <\/b><\/span><\/span><\/span><\/strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Bienvenue au podcast du <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><i>magazine Beshara<\/i><\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">, dont l\u2019objectif est <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">d\u2019offrir une tribune \u00e0 des penseurs d\u2019avant-garde<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> qui abordent le monde contemporain dans une perspective d\u2019unit\u00e9. Sur notre site web, vous trouverez pr\u00e8s de 200\u00a0articles r\u00e9dig\u00e9s par des scientifiques, des \u00e9conomistes, des artistes, des \u00e9cologistes et des adeptes de traditions spirituelles qui se concentrent sur l\u2019unit\u00e9 et l\u2019int\u00e9gration plut\u00f4t que sur la fragmentation et la discorde. Je m\u2019appelle Nikos Yiangou, je suis r\u00e9dacteur en chef du podcast du magazine, je vous parle depuis la Californie, et je suis accompagn\u00e9 de notre r\u00e9dactrice en chef, Jane Clark, qui est bas\u00e9e \u00e0 Oxford, au Royaume-Uni. Bonjour, Jane.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Jane\u00a0:<\/b><\/span><\/span><\/span><\/strong> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Bonjour, Nick.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Nick : <\/b><\/span><\/span><\/span><\/strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Aujourd\u2019hui, nous accueillons Laura Deutsch comme invit\u00e9e. Elle est \u00e9crivaine, bas\u00e9e \u00e0 Los Angeles, et titulaire d\u2019une ma\u00eetrise en \u00e9tudes religieuses. Son travail porte sur le temps, la conscience, la technologie, la mythologie et la chute du paradigme mat\u00e9rialiste. Le premier livre de Laura, <\/span><\/span><\/span><em><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><i>Time, Myth and Matter: Essays on the Natures and Narratives of Reality<\/i><\/span><\/span><\/span><\/em><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">, a \u00e9t\u00e9 publi\u00e9 par Sacred Bones Books en mai 2025. Comme l\u2019a \u00e9crit Eric Davis dans sa critique, je cite\u00a0:<\/span><\/span><\/span><\/p>\n<p class=\"western\" style=\"padding-left: 80px;\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><i>Deutsch peut discuter de physique avec clart\u00e9, respect et rigueur. Mais \u00e0 l\u2019instar de la premi\u00e8re vague de th\u00e9oriciens quantiques, elle se permet \u00e9galement de s\u2019aventurer profond\u00e9ment dans la philosophie et le mythe. Et lorsqu\u2019elle se confronte \u00e0 des concepts \u00e9tranges, tels que les dieux, les oracles et les id\u00e9es de Jung sur la synchronicit\u00e9, elle ne sombre pas dans les myst\u00e8res arch\u00e9typaux habituels<\/i>.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Apr\u00e8s cette citation \u00e9logieuse, Laura, passons \u00e0 notre conversation d\u2019aujourd\u2019hui. Donnez-nous une id\u00e9e g\u00e9n\u00e9rale de votre travail, qui tisse le mythe et la science dans un r\u00e9cit coh\u00e9rent et qui montre l\u2019imbrication de la dimension int\u00e9rieure ou psychique avec le monde ext\u00e9rieur de la physique. Pouvez-vous nous dire ce qui vous a conduite dans cette voie ?<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Laura\u00a0:<\/b><\/span><\/span><\/span><\/strong> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Oui, bien s\u00fbr. Vous savez, je pense que, depuis mon enfance, <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">je me suis toujours int\u00e9ress\u00e9e<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> aux grandes questions sur la r\u00e9alit\u00e9 et la conscience. Et d\u2019une mani\u00e8re telle que je n\u2019ai jamais vraiment eu l\u2019impression de pouvoir ignorer cet appel. J\u2019ai eu la chance de pouvoir explorer ces questions sous diff\u00e9rents angles\u00a0: scientifique, philosophique, mythologique, \u00e0 travers la psychologie analytique de Carl Jung. Et au cours de ce parcours, on commence \u00e0 voir appara\u00eetre certains sch\u00e9mas ou structures entre ces diff\u00e9rents domaines qui sont corr\u00e9latifs et, dans certains cas, isomorphes. Et je pense, <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">\u00e0 partir de l\u00e0<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">, l\u2019intuition commence \u00e0 <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">s\u2019allum<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">er et on se demande, d\u2019accord\u00a0:<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> Y a-t-il une sorte d\u2019ordre organisationnel plus profond sous-jacent ? S\u2019agit-il d\u2019occasions de donner du sens ? Ces occasions se recoupent-elles ? En quoi la question que je pose dans une direction est-elle identique ou diff\u00e9rente de celle que vous posez dans une autre ? Et comment pouvons-nous aborder toutes ces intersections de mani\u00e8re rationnelle ?<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Jane\u00a0:<\/b><\/span><\/span><\/span><\/strong> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Merci. Votre livre s\u2019intitule <\/span><\/span><\/span><em><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><i>Time, Myth and Matter (Le temps, le mythe et <\/i><\/span><\/span><\/span><\/em><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><i>la mati\u00e8re<\/i><\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">). Mais nous avons pens\u00e9 commencer par le mythe. Vous soulignez que, pendant la majeure partie de l\u2019histoire humaine, dans presque toutes les cultures, le mythe a \u00e9t\u00e9 le principal moyen utilis\u00e9 par les gens pour donner un sens au monde. Par exemple, \u00e0 travers les mythes de la cr\u00e9ation qu\u2019ils soient autochtones ou grecs, ou ceux contenus dans des textes comme la Bible ou les Upanishads. Les penseurs des Lumi\u00e8res ont en quelque sorte suppos\u00e9 que, \u00e0 mesure que la science ou la rationalit\u00e9 deviendraient culturellement dominantes, ces mythes seraient remplac\u00e9s. Et d\u2019une certaine mani\u00e8re, c\u2019est ce qui s\u2019est produit. Tr\u00e8s peu de gens croient aujourd\u2019hui que le monde a \u00e9t\u00e9 cr\u00e9\u00e9 en sept jours, comme le dit la Gen\u00e8se. Mais l\u2019activit\u00e9 de cr\u00e9ation de mythes, dites-vous, n\u2019a pas disparu. En fait, si je peux vous citer, vous dites\u00a0:<\/span><\/span><\/span><\/p>\n<p class=\"western\" style=\"padding-left: 80px;\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><i>Alors que notre esp\u00e8ce pense et agit de plus en plus \u00e0 travers des syst\u00e8mes technoscientifiques, on assiste \u00e0 une r\u00e9surgence massive du mystique dans l\u2019espace m\u00eame o\u00f9 on le croyait d\u00e9truit.<\/i><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">J\u2019ai donc deux questions\u00a0: premi\u00e8rement, quelle est l\u2019importance du mythe et pourquoi pensez-vous que nous, \u00eatres humains, semblons incapables de nous en passer ? Et deuxi\u00e8mement, qu\u2019entendez-vous par \u00ab l\u2019espace o\u00f9 on le croyait d\u00e9truit \u00bb ?<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Laura\u00a0:<\/b><\/span><\/span><\/span><\/strong> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Tout \u00e0 fait. C\u2019est une question tr\u00e8s riche qui, je pense, peut \u00eatre abord\u00e9e sous plusieurs angles. Tout d\u2019abord, je dirais que, dans le livre lui-m\u00eame et dans mon travail en g\u00e9n\u00e9ral, j\u2019utilise beaucoup les th\u00e9ories de Carl Jung, certaines de ses th\u00e9ories plus mythologiques, bien s\u00fbr, et certaines de ses th\u00e9ories scientifiques, que l\u2019on pourrait consid\u00e9rer comme plus rigoureuses. Mais il \u00e9crivait que l\u2019homme a toujours v\u00e9cu avec un mythe. Et cette p\u00e9riode qui suivit le si\u00e8cle des Lumi\u00e8res est en r\u00e9alit\u00e9 tr\u00e8s courte pour l\u2019humanit\u00e9. Penser que l\u2019homme moderne peut vivre sans mythe est une maladie, comme le dirait Jung. Mais, comme l\u2019homme ne na\u00eet pas tous les jours, il na\u00eet dans un contexte historique avec un cadre historique sp\u00e9cifique, il faut avoir une relation avec ces choses, et cette relation ne peut pas \u00eatre enti\u00e8rement rationnelle. Et c\u2019est int\u00e9ressant, car cela rejoint en quelque sorte la deuxi\u00e8me question. Mais, vous savez, je pense que les scientifiques, \u00e0 mon avis, s\u2019ils sont dignes de ce nom, admettront qu\u2019au c\u0153ur de la science, il y a un myst\u00e8re. Vous savez, la m\u00e9thode scientifique est fantastique pour explorer une partie tr\u00e8s localis\u00e9e de l\u2019univers, mais nous ne connaissons pas l\u2019origine sp\u00e9cifique de l\u2019univers ni comment la vie est apparue ni comment la conscience est apparue.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Ce sont l\u00e0 des myst\u00e8res profonds et vastes, et la pens\u00e9e scientifique, qui repose sur la viabilit\u00e9 exp\u00e9rimentale, n\u2019est pas en mesure de r\u00e9pondre \u00e0 ces questions. Je pense donc que la dimension mythique s\u2019ouvre en quelque sorte autour de ces questions, \u00e0 la limite de ce qui peut \u00eatre connu. Jung dirait \u00e9galement que, sans une certaine compr\u00e9hension de nos origines universelles, une compr\u00e9hension profonde, nous nous retrouvons avec un d\u00e9racinement qui peut \u00eatre tr\u00e8s pr\u00e9judiciable \u00e0 notre sant\u00e9 psychologique. Je pense donc que la mythologie, en particulier celle li\u00e9e \u00e0 la cr\u00e9ation, a toujours fait partie de la vie de l\u2019homme. Et je ne pense pas que, dans l\u2019histoire de l\u2019humanit\u00e9, notre \u00e9poque moderne fasse exception \u00e0 cela. Cependant, nous avons assist\u00e9 \u00e0 une sorte d\u2019effondrement syst\u00e9mique, sinon des structures religieuses organis\u00e9es, du moins un grand repositionnement de l\u2019importance culturelle de ces syst\u00e8mes et de la religion organis\u00e9e. Et, vous savez, c\u2019\u00e9tait le domaine o\u00f9 la production de mythes prosp\u00e9rait, en particulier les mythologies de la cr\u00e9ation. Si nous nous tournons vers la technologie, en particulier les technologies de l\u2019information, nous pouvons certainement la d\u00e9finir comme quelque chose qui rapproche le monde, qui met \u00e0 notre disposition une quantit\u00e9 \u00e9norme d\u2019informations.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Je suis dans le Massachusetts, vous \u00eates en Californie, vous \u00eates au Royaume-Uni. Vous savez, c\u2019est un principe de connexion. Donc, d\u2019une certaine mani\u00e8re, je pense que cela peut expliquer la migration de ces structures mythologiques d\u2019un espace \u00e0 l\u2019autre. Je pense qu\u2019il y a quelque chose qui passe un peu inaper\u00e7u, \u00e0 savoir que la science et la religion ont le m\u00eame objectif, qui est de comprendre la r\u00e9alit\u00e9 et la place de l\u2019humanit\u00e9 dans celle-ci, mais des deux c\u00f4t\u00e9s, il y a des personnes, des syst\u00e8mes et des histoires qui tentent de les s\u00e9parer compl\u00e8tement l\u2019un de l\u2019autre. Mais le probl\u00e8me, quand on ne les met pas en dialogue, c\u2019est que les penseurs ont tendance \u00e0 s\u2019aventurer aveugl\u00e9ment dans le territoire qu\u2019ils s\u2019efforcent tant de cloisonner, et c\u2019est l\u00e0 qu\u2019on trouve des structures vraiment int\u00e9ressantes, comme l\u2019hypoth\u00e8se de la simulation, dont je parle dans mon livre et que je pr\u00e9sente comme une mythologie s\u00e9culaire de la cr\u00e9ation, ou dans de nombreux objectifs et buts du mouvement transhumaniste. On retrouve des structures religieuses tr\u00e8s reconnaissables sous le couvert d\u2019une pens\u00e9e purement technoscientifique. Donc, oui, c\u2019est une conversation \u00e9trange qui se d\u00e9roule entre deux syst\u00e8mes que les gens essaient de maintenir tr\u00e8s \u00e9loign\u00e9s l\u2019un de l\u2019autre.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Nick : <\/b><\/span><\/span><\/span><\/strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Oui. Pourriez-vous nous en dire un peu plus sur cette activit\u00e9 de cr\u00e9ation de mythes, en termes de fonctionnement des \u00e9nergies arch\u00e9typales de l\u2019inconscient collectif comme une sorte de r\u00e9ponse naturelle \u00e0 cette qu\u00eate de sens ? Je veux dire, il semble que cela ne soit pas s\u00e9par\u00e9 de ce que nous sommes. Et les symboles et les images qui \u00e9mergent de cette activit\u00e9, l\u2019arch\u00e9type, vous savez, la cr\u00e9ation de mythes, sont spontan\u00e9s et constituent quelque chose dont nous devons \u00eatre conscients plut\u00f4t que de remettre en question leur validit\u00e9.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Laura\u00a0:<\/b><\/span><\/span><\/span><\/strong> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Oui. Vous savez, la th\u00e9orie des arch\u00e9types de Jung est si riche et kal\u00e9idoscopique qu\u2019elle inclut des \u00e9l\u00e9ments qui pourraient \u00eatre consid\u00e9r\u00e9s comme des symboles math\u00e9matiques, jusqu\u2019aux id\u00e9es du vieil homme sage, de la Vierge et du monstre, ces entit\u00e9s anthropomorphiques ou vivantes, mais ce qui fonde toutes ces fa\u00e7ons de voir ou d\u2019appliquer cette th\u00e9orie, c\u2019est que les arch\u00e9types sont consid\u00e9r\u00e9s comme des principes organisationnels a priori de la psych\u00e9. Comme vous l\u2019avez dit, ils ont leur propre nature active. Ils se constellent dans l\u2019inconscient collectif et apparaissent dans la conscience via l\u2019image arch\u00e9typale. Mais nous n\u2019avons pas acc\u00e8s \u00e0 eux tels qu\u2019ils sont en eux-m\u00eames, car ils existent dans l\u2019inconscient, ce qui signifie que, dans notre vie consciente, dans notre vie inconsciente personnelle et dans notre vie subconsciente, nous n\u2019avons pas acc\u00e8s au niveau arch\u00e9typal de l\u2019inconscient collectif.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">En termes de cr\u00e9ation de mythes, si nous prenons l\u2019exemple sp\u00e9cifique du mythe de la cr\u00e9ation, Marie-Louise von\u00a0Franz, qui \u00e9tait une disciple de Jung, psychanalyste et proche collaboratrice de celui-ci, souligne en quelque sorte que, chaque fois que nous nous heurtons \u00e0 l\u2019inconnu, une formation arch\u00e9typale vient combler les lacunes. Elle \u00e9voquait \u00e0 ce propos les anciennes cartes marines. Si vous regardez ces anciennes cartes, vous verrez que toutes les masses terrestres connues \u00e9taient repr\u00e9sent\u00e9es au centre. Et puis, tout autour, dans les mers, ou l\u00e0 o\u00f9 se trouvaient des masses terrestres ou des aspects de l\u2019oc\u00e9an que nous ne connaissions pas et qui n\u2019avaient pas \u00e9t\u00e9 cartographi\u00e9s, il y avait des images de sir\u00e8nes ou de monstres ou d\u2019autres entit\u00e9s arch\u00e9typales qui repr\u00e9sentaient vraiment l\u2019inconnu. Ainsi, lorsque nous nous approchons des limites de ce qui peut \u00eatre connu, nous voyons une activit\u00e9 spontan\u00e9e des arch\u00e9types, qui \u00e9mergent alors dans notre conscience \u00e0 travers les images arch\u00e9typales.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Si nous prenons le mythe de la cr\u00e9ation dans son ensemble, comme nous en discutions tout \u00e0 l\u2019heure, nous ne pouvons pas conna\u00eetre l\u2019origine de l\u2019univers. Nous ne pouvons pas conna\u00eetre l\u2019origine de la vie. Et c\u2019est pr\u00e9cis\u00e9ment lorsque nous abordons ces questions que se forment ces structures arch\u00e9typales, qui ob\u00e9issent \u00e0 des sch\u00e9mas reconnaissables dans les grands mythes de la cr\u00e9ation\u00a0: ceux des Upanishads, de la Bible, des cultures indig\u00e8nes. Et vous pouvez \u00e9galement le voir dans quelque chose comme l\u2019hypoth\u00e8se de la simulation, qui, comme vous le savez, soutient que nous vivons dans une r\u00e9alit\u00e9 programm\u00e9e par ordinateur. Mais si vous commencez \u00e0 examiner cette affirmation et les philosophies qui la soutiennent, ainsi que les r\u00e9cits qui l\u2019expliquent, vous commencez \u00e0 voir les m\u00eames sch\u00e9mas arch\u00e9typaux des mythes de la cr\u00e9ation.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Et je pense que croire que nous ne sommes pas influenc\u00e9s par d\u2019autres forces organisationnelles, plus vastes, agissant au sein de l\u2019inconscient collectif, c\u2019est peut-\u00eatre \u00eatre, d\u2019une certaine mani\u00e8re, encore plus aveugl\u00e9ment contr\u00f4l\u00e9s par elles. Les partisans de l\u2019hypoth\u00e8se de la simulation, par exemple, soutiendraient sans doute la validit\u00e9 de ce mod\u00e8le comme une structure possible de la r\u00e9alit\u00e9, sans forc\u00e9ment admettre que d\u2019autres forces organisationnelles pourraient \u00e9galement \u00eatre \u00e0 l\u2019\u0153uvre.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Nick : <\/b><\/span><\/span><\/span><\/strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Donc, l\u2019hypoth\u00e8se de la simulation informatique est r\u00e9elle, dans la mesure o\u00f9 elle <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">met en \u00e9vidence<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> certaines structures qui correspondent, par exemple, \u00e0 l\u2019id\u00e9e v\u00e9dique de Maya ou \u00e0 l\u2019id\u00e9e platonicienne selon laquelle nous ne sommes que des ombres d\u2019un \u00eatre pur. Mais ce que vous dites, c\u2019est que ce n\u2019est pas que la simulation informatique pourrait \u00eatre r\u00e9elle, que nous sommes r\u00e9ellement dans une simulation informatique, mais que, si vous examinez la question, ces structures peuvent \u00eatre d\u00e9compos\u00e9es en th\u00e8mes tr\u00e8s communs.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Laura\u00a0:<\/b><\/span><\/span><\/span><\/strong> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Oui, tout \u00e0 fait. Et je pense qu\u2019il y a aussi d\u2019autres \u00e9l\u00e9ments qui, selon moi, viennent \u00e9tayer cette perspective sur quelque chose comme l\u2019hypoth\u00e8se de la simulation. Si l\u2019on regarde l\u2019histoire de l\u2019Occident, nous avons toujours utilis\u00e9 les technologies les plus avanc\u00e9es pour d\u00e9crire le cerveau et l\u2019univers. Au XIV<\/span><\/span><\/span><span style=\"color: #000000;\"><sup><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">e<\/span><\/span><\/sup><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">\u00a0si\u00e8cle, l\u2019univers \u00e9tait d\u00e9crit comme une grande horlogerie. Si l\u2019on se penche sur le mod\u00e8le psychique de Freud, on constate qu\u2019il est fortement influenc\u00e9 par la machine \u00e0 vapeur. C\u2019est un mod\u00e8le hydraulique. On appuie sur quelque chose, et autre chose remonte. Les axones du cerveau ont \u00e9t\u00e9 mod\u00e9lis\u00e9s d\u2019apr\u00e8s les fils t\u00e9l\u00e9phoniques. Les fils t\u00e9l\u00e9phoniques sont apparus en premier et les neuroscientifiques se sont demand\u00e9 s<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">i cela pouvait fonctionner de la m\u00eame mani\u00e8re<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">. Et c\u2019est ainsi que cela fonctionnait. Dans les ann\u00e9es\u00a01980, David Bohm et Karl Pribram ont propos\u00e9 le mod\u00e8le holographique. Et aujourd\u2019hui, bien s\u00fbr, nous vivons dans un ordinateur et le cerveau est un ordinateur. Il y a donc un aspect herm\u00e9neutique dans notre fa\u00e7on de concevoir la r\u00e9alit\u00e9.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Je voudrais \u00e9galement mentionner ce merveilleux penseur, Jeff Kripal. Jeffrey Kripal est professeur d\u2019\u00e9tudes religieuses \u00e0 Rice, et il parle de cette herm\u00e9neutique en boucle qui consiste \u00e0 lire le pass\u00e9 \u00e0 travers le pr\u00e9sent, ou le pr\u00e9sent \u00e0 travers le pass\u00e9, ou encore le futur \u00e0 travers le pr\u00e9sent. C\u2019est le genre de lecture que nous faisons, que nous avons tendance \u00e0 consid\u00e9rer comme la v\u00e9rit\u00e9, mais qui est influenc\u00e9e culturellement et historiquement d\u2019une mani\u00e8re que nous ne reconnaissons pas toujours n\u00e9cessairement. On peut le voir, par exemple, \u00e0 l\u2019\u00e9poque moderne, lorsque les gens interpr\u00e8tent les tremblements de terre ou les \u00e9ruptions volcaniques, comme la r\u00e9alisation d\u2019une proph\u00e9tie biblique, ou encore lorsqu\u2019on regarde d\u2019anciennes peintures, d\u2019anciennes peintures religieuses, et qu\u2019on dirait qu\u2019il y a un ovni dans un coin et que les gens disent\u00a0: \u00ab Oh, c\u2019est un ovni \u00bb. Vous voyez, cela reviendrait \u00e0 lire le pr\u00e9sent \u00e0 travers le pass\u00e9 ou le pass\u00e9 \u00e0 travers le pr\u00e9sent ou le futur, quelle que soit votre opinion sur les ovnis.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Je pense donc que quelque chose comme l\u2019hypoth\u00e8se de la simulation, qui, vous savez, est pr\u00e9sent\u00e9e par beaucoup comme la solution \u00e0 des myst\u00e8res religieux et scientifiques anciens, rel\u00e8ve de ce type d\u2019interpr\u00e9tation, et je pense que beaucoup de ceux qui la proposent comme une structure viable de la r\u00e9alit\u00e9, vous savez, n\u2019ont pas vraiment pris en compte cet aspect herm\u00e9neutique des choses.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Jane\u00a0:<\/b><\/span><\/span><\/span><\/strong> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Donc, si l\u2019on pense \u00e0 la th\u00e9orie des arch\u00e9types de Jung, telle que je la comprends, ou du moins telle que la formule Bernardo Kastrup, il affirmerait que ces structures arch\u00e9typales ne fa\u00e7onnent pas seulement la psych\u00e9, mais aussi le monde. Et cela parce qu\u2019il n\u2019y a pas vraiment de s\u00e9paration essentielle entre l\u2019esprit et le monde, comme le postule la philosophie cart\u00e9sienne, ce qui nous am\u00e8ne \u00e0 un ph\u00e9nom\u00e8ne tel que, par exemple, la synchronicit\u00e9. Aimeriez-vous dire quelque chose \u00e0 propos de cette question de synchronicit\u00e9\u00a0?<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Laura\u00a0:<\/b><\/span><\/span><\/span><\/strong> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Bien s\u00fbr. Pour situer le contexte, \u00e0 partir de l\u2019analyse de Kastrup sur la m\u00e9taphysique de Jung, comme vous l\u2019avez mentionn\u00e9, en r\u00e9fl\u00e9chissant \u00e0 la relation entre la conscience et la mati\u00e8re, la conscience dans le monde, nous avons h\u00e9rit\u00e9 en Occident d\u2019un paradigme mat\u00e9rialiste cart\u00e9sien qui comporte un aspect dualiste. <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Comment la conscience \u00e9merge-t-elle de la mati\u00e8re ? Elle<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">s se pr\u00e9sentent comme deux choses distinctes. Cela signifie-t-il qu\u2019il s\u2019agit de deux choses s\u00e9par\u00e9es ?<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Jung avait une fa\u00e7on de parler de la psych\u00e9 et de la mati\u00e8re et de leur relation. Pour lui, la psych\u00e9 se d\u00e9compose en trois composantes principales. Il y a la psych\u00e9 personnelle, l\u2019inconscient personnel, puis l\u2019inconscient collectif. Et comme il abordait la psych\u00e9 dans son ensemble, il utilisait l\u2019analogie du spectre \u00e9lectromagn\u00e9tique et disait que, dans la partie m\u00e9diane du spectre \u2014 correspondant \u00e0 la lumi\u00e8re visible par l\u2019\u0153il humain \u2014 on trouverait la conscience personnelle. Si l\u2019on se d\u00e9pla\u00e7ait vers l\u2019infrarouge, la conscience commencerait \u00e0 se m\u00ealer \u00e0 la physiologie et finirait par se fondre dans la mati\u00e8re. Et si l\u2019on passait \u00e0 l\u2019ultraviolet, on voit la conscience, en quelque sorte la conscience personnelle, passer \u00e0 l\u2019inconscient collectif et aux arch\u00e9types, puis d\u00e9passer le domaine arch\u00e9typal pour entrer dans le domaine de l\u2019esprit, qu\u2019il d\u00e9finit comme l\u2019aspect dynamique de la conscience, ce qui fait que les pens\u00e9es se meuvent, que nous n\u2019avons pas une pens\u00e9e fig\u00e9e.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Mais ce qui est important dans cette analogie, c\u2019est que tout cela constitue une seule et m\u00eame substance, ce qui signifie qu\u2019il n\u2019y a en r\u00e9alit\u00e9 aucune s\u00e9paration entre la mati\u00e8re et la conscience. Personnellement, je vois cela comme une sorte de structure toro\u00efdale o\u00f9 la conscience, en partie, cr\u00e9e et impr\u00e8gne la r\u00e9alit\u00e9 et n\u2019est \u00e0 aucun moment s\u00e9par\u00e9e de la mati\u00e8re, m\u00eame si elle peut en donner l\u2019impression, car la mati\u00e8re et la conscience existent peut-\u00eatre dans des proportions diff\u00e9rentes l\u2019une par rapport \u00e0 l\u2019autre, \u00e0 travers ce qu\u2019on pourrait appeler une substance unitaire de la r\u00e9alit\u00e9. <\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Kastrup fait un travail remarquable dans un livre intitul\u00e9 <i>Decoding Jung\u2019s Metaphysics<\/i> (<i>D\u00e9coder la m\u00e9taphysique de Jung<\/i>) en expliquant comment Jung consid\u00e9rait l\u2019inconscient collectif et la nature comme une seule et m\u00eame chose, que l\u2019inconscient collectif, via le p\u00f4le ultraviolet, via ce que nous pourrions qualifier plus classiquement comme un aspect de la conscience, empi\u00e8te sur la conscience personnelle \u00e0 travers notre monde int\u00e9rieur, mais que l\u2019inconscient collectif, en tant que nature elle-m\u00eame, empi\u00e8te sur nous \u00e0 travers la nature et le monde ext\u00e9rieur. Maintenant, si les arch\u00e9types organisent l\u2019inconscient collectif, nous verrons cela \u00e0 la fois dans les structures psychiques et dans les structures de la nature.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Peut-\u00eatre encore une derni\u00e8re correspondance avant de revenir \u00e0 la synchronicit\u00e9, l\u2019un de mes exemples pr\u00e9f\u00e9r\u00e9s \u00e0 ce sujet vient de l\u2019Universit\u00e9 d\u2019Ottawa et de l\u2019Universit\u00e9 Sapienza de Rome en 2023. Ils ont photographi\u00e9, gr\u00e2ce \u00e0 une technique d\u2019imagerie holographique, des photons quantiques intriqu\u00e9s. Et si vous allez voir cette photo, c\u2019est un yin-yang. Il est impossible de nier ce que vous voyez, c\u2019est bien un yin-yang. Vous avez donc cette structure arch\u00e9typale incroyablement sp\u00e9cifique qu\u2019on retrouve dans le tao\u00efsme, elle a plusieurs significations, mais, vous savez, la lumi\u00e8re et l\u2019obscurit\u00e9, le cr\u00e9atif et le r\u00e9ceptif interagissant l\u2019un avec l\u2019autre, cr\u00e9ant le Tao, cr\u00e9ant le flux de la vie elle-m\u00eame, apparaissant dans une structure physique. On pourrait donc dire que la m\u00eame organisation arch\u00e9typale, la m\u00eame structure, cr\u00e9ent \u00e0 la fois les deux.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Revenons maintenant \u00e0 la synchronicit\u00e9. La synchronicit\u00e9 peut-\u00eatre d\u00e9finie comme un moment o\u00f9 des \u00e9v\u00e9nements ext\u00e9rieurs co\u00efncident avec des \u00e9v\u00e9nements int\u00e9rieurs dans la psych\u00e9 d\u2019une personne, produisant un sens profond, une signification immense \u2014 et cette corr\u00e9lation n\u2019est pas causale. La causalit\u00e9 ne pourrait pas l\u2019expliquer. Mais comme le souligne Kastrup, si les m\u00eames arch\u00e9types organisent le monde ext\u00e9rieur et le monde int\u00e9rieur, alors peut-\u00eatre que, dans un moment de synchronicit\u00e9, ces deux arch\u00e9types s\u2019activent simultan\u00e9ment, perceptibles \u00e0 la fois dans le monde ext\u00e9rieur et dans le monde int\u00e9rieur, et c\u2019est ce point de convergence qui constitue la synchronicit\u00e9.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Nick : <\/b><\/span><\/span><\/span><\/strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Vous avez donc abord\u00e9 la th\u00e9orie <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">jungienne de la conscience<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">, cette id\u00e9e du spectre \u00e9lectromagn\u00e9tique de la lumi\u00e8re<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">, o\u00f9<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> la partie visible <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">correspond \u00e0<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> ce dont nous sommes conscients<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">, tandis que l\u2019ultraviolet et l\u2019infrarouge tendent respectivement vers l\u2019esprit et vers la mati\u00e8re, englobant ainsi toute la r\u00e9alit\u00e9. Dans quelle mesure diriez-vous que vous avez d\u00e9velopp\u00e9 la th\u00e9orie originale de Jung ? Et existe-t-il d\u2019autres th\u00e9ories de la conscience \u2014 issues de la philosophie, de la science ou de la pens\u00e9e contemporaine \u2014 qui pourraient \u00e9clairer cette id\u00e9e ?<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Laura\u00a0:<\/span><\/span><\/span> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Eh bien, je ne dirais pas que je l\u2019ai d\u00e9velopp\u00e9e, mais plut\u00f4t que je l\u2019ai approfondie et appliqu\u00e9e au monde, en explorant les corr\u00e9lations et les structures isomorphes entre la pens\u00e9e mythoreligieuse et la pens\u00e9e scientifique. Von\u00a0Franz, en d\u00e9veloppant l\u2019analogie du spectre lumineux de Jung, sugg\u00e8re que ce n\u2019est pas une ligne droite, mais un cercle \u2014 o\u00f9 mati\u00e8re et esprit se rejoignent. Et elle nous invite \u00e0 imaginer ce cercle comme une sph\u00e8re. On peut alors concevoir cette relation comme un continuum o\u00f9 mati\u00e8re et conscience existent dans des proportions variables, \u00e0 travers les diff\u00e9rents plans de ce que nous appelons la r\u00e9alit\u00e9.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Cela rejoint, d\u2019une certaine mani\u00e8re, le panpsychisme \u2014 selon lequel toute mati\u00e8re poss\u00e9derait une part de conscience \u2014, mais il y a des diff\u00e9rences notables. Le panpsychisme, souvent, en cherchant \u00e0 comprendre comment un \u00ab\u00a0noyau\u00a0\u00bb de conscience existe dans toute mati\u00e8re, suppose que les syst\u00e8mes mat\u00e9riels doivent atteindre un certain seuil de complexit\u00e9 pour manifester la conscience. Cela reste un paradigme mat\u00e9rialiste, que je rejette en partie.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Je trouve que Kastrup, encore une fois, propose une magnifique alternative \u00e0 ce paradigme mat\u00e9rialiste avec ce qu\u2019il appelle l\u2019id\u00e9alisme analytique. Il dirait que, d\u2019une certaine mani\u00e8re, cela correspond incroyablement bien \u00e0 l\u2019analogie du spectre de Jung. Mais Kastrup soutient qu\u2019\u00e0 partir du XVII<sup>e<\/sup>\u00a0si\u00e8cle, la science, telle que nous la comprenons aujourd\u2019hui en Occident, commen\u00e7a comme une recherche qualitative. Toutes les informations recueillies par les premiers scientifiques et encore par les scientifiques, aujourd\u2019hui, sont recueillies de mani\u00e8re qualitative par les sens, m\u00eame si nous utilisons des instruments qui am\u00e9liorent les sens, comme les microscopes ou les t\u00e9lescopes. Nous avons commenc\u00e9 \u00e0 concevoir la science comme une description du monde qualitatif dans lequel nous vivons. Mais \u00e0 un certain moment de cette entreprise naissante, nous avons commenc\u00e9 \u00e0 utiliser la quantit\u00e9 comme moyen de d\u00e9crire la qualit\u00e9, en particulier les diff\u00e9rences entre les qualit\u00e9s. Ainsi, des \u00e9l\u00e9ments, tels que l\u2019angle, la longueur, la masse, ont tr\u00e8s bien permis de d\u00e9crire les diff\u00e9rences entre le monde qualitatif dans lequel nous vivons.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Mais, selon Kastrup, nous avons fini par attribuer la substantialit\u00e9 uniquement \u00e0 la quantit\u00e9, en la retirant de la qualit\u00e9, m\u00eame si la qualit\u00e9 est le substrat de tout ce qui est quantitatif. Cela nous conduit \u00e0 une impasse concernant la conscience, car nous commen\u00e7ons \u00e0 nous demander comment la qualit\u00e9 peut \u00e9merger de la quantit\u00e9, en oubliant que nous avons invent\u00e9 la quantit\u00e9 \u00e0 partir de la qualit\u00e9. Il compare donc cela \u00e0 un peintre qui attendrait que son autoportrait prenne vie.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Il parle ensuite de ce qu\u2019on appelle le probl\u00e8me difficile de la conscience, un terme invent\u00e9 par un philosophe nomm\u00e9 Dave Chalmers dans les ann\u00e9es\u00a090, qui se demande \u00e0 partir d\u2019un paradigme cart\u00e9sien dualiste\u00a0: comment la conscience \u00e9merge-t-elle des structures physiques du cerveau ? C\u2019est le probl\u00e8me difficile qui n\u2019a jamais \u00e9t\u00e9 r\u00e9solu, mais Kastrup l\u2019examine et dit qu\u2019il ne peut pas \u00eatre r\u00e9solu. Il faut le contourner. Il dit que c\u2019est quelque chose qui serait comique si ce n\u2019\u00e9tait pas si tragique, \u00e0 savoir que nous sommes coinc\u00e9s dans cette orni\u00e8re, oubliant que nous avons invent\u00e9 la quantit\u00e9 pour parler de la qualit\u00e9. Je pense donc que vous pouvez prendre ce genre d\u2019id\u00e9es et r\u00e9fl\u00e9chir au mat\u00e9rialisme en g\u00e9n\u00e9ral.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Kastrup qualifie le mat\u00e9rialisme qui nous anime de mat\u00e9rialisme m\u00e9taphysique, car la science telle que nous la connaissons d\u00e9crit le comportement des choses, mais nous ne pouvons jamais conna\u00eetre la mati\u00e8re en dehors du contenu psychique, en dehors d\u2019une exp\u00e9rience qualitative. C\u2019est \u00e9galement ce que dirait Jung. Ainsi, affirmer que la mati\u00e8re est le fondement de la r\u00e9alit\u00e9 n\u2019est pas quelque chose que nous pouvons r\u00e9ellement savoir, car la conscience est le fondement de notre r\u00e9alit\u00e9. C\u2019est donc d\u2019une d\u00e9duction. Une inf\u00e9rence m\u00e9taphysique. <\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Je crois sinc\u00e8rement que la conscience est la prima materia de la r\u00e9alit\u00e9. Je pense que, si vous \u00e9tudiez la mati\u00e8re, vous finissez par comprendre que le fond n\u2019a pas de fond, et vous vous retrouvez dans une impasse qui ne peut \u00eatre r\u00e9solue. Ce qui est int\u00e9ressant, cependant, surtout en ce moment et je dirais m\u00eame depuis dix ans, c\u2019est que l\u2019on assiste \u00e0 l\u2019\u00e9mergence de philosophies scientifiques non mat\u00e9rialistes, notamment en rapport avec les th\u00e9ories de la conscience et de la physique quantique, qui sont d\u00e9sormais prises tr\u00e8s au s\u00e9rieux.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Si l\u2019on examine la physique quantique, on trouve par exemple l\u2019interpr\u00e9tation transactionnelle, qui postule qu\u2019il existe des domaines r\u00e9els en dehors de la dimension spatio-temporelle dans lesquels se d\u00e9roulent les processus quantiques. Puis, par le biais d\u2019une interaction sp\u00e9cifique, le monde mat\u00e9riel mat\u00e9rialise l\u2019espace-temps dans les coordonn\u00e9es spatio-temporelles.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Et bien que nous n\u2019ayons pas acc\u00e8s \u00e0 ces domaines en dehors de l\u2019espace-temps, ils sont r\u00e9els, m\u00eame s\u2019ils ne sont pas concrets. C\u2019est ce qui les distingue. Et puis, si vous regardez les principales th\u00e9ories de la science de la conscience, l\u2019une de mes pr\u00e9f\u00e9r\u00e9es, dont je ne parle pas n\u00e9cessairement dans le livre, mais que je suis depuis longtemps, s\u2019appelle la th\u00e9orie r\u00e9ductionniste objective orchestr\u00e9e de la conscience. Elle est un peu compliqu\u00e9e, mais c\u2019est en quelque sorte un hybride entre le mat\u00e9rialisme et l\u2019id\u00e9alisme, car elle postule qu\u2019il existe un emplacement de la conscience dans le cerveau, dans les microtubules, ces sortes de structures prot\u00e9iques creuses qui ont un r\u00f4le dans la sant\u00e9 cellulaire, mais que les processus qui s\u2019y d\u00e9roulent impliquent des processus quantiques non computationnels, donc qui ont lieu dans une dimension qui n\u2019est pas dans l\u2019espace-temps \u00e0 proprement parler. Il est donc int\u00e9ressant de constater que, d\u00e8s que l\u2019on d\u00e9passe les limites du mat\u00e9rialisme, on se rapproche un peu plus de la v\u00e9rit\u00e9, je pense, et de possibilit\u00e9s tr\u00e8s int\u00e9ressantes. Mais je pense qu\u2019une partie de la lib\u00e9ration des cha\u00eenes du mat\u00e9rialisme consiste \u00e0 r\u00e9imaginer ce que nous pouvons savoir et comment nous pouvons le savoir.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Jane\u00a0<\/b><\/span><\/span><\/span><\/strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>:<\/b><\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> Pouvons-nous revenir un peu au mythe, car nous allons manquer de temps. J\u2019aimerais vous poser quelques questions. Nous n\u2019avons pas beaucoup parl\u00e9 de vos th\u00e9ories sur le temps, mais, dans votre expos\u00e9, vous \u00e9voquez la tension entre les mod\u00e8les scientifiques actuels du temps, o\u00f9 le pass\u00e9, le pr\u00e9sent et l<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">e futur<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> sont comme des points pr\u00e9d\u00e9termin\u00e9s dans le continuum espace-temps, et la fa\u00e7on dont nous percevons r\u00e9ellement le temps, qui se d\u00e9roule instant apr\u00e8s instant et dans lequel l<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">e futur<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> est ind\u00e9termin\u00e9 de notre point de vue. Ce qui m\u2019a int\u00e9ress\u00e9e, c\u2019est <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">la<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> fa\u00e7on dont vous parlez du mythe, en faisant appel \u00e0 des figures mythiques telles que Chronos, Kairos et Aion pour montrer comment le fait d\u2019\u00e9tablir une corr\u00e9lation avec ces figures mythiques peut nous aider \u00e0 r\u00e9soudre ce genre de paradoxe.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Laura\u00a0:<\/b><\/span><\/span><\/span><\/strong> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Oui. <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">J<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">e pense que le temps est l\u2019une des pierres angulaires de mon processus intellectuel et de mon d\u00e9veloppement, car, si vous tirez sur le fil du temps, vous arrivez \u00e0 la conscience, et si vous tirez sur le fil de la conscience, vous arrivez au temps. La conscience peut-elle exister si elle n\u2019<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">est pas <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">\u00e9tend<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">ue<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> dans le temps ? Notre compr\u00e9hension et notre exp\u00e9rience du temps en tant que propri\u00e9t\u00e9 consciente sont si diff\u00e9rentes des mod\u00e8les physiques du temps selon lesquels nous fonctionnons, <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">et pour lesquels nous avons pourtant de nombreuses preuves exp\u00e9rimentales sugg\u00e9rant leur validit\u00e9<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">. Si l\u2019on examine les th\u00e9ories de la relativit\u00e9 d\u2019Einstein, en particulier la relativit\u00e9 restreinte, qui stipule que le mouvement dans l\u2019espace affecte le passage du temps, cette th\u00e9orie sugg\u00e8re, ou plut\u00f4t doit sugg\u00e9rer que le pass\u00e9, le pr\u00e9sent et le futur existent tous <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">simultan\u00e9ment, ici et maintenant<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">, et que la notion de \u00ab maintenant \u00bb <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">est tr\u00e8s semblable \u00e0 celle<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> d\u2019\u00ab ici \u00bb. M\u00eame si je suis dans le Massachusetts, que vous \u00eates au Royaume-Uni et que vous \u00eates en Californie, ce sont trois endroits diff\u00e9rents, vous pouvez comparer cela \u00e0 l\u2019id\u00e9e que j\u2019existe maintenant dans le temps, mais qu\u2019il existe des endroits r\u00e9els dans l\u2019univers-bloc o\u00f9 existent des versions pass\u00e9es et futures de moi-m\u00eame. Ce qui est <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">fascinant<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">, c\u2019est qu\u2019il y a de nombreuses raisons de croire que la relativit\u00e9 restreinte est une th\u00e9orie vraie.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Nous l\u2019utilisons. Elle fonctionne. Par exemple, le GPS de votre voiture, l\u2019horloge de votre t\u00e9l\u00e9phone ne fonctionneraient pas si les ph\u00e9nom\u00e8nes relativistes sp\u00e9ciaux n\u2019\u00e9taient pas pris en compte dans les satellites correspondants. Nous avons donc toutes ces v\u00e9rifications, et pourtant oui, cela va compl\u00e8tement \u00e0 l\u2019encontre de l\u2019un des aspects les plus universels de la vie, \u00e0 savoir l\u2019\u00e9coulement ressenti du temps. Ce qui est si int\u00e9ressant dans l\u2019\u00e9tude de la mythologie du temps, c\u2019est que toutes les cultures qui ont une conception lin\u00e9aire du temps ont une mythologie du temps. Toutes sans exception. Si nous restons dans le canon grec et r\u00e9fl\u00e9chissons aux diff\u00e9rentes propri\u00e9t\u00e9s du temps, Chronos, dont nous tirons le mot chronologique, repr\u00e9sente le temps lin\u00e9aire. Plus tard, il est associ\u00e9 \u00e0 Saturne et \u00e0 la mortalit\u00e9, et \u00e0 tout ce que le temps peut en quelque sorte nous enlever. Et si l\u2019on pense \u00e0 Saturne d\u00e9vorant ses enfants, c\u2019est une analogie facile \u00e0 transposer sur la fa\u00e7on dont le temps lin\u00e9aire nous emm\u00e8ne de notre naissance \u00e0 notre mort.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Kairos est ensuite un aspect tr\u00e8s int\u00e9ressant du temps. Le temps tyrannique, vous savez, c\u2019est comme les synchronicit\u00e9s. Ce sont des moments. C\u2019est un aspect du temps qui a une grande signification, qui comporte un \u00e9l\u00e9ment de conscience en lui, car il poss\u00e8de cette grande signification et qu\u2019il faut saisir. Il ne peut \u00eatre conserv\u00e9, on ne peut pas s\u2019y fier. Il s\u2019agit de la conscience individuelle qui interagit avec le monde dans son ensemble ou la conscience dans son ensemble et qui cr\u00e9e des moments et du sens. Et il est repr\u00e9sent\u00e9 comme un dieu ail\u00e9, saisissant une balance. Et vous devez la saisir. Vous devez saisir le bon moment, le bon \u00e9quilibre.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Et puis Aion est, vous savez, une sorte de figure plus vaste, plus englobante, qui poss\u00e8de tout le temps dans ses propri\u00e9t\u00e9s et toute l\u2019intemporalit\u00e9, et qui engloberait \u00e0 la fois Chronos et Kairos, et en quelque sorte, vous savez, l\u2019aspect du temps et de l\u2019intemporalit\u00e9 qui s\u2019\u00e9tend presque jusqu\u2019\u00e0 l\u2019infini. Et je pense que, lorsque nous regardons ces espaces o\u00f9 nos exp\u00e9riences personnelles de la r\u00e9alit\u00e9 ne correspondent pas \u00e0 ce que dit la science, en particulier la science physique, nous pouvons nous tourner vers le mythe pour reconna\u00eetre que, d\u2019une certaine mani\u00e8re, les humains se sont confront\u00e9s \u00e0 cette id\u00e9e en dehors du paradigme scientifique depuis des mill\u00e9naires. Et ce qui est \u00e9tonnant, c\u2019est que l\u2019exp\u00e9rience humaine, je pense, est en quelque sorte continue \u00e0 cet \u00e9gard. Vous savez, la synchronicit\u00e9 ou quelque chose o\u00f9 une grande rencontre int\u00e9rieure co\u00efncide avec un \u00e9v\u00e9nement ext\u00e9rieur, poss\u00e8de un aspect d\u2019intemporalit\u00e9. Le temps s\u2019arr\u00eate. Et ce sont l\u00e0 des exp\u00e9riences r\u00e9elles. La r\u00e9alit\u00e9 dans la vie est d\u2019abord exp\u00e9rientielle. Je pense donc qu\u2019il existe des mani\u00e8res de trouver dans ces mythologies des v\u00e9rit\u00e9s plus profondes que celles auxquelles nous avons acc\u00e8s lorsque nous sommes confront\u00e9s \u00e0 ces incoh\u00e9rences entre nos th\u00e9ories scientifiques et la fa\u00e7on dont nous vivons notre vie.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Nick : <\/b><\/span><\/span><\/span><\/strong><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Excellent<\/span><\/span><\/span><\/strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">. Au fil de cette conversation, je pense que vous avez abord\u00e9 un certain nombre de sujets, qui recoupent divers th\u00e8mes que nous voulions explorer. Il y a une citation qui a \u00e9t\u00e9 pos\u00e9e par de nombreuses personnes \u00e0 travers les \u00e2ges\u00a0: \u00ab Ne trouverons-nous <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">donc <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">jamais ce que nous cherchons ? Car ce que nous cherchons est en r\u00e9alit\u00e9 ce qui cherche \u00bb.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">C\u2019est une question vraiment int\u00e9ressante, qui se pose peut-\u00eatre dans le contexte de votre <span style=\"color: #2f2f28;\">r\u00e9flexion<\/span> sur les qualia, ou l\u2019exp\u00e9rience commune du temps<span style=\"color: #2f2f28;\">, souvent consid\u00e9r\u00e9e comme une illusion li\u00e9e au<\/span> fonctionnement du cerveau. Et des neuroscientifiques comme Buonomano peuvent \u00e9galement souligner que la th\u00e9orie scientifique ne peut na\u00eetre que gr\u00e2ce au fonctionnement du cerveau. Cette question est donc int\u00e9ressante, et vous l\u2019avez en quelque sorte abord\u00e9e, mais je me demande si vous avez autre chose \u00e0 dire sur la fa\u00e7on dont la th\u00e9orie scientifique na\u00eet <span style=\"color: #2f2f28;\">pr\u00e9cis\u00e9ment de<\/span> notre structure particuli\u00e8re.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Laura\u00a0:<\/b><\/span><\/span><\/span><\/strong> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Oui. Nous avons un peu parl\u00e9 de l\u2019interp\u00e9n\u00e9tration de la conscience et de la mati\u00e8re. Mais je pense que c\u2019est un sujet connexe int\u00e9ressant, comme le souligne Buonomano, et <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">dont<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> j<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">e parle<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> dans <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">le<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> livre <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">\u00e0 propos du<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> temps. <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">N<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">os mod\u00e8les physiques du temps sont <\/span><\/span><\/span><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">ce que l\u2019on appellerait \u00ab \u00e9ternalistes \u00bb<\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">, c\u2019est-\u00e0-dire que le pass\u00e9, le futur et le pr\u00e9sent coexistent tous dans un univers en bloc \u00e0 l\u2019instant pr\u00e9sent. Mais cela va tellement \u00e0 l\u2019encontre de notre exp\u00e9rience v\u00e9cue du temps, que l\u2019on appellerait le pr\u00e9sentisme, <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">c\u2019est-\u00e0-dire<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> cette succession du pr\u00e9sent, cette succession des instants pr\u00e9sents. Et comment en sommes-nous arriv\u00e9s l\u00e0 ? Comment en sommes-nous arriv\u00e9s \u00e0 consid\u00e9rer le passage du temps comme une illusion afin d\u2019accepter nos mod\u00e8les physiques et le fait qu\u2019ils fonctionnent, entre autres choses ?<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Dans un livre merveilleux intitul\u00e9 <i>Your Brain Is a Time Machine <\/i>(tr fr<i> Le temps des neurones<\/i>), Dean Buonomano souligne que la physique a de tr\u00e8s bonnes raisons de fonctionner selon un paradigme \u00e9ternaliste, mais que les neurosciences fonctionnent selon un paradigme pr\u00e9sentiste. Le cerveau se tourne vers le pass\u00e9 pour faire des pr\u00e9dictions afin de survivre dans le futur, il aborde donc la question d\u2019un point de vue \u00e9volutionniste. Comment en sommes-nous arriv\u00e9s \u00e0 ces mod\u00e8les physiques qui vont \u00e0 l\u2019encontre de notre exp\u00e9rience de la vie ? Il sugg\u00e8re que, d\u2019un point de vue \u00e9volutionnaire, le cerveau emprunte et recycle constamment ses propres fonctions.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">C\u2019est une entit\u00e9 tr\u00e8s \u00e9conome et adaptative. Et si l\u2019on remonte dans le temps, il y avait probablement plus de pression \u00e9volutive pour comprendre l\u2019espace que pour comprendre le temps. Cela signifie qu\u2019il \u00e9tait probablement plus essentiel pour la survie de comprendre <span style=\"color: #2f2f28;\"><span style=\"font-family: PT Serif, Georgia, Times New Roman, serif;\">l\u2019arri\u00e8re, l\u2019avant<\/span><\/span>, le haut et le bas que de comprendre \u00ab mardi prochain \u00bb.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Ainsi, <span style=\"color: #2f2f28;\"><span style=\"font-family: PT Serif, Georgia, Times New Roman, serif;\">Buonomano<\/span><\/span> et d\u2019autres neuroscientifiques sugg\u00e8rent que le cerveau aurait peut-\u00eatre d\u00e9velopp\u00e9 notre compr\u00e9hension du temps \u00e0 partir des corr\u00e9lats neuronaux d\u00e9j\u00e0 en place pour comprendre l\u2019espace. Et si tel \u00e9tait le cas, alors la spatialisation du temps prendrait une toute nouvelle dimension. Nous le voyons avec nos mod\u00e8les physiques du temps. Mais nous le voyons aussi tr\u00e8s clairement dans le langage. Nous utilisons un langage spatial pour parler du temps\u00a0: \u00ab\u00a0La r\u00e9union a \u00e9t\u00e9 avanc\u00e9e. L\u2019heure a \u00e9t\u00e9 longue. Cela est pass\u00e9 tr\u00e8s vite\u00a0\u00bb. Ce sont des mots physiques, un langage physique.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\"><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\">Donc, pour en revenir \u00e0 ce que nous recherchons, <\/span><\/span>c\u2019est la chose qui fait la recherche\u00a0: chaque fois <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\">que <\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\">nous posons une question ou <\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\">que nous y <\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\">r\u00e9pondons, nous sommes limit\u00e9s par l\u2019organe qui pose ou r\u00e9pond \u00e0 ces questions. Et donc, si le cerveau lui-m\u00eame en venait \u00e0 comprendre le temps, ou si je peux aller aussi loin, \u00e0 cocr\u00e9er un aspect du temps, gr\u00e2ce \u00e0 sa compr\u00e9hension de l\u2019espace, alors nous ne pourrions en fait jamais comprendre un monde ext\u00e9rieur objectif, car il n\u2019y a pas d\u2019ext\u00e9rieur au monde.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Jane\u00a0:<\/b><\/span><\/span><\/span><\/strong> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">C\u2019est une r\u00e9ponse merveilleuse. Merci. Pour conclure, l\u2019une des choses qui m\u2019ont vraiment frapp\u00e9e dans <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">l<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">e livre, c\u2019est aussi la fa\u00e7on dont vous parlez d<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">u<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> mythe, <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">de <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">ces structures mythologiques <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">qui<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> entrent en jeu pour nous aux limites <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">du savoir<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">, l\u00e0 o\u00f9 nous ne savons vraiment rien et o\u00f9 nous nous aventurons dans l\u2019inconnu. Mais vous en parlez \u00e9galement en termes de choses qui nous font peur. Ainsi, les structures mythologiques, les choses mythologiques sont \u00e9galement l\u00e0 pour nous aider \u00e0 faire face \u00e0 l\u2019inconnu et aux choses qui nous effraient.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-size: medium;\"><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\">Dans le premier chapitre du livre, vous parlez de la d\u00e9couverte de la plan\u00e8te Pluton dans les ann\u00e9es\u00a01930 et de la cr\u00e9ation du nouvel \u00e9l\u00e9ment qui a \u00e9t\u00e9 appel\u00e9 plutonium, \u00e9l\u00e9ment essentiel \u00e0 la <\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\">produc<\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\">tion d\u2019armes nucl\u00e9aires. Vous d\u00e9crivez comment l\u2019arriv\u00e9e de la bombe atomique a g\u00e9n\u00e9r\u00e9 une peur \u00e9norme dans les ann\u00e9es\u00a01930 quant \u00e0 l\u2019an\u00e9antissement potentiel de toute l\u2019humanit\u00e9. Vous dites que vous pensez qu\u2019il existe aujourd\u2019hui de nombreux parall\u00e8les avec les pr\u00e9occupations que nous avons concernant l\u2019IA et ses effets destructeurs potentiels. Et vous montrez en fait dans le livre comment on peut simplement reprendre des d\u00e9clarations faites dans les ann\u00e9es\u00a01930 et remplacer les armes nucl\u00e9aires par <\/span><\/span>\u00ab intelligence artificielle \u00bb<span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\">. Et elles <\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\">paraiss<\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\">ent <\/span><\/span>d\u2019une actualit\u00e9 saisissante. <\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Mais ce qui m\u2019a int\u00e9ress\u00e9, c\u2019est que, en rapport avec la question de Pluton, vous \u00e9voquez le mythe de la d\u00e9esse Pers\u00e9phone, fille de C\u00e9r\u00e8s, d\u00e9esse de la fertilit\u00e9 et de la nature, et comment elle a \u00e9t\u00e9 enlev\u00e9e du monde et plong\u00e9e dans l\u2019Had\u00e8s, qui est bien s\u00fbr gouvern\u00e9 par le dieu Pluton, et qui est un lieu plein de peur et d\u2019incertitude. Et vous montrez comment ce mythe, s\u2019il r\u00e9sume d\u2019une part nos peurs les plus profondes, indique \u00e9galement la possibilit\u00e9 d\u2019un renouveau. Il me semble qu\u2019un aspect tr\u00e8s important du mythe est qu\u2019il ne se contente pas de d\u00e9crire, mais qu\u2019il nous donne aussi, si vous voulez, des moyens de faire face aux choses, de transformer le n\u00e9gatif en positif. Ainsi, vous dites\u00a0: \u00ab Pers\u00e9phone semble nous montrer ce qu\u2019il faut faire face \u00e0 la peur, \u00e0 la grande peur et au sentiment d\u2019accablement \u00bb.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Pourriez-vous nous dire comment vous voyez cette question ? Ou comment Pers\u00e9phone y parvient-elle ?<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Laura\u00a0:<\/b><\/span><\/span><\/span><\/strong> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Oui, tout \u00e0 fait. Vous savez, la d\u00e9couverte de la plan\u00e8te Pluton, la fission atomique, le d\u00e9veloppement des bombes nucl\u00e9aires et leur utilisation constituent une synchronicit\u00e9 remarquable\u00a0: nous avons d\u00e9couvert une plan\u00e8te, nous l\u2019avons nomm\u00e9e d\u2019apr\u00e8s le dieu de la mort, puis nous avons v\u00e9cu cette rencontre sans pr\u00e9c\u00e9dent. Et Pers\u00e9phone, vous savez, il est tr\u00e8s difficile d\u2019en savoir beaucoup sur le dieu Pluton ou le dieu Had\u00e8s, car <\/span><\/span><\/span><span style=\"color: #2f2f28;\"><span style=\"font-family: PT Serif, Georgia, Times New Roman, serif;\"><span style=\"font-size: medium;\">il existe peu <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">d\u2019\u0153uvres d\u2019art le repr\u00e9sentant\u00a0: les Grecs de l\u2019Antiquit\u00e9 ne voulaient pas attirer son attention. Je pense donc que vous pouvez vous tourner vers le mythe de Pers\u00e9phone pour voir les th\u00e8mes les plus <\/span><\/span><\/span><span style=\"color: #2f2f28;\"><span style=\"font-family: PT Serif, Georgia, Times New Roman, serif;\"><span style=\"font-size: medium;\">profond\u00e9ment plutoniens<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">, et un th\u00e8me important est \u00e9galement l\u2019invisibilit\u00e9. C\u2019est dans le royaume invisible, <\/span><\/span><\/span><span style=\"color: #2f2f28;\"><span style=\"font-family: PT Serif, Georgia, Times New Roman, serif;\"><span style=\"font-size: medium;\">le monde souterrain<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">. Et Pers\u00e9phone, oui, elle est la fille de D\u00e9m\u00e9ter, elle est la fille de la grande m\u00e8re de cet arch\u00e9type de la nature et de la f\u00e9condit\u00e9 qui, je pense, a \u00e9t\u00e9 le plus grand arch\u00e9type f\u00e9minin en Occident jusqu\u2019\u00e0 l\u2019\u00e9poque moderne. Mais ce qui est remarquable dans le mythe de Pers\u00e9phone, c\u2019est qu\u2019elle est enlev\u00e9e dans ce royaume, ce qui est un grand traumatisme et une grande initiation, mais elle fait la transition, elle passe c<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">e seuil<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">, <\/span><\/span><\/span><span style=\"color: #2f2f28;\"><span style=\"font-family: PT Serif, Georgia, Times New Roman, serif;\"><span style=\"font-size: medium;\">une fois pass\u00e9 dans<\/span><\/span><\/span> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">cette<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> nouvelle r\u00e9alit\u00e9, elle devient le seul personnage de la mythologie grecque \u00e0 \u00eatre autoris\u00e9 \u00e0 vivre \u00e0 la fois dans le monde sup\u00e9rieur et dans le monde inf\u00e9rieur.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Elle passe les deux tiers de son temps dans le monde sup\u00e9rieur et un tiers dans le monde inf\u00e9rieur. Jusqu\u2019au moment de son enl\u00e8vement, elle est principalement identifi\u00e9e comme la fille de D\u00e9m\u00e9ter. Une fois enlev\u00e9e, elle devient la femme d\u2019Had\u00e8s et une reine mis\u00e9ricordieuse. Ce qui est int\u00e9ressant dans la descente et l\u2019ascension de Pers\u00e9phone, c\u2019est que Had\u00e8s est un royaume, certes invisible, certes rempli d\u2019une grande oppression, de peur et de mort. Mais il est \u00e9galement consid\u00e9r\u00e9 comme un royaume g\u00e9n\u00e9reux. Souvent, dans les r\u00e9cits mythologiques o\u00f9 Had\u00e8s appara\u00eet, il est l\u00e0 pour apporter une sorte d\u2019\u00e9quilibre. Or, lorsque Pers\u00e9phone est emmen\u00e9e dans le monde souterrain, elle n\u2019a pas la perspective n\u00e9cessaire de l\u2019\u00e9go pour voir cette r\u00e9alit\u00e9 plus large \u00e0 l\u2019\u0153uvre. Elle vit simplement ce traumatisme dans ce monde qu\u2019elle ne pourra jamais comprendre et dans lequel elle ne voudra jamais entrer. Et je pense que vous pouvez comprendre, je veux dire, si nous restons dans les ann\u00e9es\u00a01930 un instant, qui voudrait \u00eatre initi\u00e9 \u00e0 un monde pr\u00e9sentant un risque aussi grand ? Et, vous savez, c\u2019est un risque que nous continuons \u00e0 courir aujourd\u2019hui avec les armes nucl\u00e9aires, mais il y a un \u00e9l\u00e9ment de progr\u00e8s qui ne peut \u00eatre d\u00e9volu, qui ne semble pas pouvoir \u00eatre d\u00e9samorc\u00e9 lorsqu\u2019il s\u2019agit de progr\u00e8s scientifiques et technoscientifiques.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Nous le voyons dans l\u2019histoire des armes nucl\u00e9aires. Nous le voyons \u00e9galement aujourd\u2019hui avec l\u2019histoire de l\u2019\u00e9volution de l\u2019IA, en particulier de l\u2019IAG (Intelligence artificielle g\u00e9n\u00e9rale), <span style=\"color: #2f2f28;\"><span style=\"font-family: PT Serif, Georgia, Times New Roman, serif;\">c\u2019est-\u00e0-dire une intelligence artificielle capable d\u2019\u00e9galer ou de d\u00e9passer les capacit\u00e9s intellectuelles et cr\u00e9atives humaines.<\/span><\/span> Comme vous l\u2019avez mentionn\u00e9, il existe des corr\u00e9lations directes \u2014 et de nombreux auteurs ont \u00e9crit \u00e0 ce sujet, en particulier r\u00e9cemment, entre la fa\u00e7on dont nous parlions de l\u2019atome, la fa\u00e7on dont nous concevions l\u2019atome lorsqu\u2019il \u00e9tait divis\u00e9 \u2014, la fa\u00e7on dont nous concevions le d\u00e9veloppement de l\u2019\u00e9nergie nucl\u00e9aire et la fa\u00e7on dont nous concevons l\u2019IA et l\u2019IAG en particulier, \u00e0 savoir que ce sont des technologies qui ont le pouvoir de transformer le monde pour le meilleur ou de d\u00e9truire l\u2019humanit\u00e9. <span style=\"color: #2f2f28;\"><span style=\"font-family: PT Serif, Georgia, Times New Roman, serif;\">Le projet \u00ab AI\u00a02027 \u00bb, tout r\u00e9cemment publi\u00e9, a d\u2019ailleurs fait grand bruit par ses pr\u00e9dictions inqui\u00e9tantes.<\/span><\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Je pense qu\u2019il existe souvent un d\u00e9sir de retour au principe de Ga\u00efa, au principe de D\u00e9m\u00e9ter, \u00e0 une vision de l\u2019humanit\u00e9 et de la r\u00e9alit\u00e9 qui a longtemps pr\u00e9valu. Et je ne veux pas para\u00eetre pessimiste quand je dis que ce n\u2019est plus le cas aujourd\u2019hui. Je pense qu\u2019il est important de regarder en face la situation dans laquelle nous nous trouvons et d\u2019accepter ce royaume d\u2019Had\u00e8s, ce royaume de grande oppression, de peur, de destruction potentielle et, vous le savez, de mort potentielle, car si nous ne le faisons pas, nous passerons \u00e0 c\u00f4t\u00e9 du renouveau qui s\u2019offre \u00e0 nous dans cette r\u00e9alit\u00e9 en constante \u00e9volution dans laquelle nous vivons.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Pers\u00e9phone elle-m\u00eame subit le traumatisme et la <span style=\"color: #2f2f28;\"><span style=\"font-family: PT Serif, Georgia, Times New Roman, serif;\">s\u00e9paration<\/span><\/span>, mais elle r\u00e9ussit la transition. Elle acquiert la maturit\u00e9 n\u00e9cessaire pour comprendre qu\u2019il y a des choses qui ne peuvent \u00eatre chang\u00e9es. Il y a des processus en jeu qui ne peuvent \u00eatre d\u00e9volus. Alors, comment pouvons-nous regarder cela en face ? Et ce faisant, trouver tous les aspects d\u2019amour, de lumi\u00e8re, de renouveau, de r\u00e9g\u00e9n\u00e9ration et de possibilit\u00e9s pour l\u2019avenir qui s\u2019y trouvent. Vous savez, je pense que nous pouvons rester bloqu\u00e9s en pensant que les choses sont condamn\u00e9es ou irr\u00e9parables. Et s\u2019il y a un monde \u00e0 pleurer, tout comme Pers\u00e9phone pleure son innocence <span style=\"color: #2f2f28;\"><span style=\"font-family: PT Serif, Georgia, Times New Roman, serif;\">et sa vie d\u2019avant<\/span><\/span>, il y a aussi tout un monde \u00e0 d\u00e9couvrir.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Et la derni\u00e8re chose que je dirais \u00e0 ce sujet, c\u2019est que je la consid\u00e8re comme un excellent guide pour la transition. Que se passera-t-il apr\u00e8s cela ? Je ne sais pas. Mais en termes de maturit\u00e9 et de capacit\u00e9 \u00e0 accomplir cette transition difficile, \u00e0 \u00eatre mis\u00e9ricordieux et \u00e0 comprendre la grande peur qui envahit le monde en ce moment, c\u2019est extr\u00eamement important. Et, vous savez, tout rep\u00e8re spirituel que nous pouvons trouver dans ces processus sera, je pense, important.<\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Jane\u00a0:<\/b><\/span><\/span><\/span><\/strong> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">C\u2019est tr\u00e8s int\u00e9ressant, car vous dites que C\u00e9r\u00e8s ou D\u00e9m\u00e9ter est une sorte de figure de Ga\u00efa, mais, en r\u00e9alit\u00e9, l\u2019autre menace existentielle \u00e0 laquelle nous sommes confront\u00e9s vient de la nature elle-m\u00eame, n\u2019est-ce pas ? Du changement climatique. Et je suppose que ce que nous vivons actuellement avec le changement climatique est en fait le visage n\u00e9gatif de la nature.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Laura\u00a0:<\/b><\/span><\/span><\/span><\/strong> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Oui, tout \u00e0 fait.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Jane\u00a0:<\/b><\/span><\/span><\/span><\/strong> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Elle aussi rec\u00e8le un potentiel destructeur. Oui. Tr\u00e8s, tr\u00e8s int\u00e9ressant. Nick, tu avais quelque chose \u00e0 dire pour conclure ?<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Nick : <\/b><\/span><\/span><\/span><\/strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Non, je pense que le dernier point soulev\u00e9 par Laura, \u00e0 savoir Pers\u00e9phone comme guide, comme symbole <\/span><\/span><\/span><span style=\"color: #2f2f28;\"><span style=\"font-family: PT Serif, Georgia, Times New Roman, serif;\"><span style=\"font-size: medium;\">de grande maturit\u00e9 pour avancer<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> face \u00e0 l\u2019incertitude et \u00e0 l\u2019ignorance, mais avec optimisme, en suivant le cours de la vie et en suivant les \u00e9nergies arch\u00e9typales vers <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">le futur<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">, est vraiment un tr\u00e8s bon symbole pour nous. <\/span><\/span><\/span><span style=\"color: #2f2f28;\"><span style=\"font-family: PT Serif, Georgia, Times New Roman, serif;\"><span style=\"font-size: medium;\">Cette id\u00e9e du mythe comme essentiel \u00e0 la sant\u00e9 holistique de l\u2019exp\u00e9rience humaine, parce qu\u2019il nous relie \u00e0 une compr\u00e9hension plus vaste de la psych\u00e9 \u2014 au-del\u00e0 de l\u2019orientation quotidienne \u2014, me semble \u00eatre un point tr\u00e8s fort que vous soulevez. Je ne sais pas si vous avez une derni\u00e8re r\u00e9flexion \u00e0 ajouter sur cette conversation ou sur ce dernier point, mais le mythe de Pers\u00e9phone me para\u00eet une illustration tr\u00e8s claire de la mani\u00e8re dont nous pouvons surmonter les d\u00e9fis auxquels nous faisons face.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Laura\u00a0:<\/b><\/span><\/span><\/span><\/strong> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Oui. Je suppose que la derni\u00e8re chose que je dirais \u00e0 propos de Pers\u00e9phone, c\u2019est qu\u2019elle est un pont entre deux mondes. Et je pense que c\u2019est vraiment l\u00e0 o\u00f9 nous en sommes, et d\u2019une certaine mani\u00e8re, je suis s\u00fbre qu\u2019\u00e0 chaque \u00e9poque, chaque \u00eatre humain ressent cela. <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">J<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">\u2019y pense parfois, mais avec cette vague technologique et ces id\u00e9es de singularit\u00e9s technologiques ou de loi de Moore, ce<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">tte<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> croissance exponentielle, ces progr\u00e8s technologiques qui d\u00e9passent de loin les processus psychiques<\/span><\/span><\/span><span style=\"color: #2f2f28;\"><span style=\"font-family: PT Serif, Georgia, Times New Roman, serif;\"><span style=\"font-size: medium;\">, je pense que nous vivons une p\u00e9riode de mutation.<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"> Et je pense qu\u2019il est important d\u2019avoir ces figures de transition qui ont encore acc\u00e8s \u00e0 l\u2019Ancien Monde. Elle <\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">garde<\/span><\/span><\/span> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">l\u2019<\/span><\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">acc\u00e8s \u00e0 la nature, \u00e0 sa m\u00e8re, \u00e0 ces choses-l\u00e0. Et elle a \u00e9galement acc\u00e8s \u00e0 ces processus \u00e9volutifs peut-\u00eatre plus invisibles, plus intenses. Je pense donc que tout le monde n\u2019a pas besoin de tout savoir tout de suite, mais qu\u2019il faut avancer de mani\u00e8re m\u00fbre, mesur\u00e9e, prudente et attentionn\u00e9e.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Jane\u00a0:<\/b><\/span><\/span><\/span><\/strong> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">C\u2019est une fin merveilleuse. Merci beaucoup de nous avoir parl\u00e9.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><strong><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\"><b>Laura\u00a0:<\/b><\/span><\/span><\/span><\/strong> <span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Merci. J\u2019ai pass\u00e9 un tr\u00e8s bon moment.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">Podcast et transcription, 10\u00a0octobre 2025\u00a0: <\/span><\/span><\/span><span style=\"color: #000080;\"><u><a href=\"https:\/\/besharamagazine.org\/podcast\/ld-deutsch-time-myth-matter\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #000000;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: medium;\">https:\/\/besharamagazine.org\/podcast\/ld-deutsch-time-myth-matter\/<\/span><\/span><\/span><\/a><\/u><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si l\u2019on regarde l\u2019histoire de l\u2019Occident, nous avons toujours utilis\u00e9 les technologies les plus avanc\u00e9es pour d\u00e9crire le cerveau et l\u2019univers. Au XIVe\u00a0si\u00e8cle, l\u2019univers \u00e9tait d\u00e9crit comme une grande horlogerie. Si l\u2019on se penche sur le mod\u00e8le psychique de Freud, on constate qu\u2019il est fortement influenc\u00e9 par la machine \u00e0 vapeur. C\u2019est un mod\u00e8le hydraulique. On appuie sur quelque chose, et autre chose remonte. Les axones du cerveau ont \u00e9t\u00e9 mod\u00e9lis\u00e9s d\u2019apr\u00e8s les fils t\u00e9l\u00e9phoniques. Les fils t\u00e9l\u00e9phoniques sont apparus en premier et les neuroscientifiques se sont demand\u00e9 si cela pouvait fonctionner de la m\u00eame mani\u00e8re. Et c\u2019est ainsi que cela fonctionnait. Dans les ann\u00e9es\u00a01980, David Bohm et Karl Pribram ont propos\u00e9 le mod\u00e8le holographique. Et aujourd\u2019hui, bien s\u00fbr, nous vivons dans un ordinateur et le cerveau est un ordinateur. Il y a donc un aspect herm\u00e9neutique dans notre fa\u00e7on de concevoir la r\u00e9alit\u00e9.<\/p>\n","protected":false},"author":2,"featured_media":20895,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[391,162,142,797,25,1690,359,2235,1590,2204,1748,159],"class_list":["post-20894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interview","tag-archetype","tag-espace","tag-inconscient","tag-inconscient-collectif","tag-jung","tag-kastrup","tag-mythe","tag-psyche","tag-science-et-conscience","tag-simulation","tag-synchronicite","tag-temps"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Temps, mythe et mati\u00e8re. Entretien avec LD Deutsch - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.revue3emillenaire.com\/blog\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Temps, mythe et mati\u00e8re. Entretien avec LD Deutsch - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\" \/>\n<meta property=\"og:description\" content=\"Si l\u2019on regarde l\u2019histoire de l\u2019Occident, nous avons toujours utilis\u00e9 les technologies les plus avanc\u00e9es pour d\u00e9crire le cerveau et l\u2019univers. Au XIVe\u00a0si\u00e8cle, l\u2019univers \u00e9tait d\u00e9crit comme une grande horlogerie. Si l\u2019on se penche sur le mod\u00e8le psychique de Freud, on constate qu\u2019il est fortement influenc\u00e9 par la machine \u00e0 vapeur. C\u2019est un mod\u00e8le hydraulique. On appuie sur quelque chose, et autre chose remonte. Les axones du cerveau ont \u00e9t\u00e9 mod\u00e9lis\u00e9s d\u2019apr\u00e8s les fils t\u00e9l\u00e9phoniques. Les fils t\u00e9l\u00e9phoniques sont apparus en premier et les neuroscientifiques se sont demand\u00e9 si cela pouvait fonctionner de la m\u00eame mani\u00e8re. Et c\u2019est ainsi que cela fonctionnait. Dans les ann\u00e9es\u00a01980, David Bohm et Karl Pribram ont propos\u00e9 le mod\u00e8le holographique. Et aujourd\u2019hui, bien s\u00fbr, nous vivons dans un ordinateur et le cerveau est un ordinateur. Il y a donc un aspect herm\u00e9neutique dans notre fa\u00e7on de concevoir la r\u00e9alit\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.revue3emillenaire.com\/blog\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\/\" \/>\n<meta property=\"og:site_name\" content=\"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-15T21:03:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-16T17:30:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.revue3emillenaire.com\/blog\/wp-content\/uploads\/2025\/10\/LD-Deutsch.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"339\" \/>\n\t<meta property=\"og:image:height\" content=\"324\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"3e mill\u00e9naire\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"3e mill\u00e9naire\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"39 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\\\/\"},\"author\":{\"name\":\"3e mill\u00e9naire\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#\\\/schema\\\/person\\\/b692dacff720a5344a6190bc714397eb\"},\"headline\":\"Temps, mythe et mati\u00e8re. Entretien avec LD Deutsch\",\"datePublished\":\"2025-10-15T21:03:57+00:00\",\"dateModified\":\"2025-10-16T17:30:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\\\/\"},\"wordCount\":8571,\"image\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/LD-Deutsch.jpg\",\"keywords\":[\"arch\u00e9type\",\"espace\",\"Inconscient\",\"Inconscient Collectif\",\"Jung\",\"Kastrup\",\"Mythe\",\"Psych\u00e9\",\"science et conscience\",\"Simulation\",\"Synchronicit\u00e9\",\"temps\"],\"articleSection\":[\"Entretien\\\/Interview\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\\\/\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\\\/\",\"name\":\"Temps, mythe et mati\u00e8re. Entretien avec LD Deutsch - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/LD-Deutsch.jpg\",\"datePublished\":\"2025-10-15T21:03:57+00:00\",\"dateModified\":\"2025-10-16T17:30:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#\\\/schema\\\/person\\\/b692dacff720a5344a6190bc714397eb\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/LD-Deutsch.jpg\",\"contentUrl\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/LD-Deutsch.jpg\",\"width\":339,\"height\":324},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Temps, mythe et mati\u00e8re. Entretien avec LD Deutsch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/\",\"name\":\"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\",\"description\":\"L&#039;Homme en devenir\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#\\\/schema\\\/person\\\/b692dacff720a5344a6190bc714397eb\",\"name\":\"3e mill\u00e9naire\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/author\\\/scoussa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Temps, mythe et mati\u00e8re. Entretien avec LD Deutsch - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.revue3emillenaire.com\/blog\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\/","og_locale":"fr_FR","og_type":"article","og_title":"Temps, mythe et mati\u00e8re. Entretien avec LD Deutsch - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","og_description":"Si l\u2019on regarde l\u2019histoire de l\u2019Occident, nous avons toujours utilis\u00e9 les technologies les plus avanc\u00e9es pour d\u00e9crire le cerveau et l\u2019univers. Au XIVe\u00a0si\u00e8cle, l\u2019univers \u00e9tait d\u00e9crit comme une grande horlogerie. Si l\u2019on se penche sur le mod\u00e8le psychique de Freud, on constate qu\u2019il est fortement influenc\u00e9 par la machine \u00e0 vapeur. C\u2019est un mod\u00e8le hydraulique. On appuie sur quelque chose, et autre chose remonte. Les axones du cerveau ont \u00e9t\u00e9 mod\u00e9lis\u00e9s d\u2019apr\u00e8s les fils t\u00e9l\u00e9phoniques. Les fils t\u00e9l\u00e9phoniques sont apparus en premier et les neuroscientifiques se sont demand\u00e9 si cela pouvait fonctionner de la m\u00eame mani\u00e8re. Et c\u2019est ainsi que cela fonctionnait. Dans les ann\u00e9es\u00a01980, David Bohm et Karl Pribram ont propos\u00e9 le mod\u00e8le holographique. Et aujourd\u2019hui, bien s\u00fbr, nous vivons dans un ordinateur et le cerveau est un ordinateur. Il y a donc un aspect herm\u00e9neutique dans notre fa\u00e7on de concevoir la r\u00e9alit\u00e9.","og_url":"https:\/\/www.revue3emillenaire.com\/blog\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\/","og_site_name":"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","article_published_time":"2025-10-15T21:03:57+00:00","article_modified_time":"2025-10-16T17:30:19+00:00","og_image":[{"width":339,"height":324,"url":"https:\/\/www.revue3emillenaire.com\/blog\/wp-content\/uploads\/2025\/10\/LD-Deutsch.jpg","type":"image\/jpeg"}],"author":"3e mill\u00e9naire","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"3e mill\u00e9naire","Dur\u00e9e de lecture estim\u00e9e":"39 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.revue3emillenaire.com\/blog\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\/#article","isPartOf":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\/"},"author":{"name":"3e mill\u00e9naire","@id":"https:\/\/www.revue3emillenaire.com\/blog\/#\/schema\/person\/b692dacff720a5344a6190bc714397eb"},"headline":"Temps, mythe et mati\u00e8re. Entretien avec LD Deutsch","datePublished":"2025-10-15T21:03:57+00:00","dateModified":"2025-10-16T17:30:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\/"},"wordCount":8571,"image":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revue3emillenaire.com\/blog\/wp-content\/uploads\/2025\/10\/LD-Deutsch.jpg","keywords":["arch\u00e9type","espace","Inconscient","Inconscient Collectif","Jung","Kastrup","Mythe","Psych\u00e9","science et conscience","Simulation","Synchronicit\u00e9","temps"],"articleSection":["Entretien\/Interview"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.revue3emillenaire.com\/blog\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\/","url":"https:\/\/www.revue3emillenaire.com\/blog\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\/","name":"Temps, mythe et mati\u00e8re. Entretien avec LD Deutsch - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","isPartOf":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\/#primaryimage"},"image":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revue3emillenaire.com\/blog\/wp-content\/uploads\/2025\/10\/LD-Deutsch.jpg","datePublished":"2025-10-15T21:03:57+00:00","dateModified":"2025-10-16T17:30:19+00:00","author":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/#\/schema\/person\/b692dacff720a5344a6190bc714397eb"},"breadcrumb":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.revue3emillenaire.com\/blog\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.revue3emillenaire.com\/blog\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\/#primaryimage","url":"https:\/\/www.revue3emillenaire.com\/blog\/wp-content\/uploads\/2025\/10\/LD-Deutsch.jpg","contentUrl":"https:\/\/www.revue3emillenaire.com\/blog\/wp-content\/uploads\/2025\/10\/LD-Deutsch.jpg","width":339,"height":324},{"@type":"BreadcrumbList","@id":"https:\/\/www.revue3emillenaire.com\/blog\/temps-mythe-et-matiere-entretien-avec-ld-deutsch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.revue3emillenaire.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Temps, mythe et mati\u00e8re. Entretien avec LD Deutsch"}]},{"@type":"WebSite","@id":"https:\/\/www.revue3emillenaire.com\/blog\/#website","url":"https:\/\/www.revue3emillenaire.com\/blog\/","name":"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","description":"L&#039;Homme en devenir","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.revue3emillenaire.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.revue3emillenaire.com\/blog\/#\/schema\/person\/b692dacff720a5344a6190bc714397eb","name":"3e mill\u00e9naire","url":"https:\/\/www.revue3emillenaire.com\/blog\/author\/scoussa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/posts\/20894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/comments?post=20894"}],"version-history":[{"count":0,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/posts\/20894\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/media\/20895"}],"wp:attachment":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/media?parent=20894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/categories?post=20894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/tags?post=20894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}