{"id":3757,"date":"2010-06-23T13:20:32","date_gmt":"2010-06-23T12:20:32","guid":{"rendered":"http:\/\/www.revue3emillenaire.com\/blog\/?p=3757"},"modified":"2011-10-02T15:27:16","modified_gmt":"2011-10-02T14:27:16","slug":"nostalgie-de-lunite-par-marcel-hennart","status":"publish","type":"post","link":"https:\/\/www.revue3emillenaire.com\/blog\/nostalgie-de-lunite-par-marcel-hennart\/","title":{"rendered":"Nostalgie de l&rsquo;Unit\u00e9 par Marcel Hennart"},"content":{"rendered":"<p style=\"text-align: justify;\">(Revue Spiritualit\u00e9. N<sup>o<\/sup> 9 &amp; 10. 15 Ao\u00fbt \u2013 15 Septembre 1945)<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">On rencontre assez fr\u00e9quemment la conception dualiste.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Elle s&rsquo;applique, d&rsquo;ailleurs, aux notions les plus diverses qui soient notion du monde r\u00e9el et du monde illusoire, notion de l&rsquo;\u00eatre et du non-\u00eatre, notion de l&rsquo;\u00e2me et du corps, notion de l&rsquo;amour et de la raison, notion du bien et du mal&#8230; notions plus physiques, enfin. Il est curieux de voir combien ces notions sont anciennes et se retrouvent chez les peuples les plus dissemblables.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Dans certains cas, il s&rsquo;agit d&rsquo;un concept qui exclut son contraire. Par exemple : une chose qui est ne peut pas ne pas \u00eatre (comme disait Aristote).<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Cependant, depuis longtemps, le concept ombre ou reflet est, de beaucoup, plus g\u00e9n\u00e9ral. C&rsquo;est lui qu&rsquo;on trouve aux Indes ; le monde o\u00f9 nous vivons est un reflet du monde r\u00e9el. C&rsquo;est aussi cette id\u00e9e qui se trouve \u00e0 la base de notre notion du bien et du mal : chez les peuples primitifs on trouve d&rsquo;innombrables l\u00e9gendes ayant trait \u00e0 la peur de l&rsquo;ombre que nous projetons ou d&rsquo;un reflet qu&rsquo;un miroir nous donne : ce reflet, cette ombre deviennent les symboles de notre conscience.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Tr\u00e8s souvent, dans les cosmogonies, le mal est un sous-produit du monde cr\u00e9\u00e9 : nous connaissons l&rsquo;histoire d&rsquo;Adam consistant \u00e0 pouvoir faire le mal ; la conception du Coran n&rsquo;en est gu\u00e8re \u00e9loign\u00e9e. Mais Platon est plus explicite : le mal, c&rsquo;est ce qui d\u00e9via le cours de la Cr\u00e9ation. Rappelons-le, la conception de l&rsquo;Inde est fort proche ; elle conclut : quiconque s&rsquo;identifie au reflet plut\u00f4t qu&rsquo;\u00e0 l&rsquo;\u00catre restera, m\u00eame apr\u00e8s sa mort, parmi les reflets et les ombres\u00a0 (Samsara).<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Dans un troisi\u00e8me cas, les deux principes oppos\u00e9s ne traduisent pas seulement une m\u00eame origine, mais tendent \u00e0 fusionner.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Cette conception peut se trouver, par exemple en Chine, dans le \u00ab Livre des Transformations \u00bb (Yi-king) : les trigrammes qui sans doute expliquent le monde constituent les combinaisons multiples du signe Yang (trait plein) et du signe Yin (trait bris\u00e9). Plus tard, sous les Song, le principe m\u00e2le repr\u00e9sente l&rsquo;actif ; le principe femelle l&rsquo;immobile<a href=\"#_ftn1\">[1]<\/a>. Du prunier proc\u00e8dent le soleil, les \u00e9toiles; du second, la lune, les corps c\u00e9lestes d&rsquo;o\u00f9 na\u00eet le Ciel. A ces antinomies, correspondent l&rsquo;\u00e9l\u00e9ment flexible (eau, sol) et l&rsquo;\u00e9l\u00e9ment dur (feu, pierre) d&rsquo;o\u00f9 la Terre. Quand les essences de ces \u00e9l\u00e9ments se joignent, de la voie m\u00e2le na\u00eet l&rsquo;homme, de la voie femelle la femme. Et \u00e0 partir d&rsquo;eux, bien d&rsquo;autres. On retrouve une id\u00e9e connexe dans le Zohar juif : Dieu, en se manifestant par des S\u00e9phiroth qui se mat\u00e9rialisent progressivement, s&rsquo;ext\u00e9riorise en principes-p\u00e8res et en principes-m\u00e8res successifs. Cette id\u00e9e d&rsquo;opposition, par l&rsquo;interm\u00e9diaire de Plotin, remonte peut-\u00eatre \u00e0 H\u00e9raclite. Toujours est-il qu&rsquo;\u00e0 chaque stade ces deux principes, provenant d&rsquo;une m\u00eame S\u00e9phira, tendent, aussit\u00f4t \u00e0 fusionner par l&rsquo;interm\u00e9diaire d&rsquo;une troisi\u00e8me force.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Ce troisi\u00e8me cas, tout ing\u00e9nieux et gratuit qu&rsquo;il paraisse, s&rsquo;apparente, semble-t-il, \u00e0 des faits d&rsquo;observation absolument g\u00e9n\u00e9raux.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Biologiquement, le ph\u00e9nom\u00e8ne a \u00e9t\u00e9 reconnu chez l&rsquo;infusoire. Pour autant que le milieu ne l&rsquo;intoxique pas, la cellule se divise en deux, puis en quatre, puis en huit. Si le milieu ne convient plus, deux parcelles du m\u00eame individu vont fusionner pour r\u00e9g\u00e9n\u00e9rer leur race (premi\u00e8re manifestation de la sexualit\u00e9 ?) (M. et Mme Chatten).<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Dans des organismes plus \u00e9volu\u00e9s, la diff\u00e9rence semble moins nette. Un esprit imbu de chimie aurait tendance \u00e0 voir dans la diff\u00e9renciation des sexes une diff\u00e9rence de pH : l&rsquo;un serait acide, l&rsquo;autre basique. Au fait, la folliculine et la testost\u00e9rone se distinguent par une diff\u00e9rence de saturation des noyaux I et IV (question de rH2<a href=\"#_ftn2\">[2]<\/a>). D&rsquo;autre part, chez la chlamydomonas, une isom\u00e9rie cis-trans est seule en jeu (Brachet ?). Toujours est-il que l&rsquo;antique l\u00e9gende des Androgynes, tout comme les constatations de Freud, semble prouvable.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Dans le cas ci-dessus, se traduit nettement la recherche de l&rsquo;unit\u00e9 par la reproduction d&rsquo;un \u00eatre nouveau, pareil \u00e0 l&rsquo;ancien.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Cette antinomie est \u00e0 la base m\u00eame de toute mati\u00e8re et risquerait beaucoup de compromettre une des premi\u00e8res preuves de la Cr\u00e9ation : le changeant n&rsquo;existe que gr\u00e2ce \u00e0 l&rsquo;inchangeant. Les physiciens de l&rsquo;atome supposent l&rsquo;existence d&rsquo;un noyau central (\u00e9lectrons positifs et neutrons) en \u00e9quilibre avec les \u00e9lectrons n\u00e9gatifs de p\u00e9riph\u00e9rie. Les ph\u00e9nom\u00e8nes \u00e9lectromagn\u00e9tiques et lumineux ne seraient dus qu&rsquo;\u00e0 l&rsquo;oscillation de ces \u00e9lectrons d&rsquo;un niveau \u00e0 l&rsquo;autre, ou m\u00eame \u00e0 leur \u00e9jection (Planck). On a, d&rsquo;ailleurs, pu pousser les exp\u00e9riences plus loin : par l&rsquo;effet d&rsquo;un rayonnement gamma, les \u00e9poux Joliot-Curie sont arriv\u00e9s \u00e0 provoquer l&rsquo;\u00e9mission d&rsquo;\u00e9lectrons \u00e0 signes diff\u00e9rents ; tandis que d&rsquo;autre part M. Thibaud, par intervention d&rsquo;\u00e9lectricit\u00e9 positive, a invers\u00e9 le ph\u00e9nom\u00e8ne (annihilation de la mati\u00e8re). Dans tous les cas, les rayons cosmiques, en provoquant l&rsquo;alternation de ces deux ph\u00e9nom\u00e8nes, transposent l&rsquo;ancienne th\u00e9orie du Zohar ; de plus, ils t\u00e9moignent peut-\u00eatre de l&rsquo;activit\u00e9 du principe initial (atome primitif de l&rsquo;abb\u00e9 Lemaitre)<a href=\"#_ftn3\">[3]<\/a>.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Enfin, selon les th\u00e9ories les plus modernes, l&rsquo;\u00e9lectron \u00e0 masse infime et volume tr\u00e8s grand correspondrait \u00e0 une expansion de la m\u00eame ENERGIE qui se trouve condens\u00e9e dans le noyau central (Tournaire, Baker, Ram Linssen).<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Depuis longtemps, les philosophes de l&rsquo;Inde l&rsquo;avaient pressenti quand ils parlaient du brahma s&rsquo;\u00e9panouissant, puis se r\u00e9tractant (Linssen)<a href=\"#_ftn4\">[4]<\/a>.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Mais comme rien ne vient de rien et comme le changeant suppose l&rsquo;inchangeant, sans doute faudra-t-il chercher encore plus loin les \u00e9l\u00e9ments constitutifs communs de la mati\u00e8re, de l&rsquo;\u00e9lectricit\u00e9, de la lumi\u00e8re, sans doute aussi de l&rsquo;\u00e2me.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Les m\u00eames particules infimes seraient-elles a la base de toute ENERGIE ?<\/p>\n<p style=\"text-align: right;\">Marcel HENNART<\/p>\n<p style=\"text-align: justify;\">\n<hr style=\"text-align: justify;\" size=\"1\" \/>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref1\">[1]<\/a> En chinois moderne, ces signes s&rsquo;\u00e9crivent diff\u00e9remment.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref2\">[2]<\/a> Potentiel d&rsquo;oxydor\u00e9duction.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref3\">[3]<\/a> Il ne faut pas oublier que, certains atomes se d\u00e9sagr\u00e8gent facilement. Par exemple, ceux des corps radioactifs. D&rsquo;autres r\u00e9actions interviennent \u00e9galement, surtout \u00e0 haute temp\u00e9rature. (Ram Linssen, Les nouveaux horizons de la Science, Spiritualit\u00e9 1-2.)<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref4\">[4]<\/a> A une autre \u00e9chelle, ce fait ne se perp\u00e9tuerait-il point en nous : alternation irr\u00e9guli\u00e8re de mouvements altruistes (sens de 1a Cr\u00e9ation) et de repliements sur nous-m\u00eames. (Aur\u00e9ti, Tendances \u00e0 la rupture.)<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>On rencontre assez fr\u00e9quemment la conception dualiste. Elle s&rsquo;applique, d&rsquo;ailleurs, aux notions les plus diverses qui soient notion du monde r\u00e9el et du monde illusoire, notion de l&rsquo;\u00eatre et du non-\u00eatre, notion de l&rsquo;\u00e2me et du corps, notion de l&rsquo;amour et de la raison, notion du bien et du mal&#8230; notions plus physiques, enfin. Il est curieux de voir combien ces notions sont anciennes et se retrouvent chez les peuples les plus dissemblables.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[575],"tags":[275,123],"class_list":["post-3757","post","type-post","status-publish","format-standard","hentry","category-hennart-marcel","tag-dualite","tag-unite"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nostalgie de l&#039;Unit\u00e9 par Marcel Hennart - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.revue3emillenaire.com\/blog\/nostalgie-de-lunite-par-marcel-hennart\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nostalgie de l&#039;Unit\u00e9 par Marcel Hennart - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\" \/>\n<meta property=\"og:description\" content=\"On rencontre assez fr\u00e9quemment la conception dualiste. Elle s&#039;applique, d&#039;ailleurs, aux notions les plus diverses qui soient notion du monde r\u00e9el et du monde illusoire, notion de l&#039;\u00eatre et du non-\u00eatre, notion de l&#039;\u00e2me et du corps, notion de l&#039;amour et de la raison, notion du bien et du mal... notions plus physiques, enfin. Il est curieux de voir combien ces notions sont anciennes et se retrouvent chez les peuples les plus dissemblables.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.revue3emillenaire.com\/blog\/nostalgie-de-lunite-par-marcel-hennart\/\" \/>\n<meta property=\"og:site_name\" content=\"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\" \/>\n<meta property=\"article:published_time\" content=\"2010-06-23T12:20:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-10-02T14:27:16+00:00\" \/>\n<meta name=\"author\" content=\"3e mill\u00e9naire\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"3e mill\u00e9naire\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/nostalgie-de-lunite-par-marcel-hennart\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/nostalgie-de-lunite-par-marcel-hennart\\\/\"},\"author\":{\"name\":\"3e mill\u00e9naire\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#\\\/schema\\\/person\\\/9a3a7cc4ccaa707f402d4394327106d5\"},\"headline\":\"Nostalgie de l&rsquo;Unit\u00e9 par Marcel Hennart\",\"datePublished\":\"2010-06-23T12:20:32+00:00\",\"dateModified\":\"2011-10-02T14:27:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/nostalgie-de-lunite-par-marcel-hennart\\\/\"},\"wordCount\":1064,\"keywords\":[\"dualit\u00e9\",\"Unit\u00e9\"],\"articleSection\":[\"Hennart Marcel\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/nostalgie-de-lunite-par-marcel-hennart\\\/\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/nostalgie-de-lunite-par-marcel-hennart\\\/\",\"name\":\"Nostalgie de l'Unit\u00e9 par Marcel Hennart - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#website\"},\"datePublished\":\"2010-06-23T12:20:32+00:00\",\"dateModified\":\"2011-10-02T14:27:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#\\\/schema\\\/person\\\/9a3a7cc4ccaa707f402d4394327106d5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/nostalgie-de-lunite-par-marcel-hennart\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/nostalgie-de-lunite-par-marcel-hennart\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/nostalgie-de-lunite-par-marcel-hennart\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nostalgie de l&rsquo;Unit\u00e9 par Marcel Hennart\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/\",\"name\":\"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\",\"description\":\"L&#039;Homme en devenir\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#\\\/schema\\\/person\\\/9a3a7cc4ccaa707f402d4394327106d5\",\"name\":\"3e mill\u00e9naire\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nostalgie de l'Unit\u00e9 par Marcel Hennart - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.revue3emillenaire.com\/blog\/nostalgie-de-lunite-par-marcel-hennart\/","og_locale":"fr_FR","og_type":"article","og_title":"Nostalgie de l'Unit\u00e9 par Marcel Hennart - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","og_description":"On rencontre assez fr\u00e9quemment la conception dualiste. Elle s'applique, d'ailleurs, aux notions les plus diverses qui soient notion du monde r\u00e9el et du monde illusoire, notion de l'\u00eatre et du non-\u00eatre, notion de l'\u00e2me et du corps, notion de l'amour et de la raison, notion du bien et du mal... notions plus physiques, enfin. Il est curieux de voir combien ces notions sont anciennes et se retrouvent chez les peuples les plus dissemblables.","og_url":"https:\/\/www.revue3emillenaire.com\/blog\/nostalgie-de-lunite-par-marcel-hennart\/","og_site_name":"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","article_published_time":"2010-06-23T12:20:32+00:00","article_modified_time":"2011-10-02T14:27:16+00:00","author":"3e mill\u00e9naire","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"3e mill\u00e9naire","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.revue3emillenaire.com\/blog\/nostalgie-de-lunite-par-marcel-hennart\/#article","isPartOf":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/nostalgie-de-lunite-par-marcel-hennart\/"},"author":{"name":"3e mill\u00e9naire","@id":"https:\/\/www.revue3emillenaire.com\/blog\/#\/schema\/person\/9a3a7cc4ccaa707f402d4394327106d5"},"headline":"Nostalgie de l&rsquo;Unit\u00e9 par Marcel Hennart","datePublished":"2010-06-23T12:20:32+00:00","dateModified":"2011-10-02T14:27:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/nostalgie-de-lunite-par-marcel-hennart\/"},"wordCount":1064,"keywords":["dualit\u00e9","Unit\u00e9"],"articleSection":["Hennart Marcel"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.revue3emillenaire.com\/blog\/nostalgie-de-lunite-par-marcel-hennart\/","url":"https:\/\/www.revue3emillenaire.com\/blog\/nostalgie-de-lunite-par-marcel-hennart\/","name":"Nostalgie de l'Unit\u00e9 par Marcel Hennart - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","isPartOf":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/#website"},"datePublished":"2010-06-23T12:20:32+00:00","dateModified":"2011-10-02T14:27:16+00:00","author":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/#\/schema\/person\/9a3a7cc4ccaa707f402d4394327106d5"},"breadcrumb":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/nostalgie-de-lunite-par-marcel-hennart\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.revue3emillenaire.com\/blog\/nostalgie-de-lunite-par-marcel-hennart\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.revue3emillenaire.com\/blog\/nostalgie-de-lunite-par-marcel-hennart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.revue3emillenaire.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Nostalgie de l&rsquo;Unit\u00e9 par Marcel Hennart"}]},{"@type":"WebSite","@id":"https:\/\/www.revue3emillenaire.com\/blog\/#website","url":"https:\/\/www.revue3emillenaire.com\/blog\/","name":"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","description":"L&#039;Homme en devenir","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.revue3emillenaire.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.revue3emillenaire.com\/blog\/#\/schema\/person\/9a3a7cc4ccaa707f402d4394327106d5","name":"3e mill\u00e9naire","url":"https:\/\/www.revue3emillenaire.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/posts\/3757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/comments?post=3757"}],"version-history":[{"count":0,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/posts\/3757\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/media?parent=3757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/categories?post=3757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/tags?post=3757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}