{"id":4004,"date":"2010-07-22T14:30:22","date_gmt":"2010-07-22T13:30:22","guid":{"rendered":"http:\/\/www.revue3emillenaire.com\/blog\/?p=4004"},"modified":"2011-10-02T15:16:40","modified_gmt":"2011-10-02T14:16:40","slug":"roger-godel-et-la-science-de-lessentiel-par-therese-brosse","status":"publish","type":"post","link":"https:\/\/www.revue3emillenaire.com\/blog\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\/","title":{"rendered":"Roger Godel et la science de l&rsquo;essentiel par Th\u00e9r\u00e8se Brosse"},"content":{"rendered":"<p style=\"text-align: justify;\">(Extrait de l\u2019ouvrage collectif d\u2019hommage : Roger Godel De l\u2019humanisme \u00e0 l\u2019humain, \u00c9d. Les Belles Lettres, 1963)<\/p>\n<p style=\"text-align: justify;\"><strong> <\/strong><\/p>\n<p style=\"text-align: justify; padding-left: 150px;\">\u00ab <em>O\u00f9 s&rsquo;ach\u00e8ve notre t\u00e2che de cardiologue ? Elle ne comporte pas de limites ; elle ne s&rsquo;arr\u00eate, \u00e0 vrai dire, ni aux aspects somatiques, ni \u00e0 une profondeur quelconque de la psych\u00e9 ; elle nous invite \u00e0 aller plus loin dans la direction de l&rsquo;unit\u00e9. QUI est cet \u00eatre en qui le c\u0153ur bat ? Il nous faut tout de m\u00eame tenter de l&rsquo;approcher, de l&rsquo;entendre et de nous faire entendre de lui&#8230;<\/em> \u00bb<\/p>\n<p style=\"text-align: right;\">(Roger GODEL. Correspondance.<\/p>\n<p style=\"text-align: right;\">Avril 1953.)<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Evoquer au moyen des imperfections du langage les aspects les plus attachants de la personnalit\u00e9 et de l\u2019\u0153uvre de Roger Godel, c&rsquo;est beaucoup plus que rendre hommage tout \u00e0 la fois \u00e0 l&rsquo;ami, au m\u00e9decin, au savant et au philosophe. C&rsquo;est s&rsquo;abreuver aux sources m\u00eames de potentialit\u00e9s humaines insoup\u00e7onn\u00e9es et d\u00e9couvrir, avec lui, comment la recherche de l&rsquo;ultime r\u00e9alit\u00e9 donne un sens non seulement \u00e0 la vie, mais aussi aux sciences de la vie qu&rsquo;elle ordonne, qu&rsquo;elle valorise et qu&rsquo;elle inspire.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">A cette perspective dont il ne d\u00e9tachait pas son regard, Roger Godel donnait volontiers le nom d&rsquo;\u00ab\u00a0<em>essentiel<\/em> \u00bb, sachant par exp\u00e9rience, que l&rsquo;attitude scientifique la plus rigoureuse ne viendrait pas d\u00e9mentir, bien au contraire, l&rsquo;efficacit\u00e9 d&rsquo;une prise de conscience qui transcende les voies de l&rsquo;intellect le plus subtil. Et il se chargeait d&rsquo;en proposer d&rsquo;irr\u00e9futables d\u00e9monstrations.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Lorsqu&rsquo;il y a quarante ans, un stage \u00e0 l&rsquo;H\u00f4tel-Dieu nous mettait pour la premi\u00e8re fois en pr\u00e9sence, Roger Godel et moi, des affectations diff\u00e9rentes ne favorisaient aucun rapprochement et ce coll\u00e8gue d&rsquo;externat n&rsquo;\u00e9tait alors pour moi qu&rsquo;un visage et un nom associ\u00e9s \u00e0 celui du service o\u00f9 il exer\u00e7ait ses fonctions. C&rsquo;est sans reprise de contact que, dans la suite de nos \u00e9tudes m\u00e9dicales, nous nous orientions l&rsquo;un et l&rsquo;autre vers la sp\u00e9cialisation cardiologique que Roger Godel allait exercer si brillamment \u00e0 titre de m\u00e9decin-chef de l&rsquo;H\u00f4pital d&rsquo;Isma\u00eflia.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">D\u00e8s lors, les douloureux probl\u00e8mes humains qui laissent le m\u00e9decin d\u00e9sarm\u00e9 au chevet du malade nous conduisaient, par des voies diff\u00e9rentes, mais dans une m\u00eame pr\u00e9occupation, \u00e0 demander aux traditions mill\u00e9naires, le secret d&rsquo;une sagesse riche de possibilit\u00e9s salvatrices.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Ce lien profond entre la vocation humaine de la m\u00e9decine et la n\u00e9cessit\u00e9 imp\u00e9rieuse d&rsquo;une connaissance de l&rsquo;homme revaloris\u00e9e aux sources m\u00eames de l&rsquo;\u00eatre, Roger Godel l&rsquo;a ressenti puissamment et en a d\u00e9frich\u00e9 le myst\u00e8re en mobilisant toutes les forces vives de sa nature d&rsquo;\u00e9lite. A l&rsquo;apog\u00e9e de la r\u00e9alisation, il l&rsquo;exprimait avec une \u00e9loquence poignante : \u00ab <em>Maintenant seulement, notre profession rev\u00eat pour nous un sens profond, une pl\u00e9nitude, une beaut\u00e9 que nous ne connaissions pas \u00e0 l&rsquo;origine. Maintenant, nous savons vraiment pourquoi nous l&rsquo;aimons, joyeusement et sans r\u00e9serve. Elle a \u00e9t\u00e9 notre vie, notre \u00ab sadhana \u00bb<a href=\"#_ftn1\"><strong>[1]<\/strong><\/a>, voie d&rsquo;amour et de recherche <\/em>\u00bb<a href=\"#_ftn2\">[2]<\/a>.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Au cours de vingt ann\u00e9es, nous avions d\u00e9j\u00e0 parcouru beaucoup de chemin sans que nos routes parall\u00e8les aient daign\u00e9 s&rsquo;infl\u00e9chir pour m&rsquo;accorder le privil\u00e8ge de rencontrer Roger Godel. Au terme de cet apparent isolement, ce privil\u00e8ge m&rsquo;\u00e9tait accord\u00e9, sous une forme moins concr\u00e8te, mais je dirai m\u00eame plus \u00ab <em>r\u00e9elle<\/em> \u00bb : la premi\u00e8re lecture de l&rsquo;un de ses ouvrages<a href=\"#_ftn3\">[3]<\/a>. Mieux qu&rsquo;un revoir, c&rsquo;\u00e9tait la merveilleuse d\u00e9couverte d&rsquo;un ami insoup\u00e7onn\u00e9, la communion dans un centre d&rsquo;int\u00e9r\u00eat et sur un plan qui ne conna\u00eet pas les limitations des notions d&rsquo;espace et de dur\u00e9e, un plan cependant qu&rsquo;une attitude scientifique rigoureuse peut accr\u00e9diter pour son plus grand b\u00e9n\u00e9fice.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Lorsqu&rsquo;en 1956 les circonstances nous remettaient face \u00e0 face, vieillis de 35 ans, au milieu d&rsquo;une foule massive, la \u00ab <em>re-connaissance<\/em> \u00bb s&rsquo;effectuait d&rsquo;elle-m\u00eame, sans h\u00e9sitation et pourtant sans rep\u00e8re, dans le climat de l&rsquo;\u00a0\u00ab\u00a0invisible et impersonnelle pr\u00e9sence \u00bb. De m\u00eame, la joie des entretiens ne pouvait \u00eatre que celle de la \u00ab <em>commune compr\u00e9hension de l&rsquo;essentielle r\u00e9alit\u00e9<\/em> \u00bb<a href=\"#_ftn4\">[4]<\/a>. Ces entretiens ne devaient se renouveler qu&rsquo;une fois avant la survenue de l&rsquo;in\u00e9luctable&#8230; Mais ce terme apparent est sans pouvoir pour nous s\u00e9parer d&rsquo;un Etre \u00e0 jamais pr\u00e9sent, dont la conscience et l&rsquo;\u0153uvre se sont r\u00e9alis\u00e9es sous le sceau de l&rsquo;absolu.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">En me d\u00e9dica\u00e7ant son \u00ab Platon \u00e0 H\u00e9liopolis \u00bb<a href=\"#_ftn5\">[5]<\/a>, Roger Godel faisait remarquer : \u00ab <em>Ce petit livre ne prouve rien ; on pourrait y voir un divertissement litt\u00e9raire ou \u00e9rudit. Mais il contient absolument tout ce que j&rsquo;ai \u00e0 dire d&rsquo;essentiel<\/em> \u00bb. Tant il est vrai que nous ne pouvons comprendre des \u00eatres et des choses que ce qui trouve en nous-m\u00eame une authentique r\u00e9sonance. Les consid\u00e9rations pr\u00e9c\u00e9dentes, en mati\u00e8re de prologue, situeront donc l&rsquo;esprit dans lequel je me sens inclin\u00e9e \u00e0 choisir et \u00e0 \u00e9voquer quelques traits de la physionomie aussi bien que des travaux de cet imp\u00e9rissable Ami. Hommage modeste, mais t\u00e9moignage fid\u00e8le d&rsquo;un \u00e9cho \u00e9veill\u00e9 par la puissance d&rsquo;induction du bienfaisant message.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Nous l&rsquo;avons vu d\u00e9j\u00e0, c&rsquo;est l&rsquo;exercice de la profession m\u00e9dicale qui repr\u00e9sente, pour Roger Godel, le creuset o\u00f9 s&rsquo;affrontent l&rsquo;homme, le savant, le philosophe avec une inlassable exigence de v\u00e9rit\u00e9, dans l&rsquo;\u00e9laboration d&rsquo;une synth\u00e8se tout enti\u00e8re conditionn\u00e9e par l&rsquo;ultime sagesse d&rsquo;une conscience d&rsquo;o\u00f9 \u00e9mane toute chose, mais qui semble devoir \u00e9chapper \u00e0 l&rsquo;exploration du savant.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Magnifiquement et contin\u00fbment inspir\u00e9e par Socrate, cette carri\u00e8re m\u00e9dicale qui force l&rsquo;admiration et le respect, fut \u00e0 cet \u00e9gard un v\u00e9ritable \u00ab <em>accomplissement<\/em> \u00bb : Le sage affirme en effet que la vie professionnelle, remplie avec amour, facilite l&rsquo;acheminement vers la \u00ab v\u00e9rit\u00e9 \u00bb ; elle devient la voie de la \u00ab connaissance \u00bb, mais d&rsquo;une connaissance qui transcende les acquisitions de l&rsquo;intellect, une connaissance qui existe potentiellement en tout homme et dont l&rsquo;influence du ma\u00eetre stimule l&rsquo;\u00e9veil chez le disciple. Elle n&rsquo;est rien de moins que la \u00ab <em>connaissance de soi<\/em> \u00bb, la cinglante injonction de l&rsquo;oracle de Delphes.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Des erreurs toutefois peuvent \u00eatre fatales au d\u00e9but de la route. Pour qui n&rsquo;en prend pas conscience avec une vigilance soutenue et dans une constante aspiration \u00e0 transcender leurs mirages, la \u00ab <em>qu\u00eate<\/em> \u00bb, fauss\u00e9e \u00e0 l&rsquo;origine, n&rsquo;aboutira qu&rsquo;\u00e0 des impasses. Ces emb\u00fbches sont inh\u00e9rentes \u00e0 certaines \u00ab conceptions \u00bb intellectuelles, \u00e0 des erreurs d&rsquo;optique, \u00e0 des points de vue erron\u00e9s, qu&rsquo;il importe de r\u00e9viser \u00e0 tout prix. C&rsquo;est une \u00e9chelle des valeurs conforme \u00e0 la v\u00e9rit\u00e9 qu&rsquo;il nous faut acqu\u00e9rir. Cette science des valeurs, guide indispensable d&rsquo;une \u00ab science de la v\u00e9rit\u00e9 \u00bb, porte un nom dans notre milieu scientifique contemporain, c&rsquo;est l&rsquo;\u00ab <em>\u00e9pist\u00e9mologie<\/em> \u00bb, nom qui par l&rsquo;\u00e9tymologie grecque est pr\u00e9cis\u00e9ment charg\u00e9 de signification : \u00ab <em>l&rsquo;\u00e9pist\u00e9m\u00e8<\/em> \u00bb, autre appellation du \u00ab <em>N<\/em><em>?<\/em><em>??<\/em> \u00bb n&rsquo;est autre que cette conscience pure synonyme de \u00ab <em>connaissance absolue<\/em> \u00bb, cette sagesse qui situe l&rsquo;ordre des choses dans une lumi\u00e8re v\u00e9ridique. L&rsquo;\u00e9pist\u00e9mologie correcte sera donc en d\u00e9finitive celle-l\u00e0 seule qui se placera dans cette lumi\u00e8re ou du moins qui s&rsquo;y r\u00e9f\u00e8rera.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Ces assertions des sages hell\u00e8nes sont en tous points conformes \u00e0 celles des grands rishis de la tradition indienne. (Pourrait-il en \u00eatre autrement dans une exp\u00e9rience de \u00ab <em>v\u00e9rit\u00e9<\/em> \u00bb conforme \u00e0 l&rsquo;universelle nature humaine ?) Dans cette tradition vieille de plusieurs mill\u00e9naires mais qui se traduit encore de nos jours en de sublimes r\u00e9alisations, v\u00e9cues dans leur pl\u00e9nitude, cette voie de la \u00ab connaissance \u00bb qui m\u00e8ne \u00e0 la \u00ab lib\u00e9ration \u00bb tout comme les deux autres voies de la d\u00e9votion (bhakti) \u2014 et de l&rsquo;action (karma) \u2014 est plus pr\u00e9cis\u00e9ment celle qui s&rsquo;adresse \u00e0 l&rsquo;intellectuel, encore qu&rsquo;elle suppose \u00e9galement la pratique de l&rsquo;amour et de l&rsquo;action juste. Elle porte le nom de \u00ab <em>Jnana<\/em> \u00bb et exige imp\u00e9rieusement elle aussi, au stage initial, la pratique du \u00ab\u00a0<em>discernement<\/em> \u00bb (viveka) qui permettra de distinguer entre \u00ab <em>r\u00e9el<\/em> \u00bb et \u00ab <em>irr\u00e9el<\/em> \u00bb, \u00ab <em>relatif<\/em> \u00bb et \u00ab <em>absolu<\/em> \u00bb. Loin de condamner l&rsquo;intellect qu&rsquo;il s&rsquo;agit cependant de transcender, cette pratique l&rsquo;utilisera avec un maximum d&rsquo;acuit\u00e9, \u00a0jusqu&rsquo;\u00e0 un sommet qui deviendra le tremplin m\u00eame du \u00ab d\u00e9passement \u00bb. Cet intellect sera tr\u00e8s exactement \u00e0 la recherche d&rsquo;une \u00ab \u00e9pist\u00e9mologie juste\u00a0\u00bb pour reprendre les termes hell\u00e9niques.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Le message de la Gr\u00e8ce antique connut une r\u00e9sonance si parfaite dans la conscience de Roger Godel qu&rsquo;\u00e0 lui seul il eut suffi \u00e0 transfigurer sa personnalit\u00e9 m\u00e9dicale et \u00e0 inspirer toute son \u0153uvre. Dans ses lectures comme dans ses p\u00e8lerinages<a href=\"#_ftn6\">[6]<\/a>, c&rsquo;est v\u00e9ritablement l&rsquo;esprit des sages et l&rsquo;\u00e2me des lieux sacr\u00e9s qui deviennent exp\u00e9rience. Exp\u00e9rience si authentiquement v\u00e9cue, qu&rsquo;en l&rsquo;exprimant sous la plume il acquiert lui aussi ce pouvoir socratique de susciter un \u00ab <em>r\u00e9veil<\/em> \u00bb chez le lecteur en qu\u00eate sinc\u00e8re de v\u00e9rit\u00e9.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Mais parce que l&rsquo;Inde avait ses sages actuels, ceux que notre ami d\u00e9crit sous l&rsquo;appellation de \u00ab <em>lib\u00e9r\u00e9s-vivants<\/em> \u00bb (jivan-muktis)<a href=\"#_ftn7\">[7]<\/a>, et sachant qu&rsquo;ils incarnaient la m\u00eame r\u00e9alit\u00e9, il se rendit en Inde pour demander au sage indou d&rsquo;\u00e9clairer le probl\u00e8me pos\u00e9 si dramatiquement par Socrate : \u00ab <em>Qu&rsquo;est-ce que l&rsquo;homme ?<\/em> \u00bb. Il ne souhaitait rien d&rsquo;autre, nous dit-il, que d&rsquo;obtenir une \u00ab <em>instruction \u00e9pist\u00e9mologique applicable \u00e0 cette science de la nature humaine qu&rsquo;est la m\u00e9decine<\/em> \u00bb. Ses esp\u00e9rances furent r\u00e9alis\u00e9es, il \u00ab\u00a0<em>crut entendre parler Socrate<\/em> \u00bb<a href=\"#_ftn8\">[8]<\/a>.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Cette identit\u00e9 de la \u00ab <em>Sagesse<\/em> \u00bb selon les Traditions indiennes et socratiques a combl\u00e9 les v\u0153ux de ce Chercheur de V\u00e9rit\u00e9. Il rapproche parfois ces traditions dans une m\u00eame pr\u00e9sentation<a href=\"#_ftn9\">[9]<\/a> mais son \u0153uvre enti\u00e8re les invoque indiff\u00e9remment en m\u00eame temps qu&rsquo;elle les transpose sur le plan scientifique. Ce faisant, il nous en rappelle l&rsquo;\u00ab <em>essentiel<\/em> \u00bb : l&rsquo;existence au sommet de la constitution humaine d&rsquo;une puissance \u00e9clairante&#8230; implicite dans la conscience et par quoi toute d\u00e9marche humaine est illumin\u00e9e. C&rsquo;est le \u00ab <em>N??? <\/em>\u00bb de la tradition platonicienne et n\u00e9o-platonicienne ; r\u00e9alit\u00e9 pragmatique, autant que th\u00e9orique, \u00ab <em>agissant en nous et \u00e0 travers nous<\/em> \u00bb. Le \u00ab <em>Jnana<\/em> \u00bb du sage indien d\u00e9signe cette m\u00eame conscience \u00e9clairante.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Chez Roger Godel, cette prise de conscience de l&rsquo;\u00ab <em>essentiel<\/em> \u00bb, est issue de l&rsquo;imp\u00e9rieux besoin d&rsquo;une \u00e9pist\u00e9mologie sans erreur au service de la science de l&rsquo;homme que doit \u00eatre une m\u00e9decine digne de ce nom. Ce colossal \u00e9lan spirituel, suscit\u00e9 par une profession exerc\u00e9e avec amour, nous le verrons se d\u00e9velopper parall\u00e8lement \u00e0 la mise en \u0153uvre d&rsquo;une connaissance scientifique et d&rsquo;une attitude exp\u00e9rimentale rigoureuse. Au terme de l&rsquo;exp\u00e9rience, c&rsquo;est encore au m\u00e9decin qu&rsquo;il appartiendra d&rsquo;apporter au malade le b\u00e9n\u00e9fice de l&rsquo;\u0153uvre de r\u00e9novation. Ce Grand C\u0153ur nous le rappelle : \u00ab <em>Si la Sagesse devait conf\u00e9rer \u00e0 qui la pratique, le privil\u00e8ge d&rsquo;un bonheur \u00e9go\u00efste, aucune \u00e2me g\u00e9n\u00e9reuse n&rsquo;en accepterait les dons<\/em> \u00bb.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Aux prises avec le probl\u00e8me de la maladie, le m\u00e9decin et le savant, en lui, jettent le cri d&rsquo;alarme. Dans le domaine clinique bien des acquisitions restent \u00e0 faire : nos cadres nosologiques et nos modes d&rsquo;approche exigent une profonde r\u00e9vision. De nouvelles perspectives sur la m\u00e9decine et plus particuli\u00e8rement sur la cardiologie \u2014 son fief sp\u00e9cialis\u00e9 \u2014 ne pourraient-elles pas r\u00e9duire la mortalit\u00e9 des affections les plus s\u00e9v\u00e8res ? La mise en jeu d&rsquo;une nouvelle optique th\u00e9rapeutique pourrait d\u00e9couler d&rsquo;une r\u00e9vision \u00e9pist\u00e9mologique rigoureuse de la m\u00e9decine qui s&rsquo;impose imp\u00e9rieusement. Seule, en effet, parmi les sciences contemporaines, cette derni\u00e8re n&rsquo;a pas \u00e9t\u00e9 soumise \u00e0 une critique \u00e9pist\u00e9mologique.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">C&rsquo;est alors que surgit l&rsquo;aspect philosophique de cette science m\u00e9dicale. Son approche ne peut \u00eatre fond\u00e9e que sur une connaissance correcte de la nature de l&rsquo;homme. Celle-ci ne pourrait-elle pas nous \u00eatre propos\u00e9e selon une perspective adva\u00eftique<a href=\"#_ftn10\">[10]<\/a> ?<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Ce que la m\u00e9decine \u00e9tudie et atteint actuellement dans son examen du malade, ce sont les m\u00e9canismes de la souffrance, mais elle n&rsquo;affronte pas l&rsquo;homme. Sans doute, les aspects psychosomatiques de la maladie se sont-ils impos\u00e9s et nul n&rsquo;ignore plus le fardeau aggravant que fait peser sur un organe en difficult\u00e9, un psychisme d\u00e9sorganis\u00e9. Mais s&rsquo;attaquer \u00e0 l&rsquo;insoluble probl\u00e8me du lieu de jonction de l&rsquo;esprit avec la mati\u00e8re appara\u00eet comme une \u00ab <em>erreur \u00e9pist\u00e9mologique<\/em> \u00bb. La psych\u00e9, pas plus que le corps ne saurait repr\u00e9senter l&rsquo;homme int\u00e9gral et, si les m\u00e9canismes d&rsquo;int\u00e9gration, si bien analys\u00e9s au niveau physiologique veulent se d\u00e9rouler dans une perspective humaine authentique, force nous est de les faire culminer dans leur foyer ultime et immuable qui \u00e9mane et r\u00e9sorbe les autres niveaux.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">D&rsquo;o\u00f9 proviennent, en effet, ce corps, ce cerveau et sa contrepartie psychique, \u00e9motionnelle et mentale ? C&rsquo;est en faisant usage des acquisitions r\u00e9centes de la neurobiologie que Roger Godel r\u00e9pond \u00e0 ses contemporains :<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0<em>J&rsquo;examine la nature de ce corps. A quoi en d\u00e9finitive se ram\u00e8ne sa substance ? La physiologie nous d\u00e9montre qu&rsquo;elle appartient sans conteste au domaine des images sensorielles. Ce corps se manifeste dans un champ de conscience comme une image visuelle, une image tactile, une image proprioceptive ; il assume aussi la nature d&rsquo;un concept, d&rsquo;un sch\u00e9ma : l&rsquo;id\u00e9e d&rsquo;un corps. Son apparition est ins\u00e9parable du ph\u00e9nom\u00e8ne de conscience. La conscience l&rsquo;\u00e9labore dans l&rsquo;intimit\u00e9 de notre nature neuropsychique et se la donne en spectacle<\/em> \u00bb.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Ainsi, nous d\u00e9solidarisant de l&rsquo;objet examin\u00e9 : notre image corporelle, abandonnant l&rsquo;identification pour prendre le poste de spectateur, il nous devient ais\u00e9 d&rsquo;enregistrer la gen\u00e8se et la dissolution des images, aussi bien que le \u00ab <em>d\u00e9fil\u00e9 incessant des expressions \u00e9motionnelles et mentales de la conscience<\/em> \u00bb. Etabli en ce poste d&rsquo;observation, au plus profond de lui-m\u00eame, l&rsquo;homme apprend \u00e0 reconna\u00eetre le caract\u00e8re \u00e9ph\u00e9m\u00e8re et inconsistant des formes apparemment objectives qui traversent le champ de sa conscience. Il ne peut plus s&rsquo;inclure dans cette \u00ab <em>imagerie<\/em> \u00bb.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">La science admet le postulat que le savant assume une position invariable d&rsquo;observateur. Ici doit intervenir le discernement : cela serait exact si, comme nous venons de le voir, ce dernier examinait sa propre position de sujet avant d&rsquo;entreprendre ses recherches. L&rsquo;erreur r\u00e9side dans l&rsquo;illusion de la dualit\u00e9 \u00ab <em>sujet-objet<\/em> \u00bb ; l&rsquo;espace et le temps ont en nous leur origine ; le monde lui aussi est en nous au m\u00eame titre que l&rsquo;image de notre corps. Au grand physiologiste Sherrington<a href=\"#_ftn11\">[11]<\/a> revient le m\u00e9rite d&rsquo;avoir situ\u00e9 l&rsquo;observateur hors des cat\u00e9gories du temps et de l&rsquo;espace. Que subsiste-t-il apr\u00e8s la r\u00e9sorption des images et des concepts ? Un \u00e9tat de pure vigilance ; en cet \u00e9tat r\u00e9side la \u00ab <em>position invariable d&rsquo;observateur<\/em> \u00bb.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Pour atteindre la v\u00e9rit\u00e9, la recherche scientifique doit \u00eatre un continuel interrogatoire non seulement du Cosmos, mais aussi de nous-m\u00eame. L&rsquo;univers cesse de nous appara\u00eetre lorsqu&rsquo;il est transform\u00e9 en connaissance, la loi se substitue alors aux ph\u00e9nom\u00e8nes. Mais cette loi elle-m\u00eame est appel\u00e9e \u00e0 s&rsquo;\u00e9vanouir lorsqu&rsquo;elle a \u00e9veill\u00e9 la connaissance. Ne peut-on pas d\u00e8s lors esp\u00e9rer que lorsque l&rsquo;homme moderne \u00ab <em>aura reconnu la n\u00e9cessit\u00e9 pratique de se r\u00e9f\u00e9rer \u00e0 une \u00e9pist\u00e9mologie sans d\u00e9faut, une \u00e8re d&rsquo;incomparables d\u00e9couvertes s&rsquo;ouvrira \u00e0 lui ?<\/em>\u00bb L&rsquo;image de la r\u00e9alit\u00e9 ne sera plus alors confondue avec la r\u00e9alit\u00e9 qu&rsquo;elle recouvre : erreur fatale \u00e0 l&rsquo;investigation.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Comment une fonction chimique, physique, ou mentale pourrait-elle appartenir \u00e0 la mati\u00e8re puisque l&rsquo;aspect mat\u00e9riel des choses n&rsquo;est lui-m\u00eame qu&rsquo;une image de la conscience de l&rsquo;homme ? La recherche scientifique tend vers cette unit\u00e9 au cours de son ascension, de m\u00eame que la recherche spirituelle indienne oriente ses adeptes de la multiplicit\u00e9 vers l&rsquo;unit\u00e9 et les courants profonds de la tradition semblent bien \u00eatre de nature \u00e0 rencontrer la culture scientifique de notre \u00e8re. Les sciences physiques n&rsquo;en sont-elles pas l&rsquo;indication la plus claire ? Les formes s&rsquo;y r\u00e9solvent en \u00e9nergie, l&rsquo;\u00e9nergie en symboles math\u00e9matiques ; ces symboles dans l&rsquo;unique \u00e9quation recherch\u00e9e par Einstein. De nos jours, sous les termes scientifiques se laisse d\u00e9couvrir de plus en plus un enseignement analogue \u00e0 celui des grands mythes de l&rsquo;antiquit\u00e9, symboles eux aussi d&rsquo;une connaissance qu&rsquo;il faut apprendre \u00e0 d\u00e9voiler.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Dans une application pr\u00e9cise, \u00e0 savoir l&rsquo;interpr\u00e9tation des ph\u00e9nom\u00e8nes \u00e9piphaniques, Roger Godel nous donne l&rsquo;exemple plein d&rsquo;int\u00e9r\u00eat d&rsquo;une connaissance scientifique f\u00e9cond\u00e9e par une intuition s\u00fbre, une \u00e9pist\u00e9mologie r\u00e9vis\u00e9e. Dans un domaine qui d\u00e9passe de beaucoup la parapsychologie \u00e9l\u00e9mentaire \u00e0 l&rsquo;\u00e9tude dans les laboratoires scientifiques, il s&rsquo;appuie sur les d\u00e9couvertes physiologiques les plus r\u00e9centes pour pr\u00e9senter une hypoth\u00e8se hardie mais simple et lumineuse, l\u00e0 o\u00f9 la science se refuse encore \u00e0 intervenir. \u00ab <em>Une longue pratique de la m\u00e9decine dans les pays de l&rsquo;orient m\u00e9diterran\u00e9en<\/em>, \u00e9crit-il dans \u00ab La Gr\u00e8ce secr\u00e8te \u00bb <em>m&rsquo;a convaincu que les t\u00e9moignages des visionnaires posent au physiologiste, au philosophe, \u00e0 l&rsquo;historien, un probl\u00e8me d&rsquo;une extr\u00eame importance<\/em>. \u00bb<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">En savant avis\u00e9, en m\u00e9decin comp\u00e9tent, il distingue soigneusement entre les manifestations conscientes de l&rsquo;\u00e9lite d&rsquo;une antique civilisation et les m\u00e9canismes pathologiques qui se peuvent \u00e9tudier dans nos hospices psychiatriques : \u00ab <em>La vision \u00e9piphanique assume une fonction constructive, elle ouvre une voie sur une perspective r\u00e9novatrice<\/em> \u00bb ainsi que le d\u00e9montrent certaines observations m\u00e9dicales soigneusement recueillies : en cela, \u00ab <em>elle contraste d&rsquo;une mani\u00e8re irr\u00e9ductible avec les hallucinations qui accompagnent de profonds d\u00e9sordres du comportement, du caract\u00e8re et du jugement<\/em>. \u00bb<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Et aussit\u00f4t surgit l&rsquo;utilisation judicieuse des travaux de neurophysiologie ; la r\u00e9f\u00e9rence aux donn\u00e9es les plus r\u00e9centes de m\u00e9canisme \u00ab <em>d&rsquo;int\u00e9gration<\/em> \u00bb d&rsquo;apr\u00e8s les travaux de Penfield sur le foyer \u00ab <em>centrenc\u00e9phalique<\/em> \u00bb<a href=\"#_ftn12\">[12]<\/a> : Les formations r\u00e9ticul\u00e9es de la base du cerveau repr\u00e9sentent un syst\u00e8me g\u00e9n\u00e9ral d&rsquo;int\u00e9gration dont l&rsquo;une des fonctions les plus importantes est de potentialiser les centres sensoriels. Pourquoi le savant ne verrait-il pas ce r\u00e9seau participer \u00e0 la gen\u00e8se et \u00e0 la projection ext\u00e9rieure des images \u00e9piphaniques ? Il suffit d&rsquo;admettre une simple transposition du cheminement du courant excitateur venant ici de l&rsquo;int\u00e9riorit\u00e9 centrale et non plus des stimuli \u00e9manant de la p\u00e9riph\u00e9rie pour atteindre les r\u00e9cepteurs des organes des sens. \u00ab <em>Le m\u00e9canisme qui proc\u00e8de \u00e0 l&rsquo;\u00e9mission des images \u00e9piphaniques nous \u00e9tonne par la perfection de son r\u00e9glage. C&rsquo;est avec une exactitude remarquable qu&rsquo;il s&rsquo;adapte aux circonstances et aux choses de l&rsquo;ext\u00e9rieur tout en exprimant les normes profondes de la vie subjective, individuelle ou collective<\/em> \u00bb. Le pouvoir d&rsquo;int\u00e9gration qui se manifeste dans ce m\u00e9canisme d\u00e9montre que la fonction spirituelle cr\u00e9atrice de formes rel\u00e8ve des \u00ab <em>hi\u00e9rarchies les plus \u00e9lev\u00e9es de la neurophysiologie<\/em>. \u00bb<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Ceci n&rsquo;est qu&rsquo;un exemple entre bien d&rsquo;autres. Nous ne saurions rappeler ici toute la pr\u00e9sentation physiologique soigneusement document\u00e9e et judicieusement utilis\u00e9e que Roger Godel met \u00e0 la disposition du lecteur dans un ouvrage tel que \u00ab Vie et R\u00e9novation \u00bb<a href=\"#_ftn13\">[13]<\/a>. Pour qui sait \u00eatre \u00e0 l&rsquo;\u00e9coute de la source de V\u00e9rit\u00e9 qui a inspir\u00e9 l&rsquo;auteur, le pouvoir catalyseur du message socratique, favorise l&rsquo;\u00e9veil d&rsquo;une nouvelle conscience ou en d&rsquo;autres termes le r\u00e9veil du r\u00eaveur abus\u00e9 par ses propres images.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Quel va \u00eatre ce r\u00e9veil et comment va-t-il s&rsquo;effectuer ? Nous avons compris d\u00e9j\u00e0 qu&rsquo;il va r\u00e9sider tout entier dans l&rsquo;appr\u00e9hension d&rsquo;une donn\u00e9e qui nous \u00e9tait jusqu&rsquo;ici \u00e9trang\u00e8re : la prise de conscience de l&rsquo;essentiel. C&rsquo;est alors qu&rsquo;il appara\u00eet souhaitable qu&rsquo;un homme de science \u00ab <em>entreprenne en exp\u00e9rimentateur l&rsquo;\u00e9tude du domaine m\u00e9taphysique, ce monde de la profonde int\u00e9riorit\u00e9<\/em>. \u00bb<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Mais tout d&rsquo;abord, y a-t-il place dans ce domaine pour une d\u00e9marche de caract\u00e8re scientifique ? Roger Godel n&rsquo;en doute pas qui attribue d\u00e9lib\u00e9r\u00e9ment le titre de \u00ab <em>savant<\/em> \u00bb \u00e0 un X\u00e9nophane, \u00e0 un Parm\u00e9nide. \u00ab <em>L&rsquo;exigence de V\u00e9rit\u00e9 qui incita Parm\u00e9nide \u00e0 porter sa recherche au c\u0153ur de l&rsquo;Etre rel\u00e8ve bien de l&rsquo;esprit scientifique car elle \u00e9tablit d&#8217;embl\u00e9e les conditions indispensables \u00e0 une entreprise de ce genre<\/em> \u00bb. Elle lui fait \u00e9carter l&rsquo;incertain et le relatif en faveur d&rsquo;une r\u00e9alit\u00e9 stable soustraite aux vicissitudes du changement et du temps. Elle l&rsquo;engage \u00e0 d\u00e9couvrir dans la conscience et \u00e0 utiliser \u00ab <em>l&rsquo;instrument propre \u00e0 atteindre le but propos\u00e9<\/em> \u00bb.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">L&rsquo;\u00e9pith\u00e8te de \u00ab <em>savant<\/em> \u00bb se peut-elle discuter pour qui t\u00e9moigne d&rsquo;un besoin aussi absolu de connaissance du R\u00e9el, pour qui aspire \u00e0 cette exp\u00e9rience cruciale qui satisfait \u00e0 l&rsquo;exigence d&rsquo;un besoin de V\u00e9rit\u00e9 ? Ce qui va conf\u00e9rer ici \u00e0 l&rsquo;exp\u00e9rience son caract\u00e8re d&rsquo;inhabituel, c&rsquo;est le \u00ab <em>niveau<\/em> \u00bb o\u00f9 l&rsquo;exploration va prendre place. Cette diff\u00e9rence fondamentale va exiger une transposition m\u00e9thodologique qui d\u00e9laisse l&rsquo; \u00ab\u00a0<em>\u00e9rudition chevronn\u00e9e<\/em> \u00bb acquise par l&rsquo;observation de l&rsquo;aspect changeant des ph\u00e9nom\u00e8nes associ\u00e9e au jeu de la sp\u00e9culation intellectuelle et dont le d\u00e9ploiement faisait autorit\u00e9.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">La science supr\u00eame ne vise plus l&rsquo;exploration du monde sensoriel ni la puissance et l&rsquo;ing\u00e9niosit\u00e9 de la pens\u00e9e diversifi\u00e9e. Elle ouvre la voie \u00e0 un r\u00e9alisme nouveau qui substitue au faux r\u00e9alisme des apparences, un t\u00e9moignage direct \u00ab <em>jailli du socle in\u00e9branlable de l&rsquo;\u00eatre<\/em> \u00bb. Au seuil de cette mutation, la pens\u00e9e se r\u00e9duit au silence ; sa nature m\u00eame lui interdit la perception de cette \u00ab <em>immuable r\u00e9alit\u00e9<\/em> \u00bb. Les sp\u00e9culations intellectuelles avec leurs limitations font place \u00e0 une exp\u00e9rience m\u00e9taphysique authentique qui met en jeu le N???, ce principe sup\u00e9rieur d&rsquo;intelligibilit\u00e9. Ce que le Sage nous propose, ce n&rsquo;est pas l&rsquo;adh\u00e9sion \u00e0 un expos\u00e9 th\u00e9orique, c&rsquo;est une exp\u00e9rience int\u00e9rieure qu&rsquo;il induit, exp\u00e9rience d\u00e8s lors irr\u00e9cusable. Socrate n&rsquo;eut pas de \u00ab <em>disciples<\/em> \u00bb au sens intellectuel du terme, mais des \u00ab <em>compagnons d&rsquo;\u00e9merveillement<\/em> \u00bb. Sa sagesse irradiante ouvrait pour chacun \u00ab une route royale \u00e0 la recherche de l&rsquo;essentiel \u00bb.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Sur cette voie ascendante o\u00f9 l&rsquo;intellect est somm\u00e9 \u00e0 un moment donn\u00e9 d&rsquo;abandonner ses pr\u00e9rogatives, il ne saurait y avoir d&rsquo;anticipation, de pr\u00e9figuration, de ce que sera l&rsquo;exp\u00e9rience. Sur l&rsquo;arc descendant au contraire au niveau neurophysiologique de l&rsquo;int\u00e9gration, un acte moteur par exemple comportait un sch\u00e9ma neurologique d&rsquo;ex\u00e9cution (sch\u00e9ma id\u00e9o-praxique). La configuration dynamique invisible, d\u00e9termin\u00e9e en ses moindres d\u00e9tails, pr\u00e9c\u00e9dait l&rsquo;apparition du mouvement d\u00e9celable. Au sommet de l&rsquo;Etre, rien de semblable ; le contenu de l&rsquo;exp\u00e9rience surgit dans une r\u00e9v\u00e9lation impr\u00e9visible.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Et cependant de grandes lois pr\u00e9sident in\u00e9vitablement \u00e0 ce dynamisme de la vie int\u00e9rieure et la m\u00e9decine qui \u00ab <em>se r\u00e9clame en pratique d&rsquo;une science de l&rsquo;homme dont elle pr\u00e9tend d\u00e9river son savoir <\/em>\u00bb ne saurait \u00ab <em>y demeurer plus longtemps \u00e9trang\u00e8re<\/em>&#8230; \u00bb A cet \u00e9gard nul t\u00e9moignage dans le champ de la connaissance humaine n&rsquo;appara\u00eet n\u00e9gligeable dans l&rsquo;\u00e9laboration d&rsquo;une science dont la n\u00e9cessit\u00e9 s&rsquo;impose. Tel le domaine o\u00f9 l&rsquo;historien des religions et des m\u00e9taphysiques nous invite \u00e0 p\u00e9n\u00e9trer. L&rsquo;homme de science r\u00e9pugne \u00e0 en aborder l&rsquo;exploration \u00ab <em>sans parti pris, avec un esprit ouvert<\/em> \u00bb. Et cependant, tel le domaine de la neurophysiologie, ce terrain d&rsquo;exploration pourrait bien rec\u00e9ler pour nous des \u00e9l\u00e9ments susceptibles d&rsquo;\u00ab <em>\u00e9tayer des m\u00e9canismes pressentis<\/em> \u00bb. Roger Godel qui sait allier l&rsquo;\u00e9rudition de l&rsquo;historien \u00e0 la vision du sage ne manque pas de nous en proposer l&rsquo;\u00e9tude, tout en reconnaissant les difficult\u00e9s de l&rsquo;entreprise.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Cette mati\u00e8re, \u00ab <em>aussi exigeante de rigueur scientifique qu&rsquo;une autre<\/em> \u00bb exige de l&rsquo;\u00e9tudiant \u00ab <em>une pr\u00e9paration m\u00e9thodique \u00e0 l&rsquo;investigation, et les m\u00e9thodes applicables \u00e0 l&rsquo;\u00e9tude du monde objectif ne sauraient convenir \u00e0 la prospection de cet univers fluide de l&rsquo;int\u00e9riorit\u00e9 si commun\u00e9ment qualifi\u00e9 \u00e0 la l\u00e9g\u00e8re d&rsquo;irr\u00e9el<\/em> \u00bb. A nouveau intervient le test \u00e9pist\u00e9mologique : \u00ab <em>Dans ce champ de forces aux configurations si mal connues<\/em> \u00bb <em>une \u00ab fausse optique \u00bb incite l&rsquo;observateur \u00e0 d\u00e9former et substantialiser les figures qui se pr\u00e9sentent \u00e0 lui. Il les soumet par surcro\u00eet \u00e0 une analyse grossi\u00e8rement rationnelle et en perd l&rsquo;essence. Ses documents sont d\u00e9pourvus de valeur<\/em> \u00bb.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Ici, Roger Godel ne manque pas d&rsquo;invoquer l&rsquo;\u0153uvre incontest\u00e9e du Professeur Bachelard qui \u00ab <em>au cours d&rsquo;une s\u00e9rie d&rsquo;\u00e9tudes p\u00e9n\u00e9trantes consacr\u00e9es \u00e0 la d\u00e9couverte des lois de l&rsquo;int\u00e9riorit\u00e9&#8230; a d\u00e9montr\u00e9 que l&rsquo;imagination ob\u00e9it \u00e0 des imp\u00e9ratifs pr\u00e9cis <\/em>\u00bb<a href=\"#_ftn14\">[14]<\/a>. N&rsquo;y puise-t-on pas la conviction que les images et les mythes \u00ab <em>d\u00e9c\u00e8lent \u00e0 coup s\u00fbr, les lignes de force d&rsquo;une structure int\u00e9rieure \u00e0 l&rsquo;homme ?<\/em> \u00bb<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Heureux celui qui, dans l&rsquo;\u00e9tude des formes, sait d\u00e9celer l&rsquo;\u00e9volution de la vie. C&rsquo;est impitoyablement que le Professeur Bachelard stigmatise l&rsquo;\u00eatre priv\u00e9 de ce qu&rsquo;il appelle \u00ab <em>la fonction de l&rsquo;irr\u00e9el<\/em> \u00bb. \u00ab <em>Aussi bien que l&rsquo;\u00eatre priv\u00e9 de la fonction du r\u00e9el, il est un n\u00e9vros\u00e9<\/em> \u00bb. Derri\u00e8re l&rsquo;imagerie des figures mythiques, c&rsquo;est une v\u00e9ritable \u00ab <em>fonction biologique<\/em> \u00bb qui est propos\u00e9e \u00e0 notre d\u00e9couverte. Au-del\u00e0 m\u00eame des fonctions psychiques, pourquoi la recherche scientifique se refuserait-elle \u00e0 explorer l&rsquo;homme \u00ab <em>jusqu&rsquo;au terme de sa vie int\u00e9rieure<\/em> \u00bb ?<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">C&rsquo;est la plus haute d\u00e9marche qui nous soit propos\u00e9e : l&rsquo;homme porte dans sa structure des lois biologiques dont il peut enregistrer les effets, mais son essence semble lui demeurer inaccessible. Elle le serait en fait si l&rsquo;injonction des sages ne nous proposait un autre mode d&rsquo;approche&#8230; C&rsquo;est une mont\u00e9e en sens inverse de la morphog\u00e9n\u00e8se, l&rsquo;invitation \u00e0 r\u00e9sorber les formes et la pens\u00e9e. Platon nous avertit que \u00ab <em>la vision de l&rsquo;esprit ne commence d&rsquo;avoir l&rsquo;\u0153il per\u00e7ant que lorsque celle des yeux a perdu son acuit\u00e9<\/em> \u00bb<a href=\"#_ftn15\">[15]<\/a>. Le \u00ab <em>silence int\u00e9rieur<\/em> \u00bb que le sage pr\u00e9conise lui r\u00e9v\u00e8le une v\u00e9rit\u00e9 semblable \u00e0 celle qu&rsquo;\u00e9voquait Socrate. Bien quelle transcende la notion d&rsquo;espace, cette exp\u00e9rience d&rsquo;absolu appara\u00eet comme le r\u00e9sultat d&rsquo;une v\u00e9ritable progression ascensionnelle. La verticalit\u00e9 au sein des ph\u00e9nom\u00e8nes psychiques n&rsquo;est pas seulement une m\u00e9taphore, ainsi que le remarque M. Bachelard, c&rsquo;est une authentique \u00e9chelle de degr\u00e9s. En psychoth\u00e9rapie, la m\u00e9thode du r\u00eave \u00e9veill\u00e9 de M. Desoille r\u00e9v\u00e8le que ce symbole rec\u00e8le effectivement une puissance efficace<a href=\"#_ftn16\">[16]<\/a>.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Au-del\u00e0 de la psych\u00e9 o\u00f9 se manifestent l&rsquo;\u00e9motion aussi bien que la raison ordinaire il existe une \u00ab <em>fonction connaissante apte \u00e0 saisir ce qui \u00e9chappe enti\u00e8rement aux sens et \u00e0 l&rsquo;intellection<\/em> \u00bb. Faire pointer l&rsquo;investigation vers cette lumi\u00e8re en reconnaissant (avec l&rsquo;appui de la science moderne), la relativit\u00e9 et l&rsquo;illusion du monde ph\u00e9nom\u00e9nal, c&rsquo;est d\u00e9j\u00e0 \u00e9carter un \u00e9garement \u00e9pist\u00e9mologique qui peut \u00eatre fatal \u00e0 la progression. Chemin faisant, en m\u00eame temps que se r\u00e9vise la valeur de nos concepts intellectuels, notre \u00ab <em>moi<\/em> \u00bb lui-m\u00eame, se r\u00e9v\u00e8le comme un compromis funeste entre la soi-conscience \u00e9manant du niveau sup\u00e9rieur, impersonnel de notre constitution et l&rsquo;image sans consistance d&rsquo;un corps personnel.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Aux grands rishis de l&rsquo;Inde, aux Sages de la Gr\u00e8ce convient seulement le terme de lib\u00e9r\u00e9s-vivants. Leur exp\u00e9rience est lib\u00e9ratrice en ce sens qu&rsquo;elle a une fois pour toutes d\u00e9gag\u00e9 la Conscience pure des niveaux de la manifestation. Il ne s&rsquo;agit pas d&rsquo;une telle r\u00e9alisation pour le savant qui veut b\u00e9n\u00e9ficier dans sa recherche de la pratique du \u00ab <em>discernement<\/em> \u00bb. Le stade ultime en effet est \u00ab <em>connaissance absolue<\/em> \u00bb et la notion m\u00eame de science n&rsquo;a plus sa place. Nous pouvons admettre l&rsquo;authenticit\u00e9 de cette exp\u00e9rience en nous r\u00e9f\u00e9rant m\u00eame \u00e0 de nombreuses notions mises \u00e0 jour par la science contemporaine ; nous pouvons aussi trouver dans la pr\u00e9sence ou dans l&rsquo;\u0153uvre de ces pionniers de l&rsquo;esp\u00e8ce humaine une aide non douteuse \u00e0 notre propre d\u00e9veloppement. Mais les perspectives qu&rsquo;ils nous d\u00e9couvrent sont incontestablement de solides jalons sur le chemin de la connaissance de l&rsquo;Homme. Ils nous fournissent l&rsquo;aimant qui va r\u00e9organiser les \u00e9l\u00e9ments de notre connaissance. Ils ouvrent une vie \u00e0 la \u00ab <em>science de l&rsquo;Essentiel<\/em> \u00bb.<\/p>\n<p style=\"text-align: justify;\">Pour Roger Godel, cette longue et fructueuse p\u00e9r\u00e9grination en compagnie des Sages se r\u00e9sout en une \u0153uvre de synth\u00e8se de haute port\u00e9e dans l&rsquo;\u00e9dification des sciences humaines. Mais ce m\u00e9decin d&rsquo;\u00e9lite a voulu aussi, et avant tout, peut-\u00eatre que sa propre compr\u00e9hension favorise l&rsquo;\u0153uvre de \u00ab r\u00e9novation \u00bb que doit \u00eatre l&rsquo;assistance au malade. Les observations si pleinement encourageantes que nous rapporte les \u00ab <em>Regards sur la M\u00e9decine<\/em> \u00bb prouvent p\u00e9remptoirement que son sentiment si profond du r\u00e9el, s&rsquo;est av\u00e9r\u00e9 prescience. Comme ses ma\u00eetres de l&rsquo;Antiquit\u00e9, il a su d\u00e9couvrir chez le malade la voie de p\u00e9n\u00e9tration vers ce potentiel d&rsquo;\u00e9nergie r\u00e9novatrice. \u00ab <em>Si une telle br\u00e8che vient \u00e0 s&rsquo;ouvrir, ce n&rsquo;est pas devant l&rsquo;ing\u00e9niosit\u00e9 d&rsquo;un savant, mais par l&rsquo;authentique connaissance de l&rsquo;homme<\/em> \u00bb.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Tel est le message de transfiguration que livre \u00e0 notre m\u00e9ditation Roger Godel, \u00e0 la recherche de \u00ab <em>l&rsquo;Essentiel<\/em> \u00bb. En l&rsquo;arrachant trop pr\u00e9matur\u00e9ment \u00e0 cette \u0153uvre scientifique si totalement humaine, l&rsquo;implacable destin semble avoir voulu couronner la vocation dramatiquement entrevue et exprim\u00e9e<a href=\"#_ftn17\">[17]<\/a> : \u00ab <em>S&rsquo;effacer dans l&rsquo;amour, perdre dans l&rsquo;instant, au foyer de la b\u00e9atifique lumi\u00e8re, jusqu&rsquo;au dernier vestige de soi-m\u00eame<\/em> \u00bb.<\/p>\n<p style=\"text-align: right;\">Th\u00e9r\u00e8se BROSSE<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<hr style=\"text-align: justify;\" size=\"1\" \/>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref1\">[1]<\/a> En terminologie hindoue, la \u00ab sadhana \u00bb d\u00e9signe la voie du d\u00e9veloppement spirituel, la \u00ab qu\u00eate \u00bb du disciple pour s&rsquo;\u00e9lever \u00e0 la conscience de l&rsquo;unit\u00e9.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref2\">[2]<\/a> Roger Godel. Correspondance. Septembre 1956.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref3\">[3]<\/a> Roger Godel. Essais sur l&rsquo;Exp\u00e9rience Lib\u00e9ratrice. Pr\u00e9face de Mircea Eliade. Paris. Gallimard. 1952.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref4\">[4]<\/a> Les expressions ou passages entre guillemets sont des citations de Roger Godel (recueillies dans sa correspondance).<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref5\">[5]<\/a> Roger Godel. Platon \u00e0 H\u00e9liopolis d&rsquo;Egypte. Post-Face de Fran\u00e7ois Daumas. Paris. Edition \u00ab Les Belles-Lettres \u00bb. 1956.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref6\">[6]<\/a> R. Godel. Une Gr\u00e8ce Secr\u00e8te. Les Belles-Lettres. Paris 1960<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref7\">[7]<\/a> Essais sur l&rsquo;Exp\u00e9rience Lib\u00e9ratrice. Op. Cit.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref8\">[8]<\/a> R. Godel. Un compagnon de Socrate. Dialogues sur \u00ab l&rsquo;Exp\u00e9rience Lib\u00e9ratrice \u00bb. Les Belles-Lettres. Paris 1956.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref9\">[9]<\/a> R. Godel. <a href=\"http:\/\/www.revue3emillenaire.com\/blog\/?p=24\">La Sagesse selon les Traditions indiennes et socratiques<\/a>. Revue \u00ab Synth\u00e8ses \u00bb, n<sup>o<\/sup> 130, mars 1957.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref10\">[10]<\/a> Advaita, philosophie du non-dualisme&#8230; Connaissance la plus \u00e9lev\u00e9e. Cette suggestion fut pr\u00e9sent\u00e9e au cours d&rsquo;un \u00e9change de vues avec un groupe de m\u00e9decins indiens (correspondance).<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref11\">[11]<\/a> Sherrington. C.S.: \u00a0Man on his Nature. Cambridge University Press, 1946.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref12\">[12]<\/a> W. Penfield. Memory mechanism, in Archives of neurology and psychiatry, vol. 67, n<sup>o<\/sup> 2. Chicago. 1952.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref13\">[13]<\/a> Roger Godel. Vie et R\u00e9novation. De la biologie \u00e0 la M\u00e9decine vers la connaissance de soi. Paris, Gallimard, 1957.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref14\">[14]<\/a> G. Bachelard. L&rsquo;air et les songes, \u00e9dit. Corti, Paris, 1943. L&rsquo;Eau et les R\u00eaves. La psychanalyse du feu, Gallimard. La Terre et les r\u00eaveries de la volont\u00e9, \u00e9dit. Corti. La Terre et les r\u00eaveries du Repos.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref15\">[15]<\/a> Platon. Le Banquet. 21 ; a.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref16\">[16]<\/a> R. Desoille. Exploration de l&rsquo;affectivit\u00e9 subconsciente par la m\u00e9thode du r\u00eave \u00e9veill\u00e9, Paris 1938. Le r\u00eave \u00e9veill\u00e9 en psychoth\u00e9rapie, Paris 1945. Psychanalyse et r\u00eave \u00e9veill\u00e9 dirig\u00e9, Paris 1950.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref17\">[17]<\/a> La Sagesse selon les traditions indienne et socratique. Texte de la Conf\u00e9rence donn\u00e9e, sous les auspices de la revue \u00ab Synth\u00e8ses \u00bb et de l&rsquo;Association Belge-Indienne, au Palais des Beaux-arts, \u00e0 Bruxelles, le 14 f\u00e9vrier 1957, page 8.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Magnifiquement et contin\u00fbment inspir\u00e9e par Socrate, cette carri\u00e8re m\u00e9dicale qui force l&rsquo;admiration et le respect, fut \u00e0 cet \u00e9gard un v\u00e9ritable \u00ab accomplissement \u00bb : Le sage affirme en effet que la vie professionnelle, remplie avec amour, facilite l&rsquo;acheminement vers la \u00ab v\u00e9rit\u00e9 \u00bb ; elle devient la voie de la \u00ab connaissance \u00bb, mais d&rsquo;une connaissance qui transcende les acquisitions de l&rsquo;intellect, une connaissance qui existe potentiellement en tout homme et dont l&rsquo;influence du ma\u00eetre stimule l&rsquo;\u00e9veil chez le disciple. Elle n&rsquo;est rien de moins que la \u00ab connaissance de soi \u00bb, la cinglante injonction de l&rsquo;oracle de Delphes.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[446],"tags":[37,42,598,99],"class_list":["post-4004","post","type-post","status-publish","format-standard","hentry","category-therese-brosse","tag-conscience","tag-eveil","tag-roger-godel","tag-science"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Roger Godel et la science de l&#039;essentiel par Th\u00e9r\u00e8se Brosse - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.revue3emillenaire.com\/blog\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roger Godel et la science de l&#039;essentiel par Th\u00e9r\u00e8se Brosse - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\" \/>\n<meta property=\"og:description\" content=\"Magnifiquement et contin\u00fbment inspir\u00e9e par Socrate, cette carri\u00e8re m\u00e9dicale qui force l&#039;admiration et le respect, fut \u00e0 cet \u00e9gard un v\u00e9ritable \u00ab accomplissement \u00bb : Le sage affirme en effet que la vie professionnelle, remplie avec amour, facilite l&#039;acheminement vers la \u00ab v\u00e9rit\u00e9 \u00bb ; elle devient la voie de la \u00ab connaissance \u00bb, mais d&#039;une connaissance qui transcende les acquisitions de l&#039;intellect, une connaissance qui existe potentiellement en tout homme et dont l&#039;influence du ma\u00eetre stimule l&#039;\u00e9veil chez le disciple. Elle n&#039;est rien de moins que la \u00ab connaissance de soi \u00bb, la cinglante injonction de l&#039;oracle de Delphes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.revue3emillenaire.com\/blog\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\/\" \/>\n<meta property=\"og:site_name\" content=\"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-22T13:30:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-10-02T14:16:40+00:00\" \/>\n<meta name=\"author\" content=\"3e mill\u00e9naire\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"3e mill\u00e9naire\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"26 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\\\/\"},\"author\":{\"name\":\"3e mill\u00e9naire\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#\\\/schema\\\/person\\\/9a3a7cc4ccaa707f402d4394327106d5\"},\"headline\":\"Roger Godel et la science de l&rsquo;essentiel par Th\u00e9r\u00e8se Brosse\",\"datePublished\":\"2010-07-22T13:30:22+00:00\",\"dateModified\":\"2011-10-02T14:16:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\\\/\"},\"wordCount\":5158,\"keywords\":[\"Conscience\",\"Eveil\",\"Roger Godel\",\"Science\"],\"articleSection\":[\"Brosse Th\u00e9r\u00e8se\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\\\/\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\\\/\",\"name\":\"Roger Godel et la science de l'essentiel par Th\u00e9r\u00e8se Brosse - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#website\"},\"datePublished\":\"2010-07-22T13:30:22+00:00\",\"dateModified\":\"2011-10-02T14:16:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#\\\/schema\\\/person\\\/9a3a7cc4ccaa707f402d4394327106d5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roger Godel et la science de l&rsquo;essentiel par Th\u00e9r\u00e8se Brosse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/\",\"name\":\"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation\",\"description\":\"L&#039;Homme en devenir\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/#\\\/schema\\\/person\\\/9a3a7cc4ccaa707f402d4394327106d5\",\"name\":\"3e mill\u00e9naire\",\"url\":\"https:\\\/\\\/www.revue3emillenaire.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Roger Godel et la science de l'essentiel par Th\u00e9r\u00e8se Brosse - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.revue3emillenaire.com\/blog\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\/","og_locale":"fr_FR","og_type":"article","og_title":"Roger Godel et la science de l'essentiel par Th\u00e9r\u00e8se Brosse - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","og_description":"Magnifiquement et contin\u00fbment inspir\u00e9e par Socrate, cette carri\u00e8re m\u00e9dicale qui force l'admiration et le respect, fut \u00e0 cet \u00e9gard un v\u00e9ritable \u00ab accomplissement \u00bb : Le sage affirme en effet que la vie professionnelle, remplie avec amour, facilite l'acheminement vers la \u00ab v\u00e9rit\u00e9 \u00bb ; elle devient la voie de la \u00ab connaissance \u00bb, mais d'une connaissance qui transcende les acquisitions de l'intellect, une connaissance qui existe potentiellement en tout homme et dont l'influence du ma\u00eetre stimule l'\u00e9veil chez le disciple. Elle n'est rien de moins que la \u00ab connaissance de soi \u00bb, la cinglante injonction de l'oracle de Delphes.","og_url":"https:\/\/www.revue3emillenaire.com\/blog\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\/","og_site_name":"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","article_published_time":"2010-07-22T13:30:22+00:00","article_modified_time":"2011-10-02T14:16:40+00:00","author":"3e mill\u00e9naire","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"3e mill\u00e9naire","Dur\u00e9e de lecture estim\u00e9e":"26 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.revue3emillenaire.com\/blog\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\/#article","isPartOf":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\/"},"author":{"name":"3e mill\u00e9naire","@id":"https:\/\/www.revue3emillenaire.com\/blog\/#\/schema\/person\/9a3a7cc4ccaa707f402d4394327106d5"},"headline":"Roger Godel et la science de l&rsquo;essentiel par Th\u00e9r\u00e8se Brosse","datePublished":"2010-07-22T13:30:22+00:00","dateModified":"2011-10-02T14:16:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\/"},"wordCount":5158,"keywords":["Conscience","Eveil","Roger Godel","Science"],"articleSection":["Brosse Th\u00e9r\u00e8se"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.revue3emillenaire.com\/blog\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\/","url":"https:\/\/www.revue3emillenaire.com\/blog\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\/","name":"Roger Godel et la science de l'essentiel par Th\u00e9r\u00e8se Brosse - 3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","isPartOf":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/#website"},"datePublished":"2010-07-22T13:30:22+00:00","dateModified":"2011-10-02T14:16:40+00:00","author":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/#\/schema\/person\/9a3a7cc4ccaa707f402d4394327106d5"},"breadcrumb":{"@id":"https:\/\/www.revue3emillenaire.com\/blog\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.revue3emillenaire.com\/blog\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.revue3emillenaire.com\/blog\/roger-godel-et-la-science-de-lessentiel-par-therese-brosse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.revue3emillenaire.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Roger Godel et la science de l&rsquo;essentiel par Th\u00e9r\u00e8se Brosse"}]},{"@type":"WebSite","@id":"https:\/\/www.revue3emillenaire.com\/blog\/#website","url":"https:\/\/www.revue3emillenaire.com\/blog\/","name":"3e mill\u00e9naire - Spiritualit\u00e9 - Connaissance de soi - Non-dualit\u00e9 - M\u00e9ditation","description":"L&#039;Homme en devenir","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.revue3emillenaire.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.revue3emillenaire.com\/blog\/#\/schema\/person\/9a3a7cc4ccaa707f402d4394327106d5","name":"3e mill\u00e9naire","url":"https:\/\/www.revue3emillenaire.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/posts\/4004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/comments?post=4004"}],"version-history":[{"count":0,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/posts\/4004\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/media?parent=4004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/categories?post=4004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.revue3emillenaire.com\/blog\/wp-json\/wp\/v2\/tags?post=4004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}